{"id":203507,"date":"2019-02-25T19:13:15","date_gmt":"2019-02-25T22:13:15","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203507"},"modified":"2019-02-25T21:35:16","modified_gmt":"2019-02-26T00:35:16","slug":"inquerito-indica-que-ataque-a-bolsonaro-foi-ato-isolado","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/inquerito-indica-que-ataque-a-bolsonaro-foi-ato-isolado\/","title":{"rendered":"Inqu\u00e9rito indica que ataque a Bolsonaro foi ato isolado"},"content":{"rendered":"<p>Em reuni\u00e3o realizada nesta segunda-feira, 25, a Pol\u00edcia Federal informou ao presidente Jair Bolsonaro que, at\u00e9 agora, n\u00e3o h\u00e1 evid\u00eancia da participa\u00e7\u00e3o de outras pessoas al\u00e9m de Ad\u00e9lio Bispo no atentado cometido contra o presidente em setembro. A PF explicou que o inqu\u00e9rito ainda est\u00e1 em andamento. Falta concluir a an\u00e1lise dos materiais apreendidos com um advogado do autor do ataque sofrido por Bolsonaro em setembro.<\/p>\n<p>O encontro no Planalto foi realizado duas semanas ap\u00f3s o presidente cobrar da Pol\u00edcia Federal uma solu\u00e7\u00e3o para o caso. Estavam presentes o delegado federal respons\u00e1vel pelo caso, Rodrigo Morais, o diretor-geral da PF, Maur\u00edcio Valeixo, o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, S\u00e9rgio Moro, e o superintendente da PF em Minas Gerais, o delegado Cairo Costa Duarte.<\/p>\n<p>Antes da reuni\u00e3o, Moro disse \u00e0 imprensa que ainda n\u00e3o havia uma conclus\u00e3o e disse que na ocasi\u00e3o o presidente seria informado do andamento. \u201cO presidente \u00e9 a v\u00edtima, ent\u00e3o \u00e9 interessado. Ent\u00e3o, ser\u00e1 apresentado a ele o resultado da investiga\u00e7\u00e3o at\u00e9 o momento\u201d, disse o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, ap\u00f3s um semin\u00e1rio sobre seguran\u00e7a p\u00fablica em Bras\u00edlia.<\/p>\n<p>At\u00e9 o momento, a tese sobre a atua\u00e7\u00e3o isolada de Bispo \u00e9 a que prevalece no segundo inqu\u00e9rito instaurado pela PF. No primeiro, que focou na apura\u00e7\u00e3o sobre quem era o autor da facada, a PF j\u00e1 havia conclu\u00eddo que os ind\u00edcios levantados apontavam para a aus\u00eancia de mandantes ou de incentivadores envolvidos com Bispo.<\/p>\n<p>Entretanto, a PF instaurou esse segundo inqu\u00e9rito no qual realizou uma devassa na vida de Bispo e de pessoas ligadas a ele. Um dos alvos dessa nova investiga\u00e7\u00e3o foi o advogado Zanone Manoel de Oliveira J\u00fanior, defensor de Bispo.<\/p>\n<p>Em dezembro do ano passado a PF chegou a realizar uma busca e apreens\u00e3o no escrit\u00f3rio do advogado para tentar angariar informa\u00e7\u00f5es sobre quem financiou a defesa de Bispo. Outra linha de apura\u00e7\u00e3o seguida pela PF foi sobre o poss\u00edvel envolvimento do Primeiro Comando Da Capital (PCC) no caso. As duas teses foram descartadas na investiga\u00e7\u00e3o conduzida pelo delegado Rodrigo de Morais.<\/p>\n<p><strong>Hist\u00f3rico<\/strong> &#8211; Em setembro do ano passado, a PF havia conclu\u00eddo um primeiro inqu\u00e9rito instaurado logo ap\u00f3s o atentando. Nessa primeira investiga\u00e7\u00e3o, encerrada em 28 de setembro, a PF n\u00e3o encontrou ind\u00edcios da participa\u00e7\u00f5es de outras pessoas e concluiu que Bispo agiu por \u201cinconformismo pol\u00edtico\u201d.<\/p>\n<p>\u00c0 \u00e9poca, o delegado do caso afirmou ao Estado que a an\u00e1lise do material permitiu afirmar que \u201ca motiva\u00e7\u00e3o foi o inconformismo pol\u00edtico em rela\u00e7\u00e3o ao candidato Jair Bolsonaro\u201d. Bispo, disse o delegado, se disse adepto da ideologia pol\u00edtica de esquerda enquanto Bolsonaro seria de extrema-direita.<\/p>\n<p>\u201cFicou claro que havia essa discord\u00e2ncia em rela\u00e7\u00e3o aos projetos pol\u00edticos do candidato. Dessa forma se configurou o crime contra a seguran\u00e7a nacional\u201d, explicou Morais.<\/p>\n<p>Bispo foi indiciado no artigo 20 da Lei de Seguran\u00e7a Nacional que fala sobre atentado a pessoas por inconformismo pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em reuni\u00e3o realizada nesta segunda-feira, 25, a Pol\u00edcia Federal informou ao presidente Jair Bolsonaro que, at\u00e9 agora, n\u00e3o h\u00e1 evid\u00eancia da participa\u00e7\u00e3o de outras pessoas al\u00e9m de Ad\u00e9lio Bispo no atentado cometido contra o presidente em setembro. A PF explicou que o inqu\u00e9rito ainda est\u00e1 em andamento. Falta concluir a an\u00e1lise dos materiais apreendidos com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":190268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-203507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203507"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203507\/revisions"}],"predecessor-version":[{"id":203511,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203507\/revisions\/203511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/190268"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}