{"id":203578,"date":"2019-02-26T13:21:07","date_gmt":"2019-02-26T16:21:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203578"},"modified":"2019-02-26T13:21:54","modified_gmt":"2019-02-26T16:21:54","slug":"brb-agiliza-entrega-do-cartao-escolar","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/brb-agiliza-entrega-do-cartao-escolar\/","title":{"rendered":"BRB agiliza entrega do cart\u00e3o escolar"},"content":{"rendered":"<p>O Banco de Bras\u00edlia preparando a emiss\u00e3o de 40,8 mil cart\u00f5es de material escolar. A iniciativa traz de volta um benef\u00edcio suspenso pelo ex-governador Rodrigo Rollemberg e reativado por Ibaneis Rocha, atual ocupante do Pal\u00e1cio do Buriti. Com a medida ser\u00e3o injetados cerca de 20 milh\u00f5es de reais na economia do Distrito Federal.<\/p>\n<p>Com a emiss\u00e3o dos cart\u00f5es, ser\u00e3o beneficiados 64 mil 652 estudantes, conforme o cadastro do Bolsa Fam\u00edlia. Os repasses anuais s\u00e3o nos valoires de 320 reais para 55 mil 882 estudantes do Ensino Fundamental e 240 reais para 8 mil 770 alunos do Ensino M\u00e9dio.<\/p>\n<p>Paulo Henrique Costa, presidente do BRB, avalia que o papel do banco \u00e9 fundamental para o sucesso do programa. &#8220;Vamos emitir os cart\u00f5es \u00e0s fam\u00edlias e equipar a rede parceira com os equipamentos. Contribu\u00edmos com a inje\u00e7\u00e3o de recursos na economia e cumprimos nosso papel no desenvolvimento social e humano do Distrito Federal&#8221;, disse.<\/p>\n<p>Cada fam\u00edlia beneficiada receber\u00e1 apenas um cart\u00e3o, ainda que tenha mais de um filho beneficiado. Nesses casos, o cart\u00e3o ser\u00e1 entregue na escola do filho mais novo. A previs\u00e3o \u00e9 de que a distribui\u00e7\u00e3o ocorra j\u00e1 no pr\u00f3ximo m\u00eas.<\/p>\n<p>De acordo com a Secretaria de Educa\u00e7\u00e3o, est\u00e3o previstas mais de 300 papelarias credenciadas. A todas as lojas selecionadas ser\u00e3o entregues a maquineta do BRB, a ser utilizada para recebimento dos cart\u00f5es. O cart\u00e3o funcionar\u00e1 na fun\u00e7\u00e3o de d\u00e9bito, para esta finalidade espec\u00edfica, e ser\u00e1 aceito somente nas papelarias credenciadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Banco de Bras\u00edlia preparando a emiss\u00e3o de 40,8 mil cart\u00f5es de material escolar. A iniciativa traz de volta um benef\u00edcio suspenso pelo ex-governador Rodrigo Rollemberg e reativado por Ibaneis Rocha, atual ocupante do Pal\u00e1cio do Buriti. Com a medida ser\u00e3o injetados cerca de 20 milh\u00f5es de reais na economia do Distrito Federal. Com a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":200064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-203578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203578"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203578\/revisions"}],"predecessor-version":[{"id":203580,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203578\/revisions\/203580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/200064"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}