{"id":203722,"date":"2019-02-28T12:08:05","date_gmt":"2019-02-28T15:08:05","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203722"},"modified":"2019-02-28T12:08:35","modified_gmt":"2019-02-28T15:08:35","slug":"congresso-troca-tapetas-e-suspende-visitas-publicas","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/congresso-troca-tapetas-e-suspende-visitas-publicas\/","title":{"rendered":"Congresso troca tapetes e cancela visitas p\u00fablicas"},"content":{"rendered":"<p>Quem estiver em Bras\u00edlia durante o carnaval com planos de conhecer a C\u00e2mara dos Deputados e o Senado ter\u00e1 que refazer a programa\u00e7\u00e3o.<\/p>\n<p>\u00c9 que entre o s\u00e1bado (2) at\u00e9 a quarta-feira de cinzas (6), a visita\u00e7\u00e3o nas duas Casas estar\u00e1 fechada para troca o carpete do Sal\u00e3o Verde e das Galerias do Plen\u00e1rio da C\u00e2mara.<\/p>\n<p>Segundo o coordenador de Visita\u00e7\u00e3o Institucional do Senado, Tadeu Sposito do Amaral, o procedimento inviabiliza a presen\u00e7a de visitantes devido ao forte cheiro de cola nessas \u00e1reas.<\/p>\n<p>No Senado, durante a folia, o foco ser\u00e1 na limpeza carpete do Sal\u00e3o Azul, impedindo o tr\u00e2nsito de pessoas pelo espa\u00e7o.<\/p>\n<p>\u201cSentimos por fecharmos o tour justamente em um momento em que muitos turistas visitam Bras\u00edlia, mas as interven\u00e7\u00f5es s\u00e3o importantes para a conserva\u00e7\u00e3o do pr\u00e9dio. \u00c9 natural que obras e reparos ocorram nessas ocasi\u00f5es, j\u00e1 que n\u00e3o h\u00e1 trabalho legislativo, atividade-fim do parlamento\u201d, justificou Amaral.<\/p>\n<p>A visita\u00e7\u00e3o \u00e9 gratuita e ser\u00e1 reaberta na quinta-feira (7) para visitas agendadas previamente pelo site do Congresso (www.congressonacional.leg.br\/visite). As visitas sem marca\u00e7\u00e3o ser\u00e3o retomadas somente na sexta-feira (8) com grupos saindo a cada meia hora, de 9h \u00e0s 17h30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem estiver em Bras\u00edlia durante o carnaval com planos de conhecer a C\u00e2mara dos Deputados e o Senado ter\u00e1 que refazer a programa\u00e7\u00e3o. \u00c9 que entre o s\u00e1bado (2) at\u00e9 a quarta-feira de cinzas (6), a visita\u00e7\u00e3o nas duas Casas estar\u00e1 fechada para troca o carpete do Sal\u00e3o Verde e das Galerias do Plen\u00e1rio da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-203722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203722"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203722\/revisions"}],"predecessor-version":[{"id":203725,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203722\/revisions\/203725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/203723"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}