{"id":203750,"date":"2019-02-28T18:37:41","date_gmt":"2019-02-28T21:37:41","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203750"},"modified":"2019-02-28T18:39:04","modified_gmt":"2019-02-28T21:39:04","slug":"foliao-pula-de-raiva-com-novo-aumento-da-gasolina","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/foliao-pula-de-raiva-com-novo-aumento-da-gasolina\/","title":{"rendered":"Foli\u00e3o pula de raiva com um novo aumento de 2% no litro da gasolina"},"content":{"rendered":"<p>A Petrobras anunciou alta de 1,98% no pre\u00e7o m\u00e9dio do litro da gasolina A sem tributo nas refinarias, v\u00e1lido para sexta-feira, 1, para R$ 1,6865. Al\u00e9m disso, a estatal manteve sem altera\u00e7\u00e3o o pre\u00e7o do diesel, em R$ 2,1224, conforme tabela dispon\u00edvel no site da empresa.<\/p>\n<p>Em dezembro, a Petrobras anunciou um mecanismo de prote\u00e7\u00e3o complementar em que ela pode alterar a frequ\u00eancia dos reajustes di\u00e1rios do pre\u00e7o do diesel no mercado interno em momento de elevada volatilidade, podendo mant\u00ea-lo est\u00e1vel por curtos per\u00edodos de tempo de at\u00e9 sete dias, &#8216;conciliando seus interesses empresariais com as demandas de seus clientes e agentes de mercado em geral&#8217;.<\/p>\n<p>J\u00e1 o hedge da gasolina, que passou a ser adotado em setembro, permite \u00e0 empresa manter os valores est\u00e1veis nas refinarias por at\u00e9 15 dias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Petrobras anunciou alta de 1,98% no pre\u00e7o m\u00e9dio do litro da gasolina A sem tributo nas refinarias, v\u00e1lido para sexta-feira, 1, para R$ 1,6865. Al\u00e9m disso, a estatal manteve sem altera\u00e7\u00e3o o pre\u00e7o do diesel, em R$ 2,1224, conforme tabela dispon\u00edvel no site da empresa. Em dezembro, a Petrobras anunciou um mecanismo de prote\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":190096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-203750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203750"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203750\/revisions"}],"predecessor-version":[{"id":203753,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203750\/revisions\/203753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/190096"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}