{"id":203876,"date":"2019-03-02T04:10:53","date_gmt":"2019-03-02T07:10:53","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=203876"},"modified":"2019-03-02T09:15:49","modified_gmt":"2019-03-02T12:15:49","slug":"tucuruvi-lembra-que-liberdade-e-o-unico-caminho","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/tucuruvi-lembra-que-liberdade-e-o-unico-caminho\/","title":{"rendered":"Tucuruvi lembra que liberdade \u00e9 o \u00fanico caminho"},"content":{"rendered":"<p>Entrou no samb\u00f3dromo do Anhembi, em S\u00e3o Paulo, pouco antes das 3 horas deste s\u00e1bado, 2, a Acad\u00eamicos do Tucuruvi, a quarta escola de samba deste 1\u00b0 dia de desfiles do grupo especial do carnaval 2019. Com o enredo &#8220;Liberdade&#8230; O canto retumbante de um povo heroico&#8221;, este ano a Tucuruvi leva para a avenida 2,8 mil integrantes, vinte e duas alas e cinco alegorias.<\/p>\n<p>A avenida ficou pontilhada das principais cores da escola: azul, branco, vermelho e amarelo. O primeiro carro aleg\u00f3rico \u00e9 um navio com um esqueleto na proa, utilizado para mostrar a rela\u00e7\u00e3o do colonizador com o \u00edndio colonizado nas origens do Brasil.<\/p>\n<p>Na letra da escola, s\u00e3o feitas refer\u00eancias a can\u00e7\u00f5es de Geraldo Vandr\u00e9 (&#8220;Quem sabe faz a hora, n\u00e3o espera acontecer&#8230;&#8221;), Chico Buarque (&#8220;Apesar de voc\u00ea&#8230;&#8221;) e Caetano Veloso (&#8220;Caminhar contra o vento, eu vou&#8221;&#8230;).<\/p>\n<p>A composi\u00e7\u00e3o fala de liberdade e rompimento de barreiras, em tom pol\u00edtico, mas com foco nos movimentos sociais e nas manifesta\u00e7\u00f5es, como Parada Gay e greve dos professores.<\/p>\n<p>Fechando o desfile, o \u00faltimo carro aleg\u00f3rico tem como tem\u00e1tica o embate pol\u00edtico-eleitoral entre #EleN\u00e3o e #EleSim, que dominou as redes sociais entre apoiadores e opositores do presidente Jair Bolsonaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrou no samb\u00f3dromo do Anhembi, em S\u00e3o Paulo, pouco antes das 3 horas deste s\u00e1bado, 2, a Acad\u00eamicos do Tucuruvi, a quarta escola de samba deste 1\u00b0 dia de desfiles do grupo especial do carnaval 2019. Com o enredo &#8220;Liberdade&#8230; O canto retumbante de um povo heroico&#8221;, este ano a Tucuruvi leva para a avenida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":203878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-203876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=203876"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203876\/revisions"}],"predecessor-version":[{"id":203879,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/203876\/revisions\/203879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/203878"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=203876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=203876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=203876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}