{"id":204198,"date":"2019-03-06T18:14:48","date_gmt":"2019-03-06T21:14:48","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=204198"},"modified":"2019-03-06T18:14:48","modified_gmt":"2019-03-06T21:14:48","slug":"mangueira-fica-com-titulo-com-homenagem-a-marielle","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/mangueira-fica-com-titulo-com-homenagem-a-marielle\/","title":{"rendered":"Mangueira fica com t\u00edtulo com homenagem a Marielle"},"content":{"rendered":"<p>Com homenagem \u00e0 vereadora Marielle Franco, a Esta\u00e7\u00e3o Primeira de Mangueira venceu o carnaval do Rio de 2019. A leitura das notas das escolas de samba foi realizada nesta Quarta-feira de Cinzas, 6, na Marqu\u00eas de Sapuca\u00ed, sob clima de comemora\u00e7\u00e3o entre diretores da agremia\u00e7\u00e3o e torcedores na quadra da escola. A Mangueira liderou a apura\u00e7\u00e3o desde o primeiro quesito e conquistou neste ano seu vig\u00e9simo t\u00edtulo.<\/p>\n<p>Sexta escola a se apresentar na segunda noite de desfiles, j\u00e1 ao amanhecer de ter\u00e7a-feira, 5, a verde e rosa se equiparou a outras em fantasias e alegorias, mas arrebatou a plateia com uma comovente homenagem a Marielle Franco (PSOL), assassinada em mar\u00e7o de 2018 no centro do Rio. A parlamentar era citada nominalmente no samba, o mais cantado deste carnaval.<\/p>\n<p>Marielle foi figura central de um enredo que elogiava her\u00f3is populares brasileiros n\u00e3o reconhecidos na maioria dos livros did\u00e1ticos e demais registros hist\u00f3ricos. O auge da como\u00e7\u00e3o ocorreu na parte final do desfile, onde correligion\u00e1rios, familiares e apoiadores da vereadora balan\u00e7avam bandeiras com retratos de Marielle e outras lideran\u00e7as populares, enquanto outros carregavam uma imensa bandeira do Brasil onde o lema positivista \u201cordem e progresso\u201d foi substitu\u00eddo por \u201c\u00edndios, negros e pobres\u201d.<\/p>\n<p>Entre as pessoas que empunharam bandeiras figuram o deputado federal Marcelo Freixo e o vereador Tarc\u00edsio Motta, ambos do PSOL. M\u00f4nica Ben\u00edcio, vi\u00fava de Marielle, tamb\u00e9m desfilou, mas apenas com uma camisa que homenageava a parlamentar.<\/p>\n<p>Outra men\u00e7\u00e3o a Marielle era feita na comiss\u00e3o de frente, que virava a hist\u00f3ria oficial pelo avesso: figuras hist\u00f3ricas tradicionalmente reconhecidas, representadas como an\u00f5es, eram substitu\u00eddas por \u00edndios e negros. Na encena\u00e7\u00e3o, as novas personalidades erguiam uma menina que, representando Marielle, empunhava uma faixa onde se lia \u201cpresente\u201d. O coro de \u201cMarielle: presente\u201d \u00e9 uma forma frequente de homenagear a vereadora morta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com homenagem \u00e0 vereadora Marielle Franco, a Esta\u00e7\u00e3o Primeira de Mangueira venceu o carnaval do Rio de 2019. A leitura das notas das escolas de samba foi realizada nesta Quarta-feira de Cinzas, 6, na Marqu\u00eas de Sapuca\u00ed, sob clima de comemora\u00e7\u00e3o entre diretores da agremia\u00e7\u00e3o e torcedores na quadra da escola. A Mangueira liderou a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":204199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-204198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=204198"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204198\/revisions"}],"predecessor-version":[{"id":204200,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204198\/revisions\/204200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/204199"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=204198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=204198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=204198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}