{"id":204583,"date":"2019-03-12T13:42:55","date_gmt":"2019-03-12T16:42:55","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=204583"},"modified":"2019-03-12T14:51:18","modified_gmt":"2019-03-12T17:51:18","slug":"delacao-pode-revelar-quem-mandou-matar-marielle-franco","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/delacao-pode-revelar-quem-mandou-matar-marielle-franco\/","title":{"rendered":"Dela\u00e7\u00e3o pode revelar quem mandou matar Marielle Franco"},"content":{"rendered":"<p>O governador do Rio de Janeiro, Wilson Witzel (PSC), disse que os suspeitos presos nesta ter\u00e7a-feira, 12, no caso Marielle &#8220;poder\u00e3o pensar na dela\u00e7\u00e3o premiada&#8221; para que a investiga\u00e7\u00e3o chegue aos mandantes do crime. Ele reuniu autoridades da Pol\u00edcia Civil e os delegados respons\u00e1veis pelo inqu\u00e9rito para apresentar o resultado do que classificou como 1\u00aa fase da apura\u00e7\u00e3o. Uma 2\u00aa fase seria a respons\u00e1vel para chegar aos mandantes do assassinato.<\/p>\n<p>Witzel comemorou a &#8220;resposta dada \u00e0 sociedade&#8221;. O delegado Giniton Lages, respons\u00e1vel pelo inqu\u00e9rito, detalhou que a investiga\u00e7\u00e3o ouviu 230 testemunhas, interceptou 318 linhas telef\u00f4nicas e chegou a um intricado rastro de vest\u00edgios deixados pelos suspeitos. &#8220;Foi uma execu\u00e7\u00e3o sofisticada e que n\u00e3o teve erro por parte dos criminosos. Eles n\u00e3o desceram do carro em nenhum momento, n\u00e3o fizeram liga\u00e7\u00e3o, n\u00e3o deram oportunidade para que a investiga\u00e7\u00e3o chegasse at\u00e9 eles&#8221;, disse Lages.<\/p>\n<p>O delegado disse que nenhuma linha de investiga\u00e7\u00e3o est\u00e1 afastada para a 2\u00aa fase. No entanto, Lages esclareceu que a testemunha que havia tentado ligar o vereador Marcello Siciliano e Orlando de Curicica ao caso voltou atr\u00e1s da declara\u00e7\u00e3o e poder\u00e1 ser responsabilizado por isso. &#8220;Mesmo assim, n\u00e3o afastamos a possibilidade de Siciliano nem de ningu\u00e9m na 2\u00aa fase da apura\u00e7\u00e3o.&#8221;<\/p>\n<p>O delegado Giniton, respons\u00e1vel pela investiga\u00e7\u00e3o do assassinato de Marielle Franco, afirmou que a execu\u00e7\u00e3o da vereadora pelo pm reformado Ronnie Lessa &#8220;foi um crime de \u00f3dio&#8221; realizado &#8220;por motivo torpe&#8221;. O delegado afirmou que neste momento a pol\u00edcia m\u00e3o sabe quem foram os mandantes do crime e a motiva\u00e7\u00e3o do assassinato.<\/p>\n<p>Na entrevista coletiva que durou quase duas horas, o delegado contou que nos meses que antecederam o crime, Lessa teria feito v\u00e1rias pesquisas online n\u00e3o s\u00f3 sobre Marielle Franco, mas tamb\u00e9m sobre o ent\u00e3o deputado estadual Marcelo freixo e sua fam\u00edlia. Segundo o delegado, Lessa demonstrava \u00f3dio dos parlamentares por conta de ideologia pol\u00edtica.<\/p>\n<p>Ronie Lessa, policial militar reformado, e Elcio Vieira de Queiroz, expulso da Pol\u00edcia Militar, foram denunciados por homic\u00eddio qualificado e por tentativa de homic\u00eddio de Fernanda Chaves, uma das assessoras de Marielle que tamb\u00e9m estava no carro. A pris\u00e3o \u00e9 resultado de uma opera\u00e7\u00e3o conjunta do Minist\u00e9rio P\u00fablico, por meio do Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (Gaeco), e da Pol\u00edcia Civil do Rio de Janeiro.<\/p>\n<p>Al\u00e9m dos mandados de pris\u00e3o, a Opera\u00e7\u00e3o Lume cumpre mandados de busca e apreens\u00e3o em endere\u00e7os dos dois acusados para apreender documentos, celulares, computadores, armas, muni\u00e7\u00f5es e outros objetos. Ap\u00f3s a pris\u00e3o dos suspeitos, parlamentares do PSOL e a vi\u00fava de Marielle pediram que as investiga\u00e7\u00f5es continuem para descobrir o mandante do crime.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador do Rio de Janeiro, Wilson Witzel (PSC), disse que os suspeitos presos nesta ter\u00e7a-feira, 12, no caso Marielle &#8220;poder\u00e3o pensar na dela\u00e7\u00e3o premiada&#8221; para que a investiga\u00e7\u00e3o chegue aos mandantes do crime. Ele reuniu autoridades da Pol\u00edcia Civil e os delegados respons\u00e1veis pelo inqu\u00e9rito para apresentar o resultado do que classificou como 1\u00aa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":204584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-204583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=204583"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204583\/revisions"}],"predecessor-version":[{"id":204585,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204583\/revisions\/204585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/204584"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=204583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=204583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=204583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}