{"id":204586,"date":"2019-03-12T16:10:28","date_gmt":"2019-03-12T19:10:28","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=204586"},"modified":"2019-03-13T08:15:48","modified_gmt":"2019-03-13T11:15:48","slug":"stj-manda-caixa-indenizar-caseiro-que-derrubou-antonio-palocci","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/stj-manda-caixa-indenizar-caseiro-que-derrubou-antonio-palocci\/","title":{"rendered":"STJ manda Caixa indenizar caseiro do caso Palocci"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) confirmou nesta ter\u00e7a (12), por unanimidade, a indeniza\u00e7\u00e3o de R$ 400 mil &#8211; com a devida corre\u00e7\u00e3o monet\u00e1ria &#8211; a ser paga pela Caixa ao caseiro Francenildo dos Santos Costa, pela quebra indevida de seu sigilo banc\u00e1rio. Em 2006, o caso resultou na sa\u00edda de Ant\u00f4nio Palocci do comando do Minist\u00e9rio da Fazenda.<\/p>\n<p>O sigilo banc\u00e1rio de Francenildo foi violado ap\u00f3s depoimento na Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) dos Bingos. O caseiro disse \u00e0 CPI que Palocci se encontrava com lobistas em uma mans\u00e3o localizada em uma \u00e1rea nobre de Bras\u00edlia. Em seguida \u00e0s declara\u00e7\u00f5es, a revista \u00c9poca publicou que o caseiro havia recebido R$ 38 mil em sua conta.<\/p>\n<p>Em 2010, o Tribunal de Justi\u00e7a do Distrito Federal e Territ\u00f3rios (TJDFT) deu ganho de causa ao caseiro e estipulou a multa a ser paga pela Caixa em R$ 500 mil. Cinco anos depois, o Tribunal Regional Federal da 1\u00aa Regi\u00e3o (TRF1) corrigiu a quantia para R$ 400 mil, valor agora confirmado pelo STJ.<\/p>\n<p>Tamb\u00e9m processada por expor a imagem de Francenildo, a editora Globo, respons\u00e1vel pela revista \u00c9poca, n\u00e3o ter\u00e1 que indenizar o caseiro, de acordo com a decis\u00e3o do STJ.<\/p>\n<p>Na esfera criminal, a maioria dos ministros do Supremo Tribunal Federal (STF) arquivou, em 2009, o inqu\u00e9rito envolvendo Palocci, por entender que n\u00e3o haver ind\u00edcios suficientes de que o ent\u00e3o ministro da Fazenda teve participa\u00e7\u00e3o na viola\u00e7\u00e3o do sigilo banc\u00e1rio do caseiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) confirmou nesta ter\u00e7a (12), por unanimidade, a indeniza\u00e7\u00e3o de R$ 400 mil &#8211; com a devida corre\u00e7\u00e3o monet\u00e1ria &#8211; a ser paga pela Caixa ao caseiro Francenildo dos Santos Costa, pela quebra indevida de seu sigilo banc\u00e1rio. Em 2006, o caso resultou na sa\u00edda de Ant\u00f4nio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":204587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-204586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=204586"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204586\/revisions"}],"predecessor-version":[{"id":204628,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204586\/revisions\/204628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/204587"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=204586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=204586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=204586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}