{"id":204772,"date":"2019-03-15T13:22:34","date_gmt":"2019-03-15T16:22:34","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=204772"},"modified":"2019-03-15T15:37:30","modified_gmt":"2019-03-15T18:37:30","slug":"professor-armado-e-preso-ao-exigir-conversa-com-secretario","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/professor-armado-e-preso-ao-exigir-conversa-com-secretario\/","title":{"rendered":"Professor armado \u00e9 preso ao exigir conversa com secret\u00e1rio"},"content":{"rendered":"<p>Um professor de 53 anos entrou no pr\u00e9dio da Secretaria de Educa\u00e7\u00e3o, no Setor Banc\u00e1rio Norte, com uma faca, dardos e uma besta, mesmo tipo de arma usada pelos jovens envolvidos no atentado na Escola Estadual Professor Raul Brasil, em Suzano (SP). O homem foi preso e encaminhado \u00e0 5\u00ba Delegacia de Pol\u00edcia do DF. De acordo com a Pol\u00edcia Militar, n\u00e3o houve feridos.<\/p>\n<p>Segundo a PM, o homem chegou \u00e0 secretaria por volta das 12 horas desta sexta, 15, dizendo que queria uma conversa com o Secret\u00e1rio de Educa\u00e7\u00e3o, Rafael Parente. A seguran\u00e7a chamou a Pol\u00edcia Militar, porque o homem estava muito alterado.<\/p>\n<p>Policiais chegaram ao local e abordaram o professor. Em nota, a PM diz que o homem ofereceu resist\u00eancia, mas os policiais conseguiram imobiliz\u00e1-lo. Dentro da mochila dele foram encontrados uma faca Imbel, uma besta e tr\u00eas dardos. &#8220;O homem alegou que queria encontrar o secret\u00e1rio, que queria mostrar esses armamentos, depois iria cometer suic\u00eddio&#8221;, informa o comunicado.<\/p>\n<p>De acordo com a Secretaria de Educa\u00e7\u00e3o, o professor subiu at\u00e9 a assessoria do gabinete, no 12\u00aa andar. &#8220;Funcion\u00e1rios perceberam o cabo da besta para fora da mochila que ele carregava e acionaram a PM. Dois policiais chegaram rapidamente e o renderam&#8221;, diz tamb\u00e9m em nota. O professor n\u00e3o chegou a utilizar as armas.<\/p>\n<p>Pelo Twitter, Rafael Parente disse que o governador em exerc\u00edcio, Paco Britto, determinou o afastamento imediato do professor e a abertura de processo administrativo disciplinar (PAD) contra ele. Nem a Secretaria de Educa\u00e7\u00e3o nem a PM confirmaram, at\u00e9 o momento, a identidade do homem.<\/p>\n<p>Tamb\u00e9m na rede social, o secret\u00e1rio de Educa\u00e7\u00e3o diz que registrou alguns casos de amea\u00e7as de alunos. &#8220;A Secretaria de Seguran\u00e7a e toda a intelig\u00eancia do GDF [governo do Distrito Federal] j\u00e1 est\u00e3o em a\u00e7\u00e3o, dentro de algumas escolas e \u00e0 paisana&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um professor de 53 anos entrou no pr\u00e9dio da Secretaria de Educa\u00e7\u00e3o, no Setor Banc\u00e1rio Norte, com uma faca, dardos e uma besta, mesmo tipo de arma usada pelos jovens envolvidos no atentado na Escola Estadual Professor Raul Brasil, em Suzano (SP). O homem foi preso e encaminhado \u00e0 5\u00ba Delegacia de Pol\u00edcia do DF. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":204773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-204772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=204772"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204772\/revisions"}],"predecessor-version":[{"id":204777,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204772\/revisions\/204777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/204773"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=204772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=204772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=204772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}