{"id":204910,"date":"2019-03-17T09:32:41","date_gmt":"2019-03-17T12:32:41","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=204910"},"modified":"2019-03-17T11:35:39","modified_gmt":"2019-03-17T14:35:39","slug":"classe-c-volta-a-crescer-e-aumenta-o-consumo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/classe-c-volta-a-crescer-e-aumenta-o-consumo\/","title":{"rendered":"Classe C volta a crescer e aumenta o consumo"},"content":{"rendered":"<p>Uma d\u00e9cada depois da cria\u00e7\u00e3o do termo \u201cnova classe m\u00e9dia\u201d, essa parcela da popula\u00e7\u00e3o no Brasil voltou a crescer de 2017 para 2018 \u2013 passando de 50% a 51% da popula\u00e7\u00e3o, uma adi\u00e7\u00e3o de mais de 2 milh\u00f5es de pessoas \u2013 ap\u00f3s uma queda brusca nos dois anos anteriores.<\/p>\n<p>Embora ainda n\u00e3o tenham recuperado tudo o que perderam durante o per\u00edodo em que a economia recuou 8%, as fam\u00edlias da classe C est\u00e3o otimistas com o que est\u00e1 por vir e pretendem voltar a comprar bens de maior valor agregado, como eletrodom\u00e9sticos e materiais de constru\u00e7\u00e3o, segundo pesquisa do Instituto Locomotiva. Mas a busca por essas metas n\u00e3o ser\u00e1 a qualquer pre\u00e7o: o consumo-ostenta\u00e7\u00e3o dos tempos de bonan\u00e7a foi substitu\u00eddo pela exig\u00eancia de um claro custo-benef\u00edcio.<\/p>\n<p>Essa nova rela\u00e7\u00e3o com o consumo \u00e9 \u201ccaminho sem volta\u201d, segundo Renato Meirelles, presidente do Instituto Locomotiva, especializado em estudar os h\u00e1bitos da classe C. Com o aumento ainda t\u00edmido \u2013 de 0,9% \u2013 da renda desse contingente no ano passado, para convencer os 106 milh\u00f5es de membros da classe m\u00e9dia a gastar o dinheiro que t\u00eam em m\u00e3os \u2013 montante estimado em R$ 1,57 trilh\u00e3o para 2019 \u2013, as empresas ter\u00e3o de suar.<\/p>\n<p>\u201cAs marcas v\u00e3o precisar saber muito mais sobre os h\u00e1bitos desses consumidores para convenc\u00ea-los a abrir a carteira\u201d, diz Meirelles. \u201cO consumo agora n\u00e3o vai estar mais ligado ao acesso a qualquer custo, \u00e0 ostenta\u00e7\u00e3o, mas sim \u00e0 performance e \u00e0 relev\u00e2ncia de cada produto.\u201d<\/p>\n<p>Esse retorno ao consumo \u00e9 pautado muito mais pela expectativa do que por avan\u00e7os econ\u00f4micos consistentes. Isso porque tanto o emprego quanto a renda ainda est\u00e3o longe de recuperar os n\u00edveis anteriores \u00e0 crise. Apesar da queda da infla\u00e7\u00e3o e do juro b\u00e1sico no patamar m\u00ednimo de 6,5% ao ano, o desemprego est\u00e1 na faixa de 12%, segundo dados do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/p>\n<p>Para este ano, no entanto, as expectativas de crescimento do PIB ainda se situam em cerca de 2%, apesar de redu\u00e7\u00f5es recentes nas estimativas, o que pode ter um efeito positivo especialmente para a classe m\u00e9dia. Segundo c\u00e1lculos da consultoria MacroSector, a renda da classe C poder\u00e1 crescer 3,5% em 2019, sobre o ano passado. A consultoria tamb\u00e9m projeta alta de 3% para as vendas no varejo este ano.<\/p>\n<p>Todas essas perspectivas, no entanto, dependem de fatores ainda n\u00e3o concretizados \u2013 como a aprova\u00e7\u00e3o das reformas estruturais no Congresso. \u201cH\u00e1 uma expectativa de crescimento respaldada na aprova\u00e7\u00e3o das reformas. Caso isso n\u00e3o ocorra, podemos entrar numa crise pior do que a de 2014\u201d, afirma Jos\u00e9 Ronaldo Souza J\u00fanior, economista do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma d\u00e9cada depois da cria\u00e7\u00e3o do termo \u201cnova classe m\u00e9dia\u201d, essa parcela da popula\u00e7\u00e3o no Brasil voltou a crescer de 2017 para 2018 \u2013 passando de 50% a 51% da popula\u00e7\u00e3o, uma adi\u00e7\u00e3o de mais de 2 milh\u00f5es de pessoas \u2013 ap\u00f3s uma queda brusca nos dois anos anteriores. Embora ainda n\u00e3o tenham recuperado tudo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-204910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=204910"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204910\/revisions"}],"predecessor-version":[{"id":204911,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/204910\/revisions\/204911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/199741"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=204910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=204910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=204910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}