{"id":205072,"date":"2019-03-19T11:45:02","date_gmt":"2019-03-19T14:45:02","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205072"},"modified":"2019-03-19T11:45:02","modified_gmt":"2019-03-19T14:45:02","slug":"ser-aliado-de-trump-e-bom-mas-subalterno-nao","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/","title":{"rendered":"&#8216;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#8217;"},"content":{"rendered":"<p>Os sinais de uma pol\u00edtica externa &#8220;altamente ideol\u00f3gica&#8221; dados pelo governo do presidente Jair Bolsonaro, que se encontrar\u00e1 nesta ter\u00e7a-feira, 19, com seu colega americano, Donald Trump, podem afastar o Brasil de outras na\u00e7\u00f5es e ser &#8220;profundamente negativos&#8221; para os interesses do pa\u00eds.<\/p>\n<p>Essa \u00e9 a vis\u00e3o do embaixador aposentado Roberto Abdenur, que comandou a embaixada brasileira nos Estados Unidos de 2004 a 2006 e deixou o Itamaraty por discord\u00e2ncias com a pol\u00edtica externa do ent\u00e3o presidente Luiz In\u00e1cio da Silva.<\/p>\n<p>Ao desembarcar nos EUA no domingo para uma visita de tr\u00eas dias, Bolsonaro tuitou que &#8220;pela primeira vez em muito tempo, um Presidente brasileiro que n\u00e3o \u00e9 antiamericano chega a Washington&#8221;, mas para Abdenur, o que distingue a visita de viagens oficiais de presidentes anteriores \u00e9 o risco de um &#8220;alinhamento autom\u00e1tico, r\u00edgido&#8221; do Brasil aos interesses americanos.<\/p>\n<p>&#8220;Paradoxalmente, o governo Bolsonaro, que tanto insiste na defesa da soberania do Brasil, est\u00e1 afetando, prejudicando essa soberania, se decidir alinhar-se incondicionalmente com os Estados Unidos no campo da pol\u00edtica internacional. Eu vejo com preocupa\u00e7\u00e3o o risco de que isso ocorra&#8221;, afirmou Abdenur.<\/p>\n<p>O diplomata, que iniciou sua carreira no Itamaraty em 1963 e chefiou tamb\u00e9m as embaixadas do Brasil no Equador, Alemanha e China, critica, tamb\u00e9m, a &#8220;atitude radicalmente simp\u00e1tica aos Estados Unidos&#8221; do chanceler Ernesto Ara\u00fajo.<\/p>\n<p>&#8220;Eu temo muito que o presidente acabe, sem se dar conta disso, talvez sem querer, se colocando numa postura subalterna ao Trump. Eu espero que isso n\u00e3o ocorra, mas \u00e9 uma hip\u00f3tese que n\u00e3o pode der descartada&#8221;, disse.<\/p>\n<p>Embora Abdenur veja poss\u00edveis ganhos para o Brasil na esfera econ\u00f4mica a partir da maior aproxima\u00e7\u00e3o com os Estados Unidos, ele v\u00ea um grande risco caso Bolsonaro decida se alinhar aos interesses de Trump contra a China.<\/p>\n<p>O embaixador n\u00e3o se op\u00f4s \u00e0 pol\u00eamica decis\u00e3o do governo brasileiro de isentar unilateralmente os turistas americanos de visto para entrada no Brasil, mas repudiou declara\u00e7\u00f5es do deputado federal e filho do presidente, Eduardo Bolsonaro, manifestando vergonha pelos imigrantes brasileiros que vivem ilegalmente nos Estados Unidos.<\/p>\n<p>&#8220;Essa declara\u00e7\u00e3o \u00e9 inaceit\u00e1vel, \u00e9 desrespeitosa para com compatriotas nossos que t\u00eam buscado no exterior h\u00e1 d\u00e9cadas oportunidades que n\u00e3o tiveram no Brasil&#8221;, ressaltou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os sinais de uma pol\u00edtica externa &#8220;altamente ideol\u00f3gica&#8221; dados pelo governo do presidente Jair Bolsonaro, que se encontrar\u00e1 nesta ter\u00e7a-feira, 19, com seu colega americano, Donald Trump, podem afastar o Brasil de outras na\u00e7\u00f5es e ser &#8220;profundamente negativos&#8221; para os interesses do pa\u00eds. Essa \u00e9 a vis\u00e3o do embaixador aposentado Roberto Abdenur, que comandou a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"tmauthors":[],"class_list":["post-205072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","tag-capa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#039; - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#039; - Notibras\" \/>\n<meta property=\"og:description\" content=\"Os sinais de uma pol\u00edtica externa &#8220;altamente ideol\u00f3gica&#8221; dados pelo governo do presidente Jair Bolsonaro, que se encontrar\u00e1 nesta ter\u00e7a-feira, 19, com seu colega americano, Donald Trump, podem afastar o Brasil de outras na\u00e7\u00f5es e ser &#8220;profundamente negativos&#8221; para os interesses do pa\u00eds. Essa \u00e9 a vis\u00e3o do embaixador aposentado Roberto Abdenur, que comandou a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-19T14:45:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"&#8216;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#8217;\",\"datePublished\":\"2019-03-19T14:45:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/\"},\"wordCount\":396,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Roberto-Abdenur.jpg\",\"keywords\":[\"capa\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/\",\"name\":\"'Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o' - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Roberto-Abdenur.jpg\",\"datePublished\":\"2019-03-19T14:45:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Roberto-Abdenur.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Roberto-Abdenur.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Foto\\\/Arquivo Notibras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o' - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/","og_locale":"pt_BR","og_type":"article","og_title":"'Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o' - Notibras","og_description":"Os sinais de uma pol\u00edtica externa &#8220;altamente ideol\u00f3gica&#8221; dados pelo governo do presidente Jair Bolsonaro, que se encontrar\u00e1 nesta ter\u00e7a-feira, 19, com seu colega americano, Donald Trump, podem afastar o Brasil de outras na\u00e7\u00f5es e ser &#8220;profundamente negativos&#8221; para os interesses do pa\u00eds. Essa \u00e9 a vis\u00e3o do embaixador aposentado Roberto Abdenur, que comandou a [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-03-19T14:45:02+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"&#8216;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#8217;","datePublished":"2019-03-19T14:45:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/"},"wordCount":396,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg","keywords":["capa"],"articleSection":["Brasil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/","url":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/","name":"'Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o' - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg","datePublished":"2019-03-19T14:45:02+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/Roberto-Abdenur.jpg","width":1280,"height":720,"caption":"Foto\/Arquivo Notibras"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/ser-aliado-de-trump-e-bom-mas-subalterno-nao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"&#8216;Ser aliado de Trump \u00e9 bom, mas subalterno, n\u00e3o&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205072"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205072\/revisions"}],"predecessor-version":[{"id":205074,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205072\/revisions\/205074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205073"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205072"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=205072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}