{"id":205090,"date":"2019-03-19T22:05:24","date_gmt":"2019-03-20T01:05:24","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205090"},"modified":"2019-03-19T22:45:26","modified_gmt":"2019-03-20T01:45:26","slug":"generais-querem-pressao-popular-contra-supremo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/generais-querem-pressao-popular-contra-supremo\/","title":{"rendered":"Generais querem press\u00e3o popular contra Supremo"},"content":{"rendered":"<p>Est\u00e1 pronto o cerco ao Senado que escondeu investiga\u00e7\u00e3o de poss\u00edvel corrup\u00e7\u00e3o no Supremo Tribunal Federal. Quem acha que j\u00e1 viu ou soube de tudo, que durma com mais essa. Depois da afronta \u00e0 maioria dos brasileiros, ao transferir para o TSE os crimes investigados pela Lava Jato, o STF abriu as portas para a derrubada de uma barreira at\u00e9 agora intranspon\u00edvel. Agora o empurr\u00e3o vem do apoio popular aos novos senadores eleitos e aos mais antigos, livres de il\u00edcitos, que j\u00e1 t\u00eam a chave para reconstruir os tribunais superiores e outras anomias graves da era p\u00f3s Lula.<\/p>\n<p>O esc\u00e1rnio hist\u00f3rico a que fomos submetidos ao longo dos anos, ter\u00e1 que enfrentar uma renova\u00e7\u00e3o nunca antes registrada naquele feudo legislativo. De cada 4 senadores que tentaram a reelei\u00e7\u00e3o em 2018, 3 n\u00e3o foram eleitos. Como na matem\u00e1tica, foi subtra\u00edda a maioria, portanto a sobra \u00e9 lixo. A assepsia mexeu nas gavetas mais profundas do Senado, onde repousava solenemente tudo o que o Brasil deseja. Anote o que est\u00e1 pronto:<\/p>\n<p>1. Pedidos de impeachment de ministros do Supremo \u2013 CPI Lava Toga \u2013 com fatos devidamente investigados e n\u00famero regimental de assinaturas obtidos para aprova\u00e7\u00e3o (27) e inic\u00edcio imediato \u00e0s poss\u00edveis revela\u00e7\u00f5es e comprova\u00e7\u00f5es de atos nada republicados de capas pretas;<\/p>\n<p>2. PEC (52\/2015 de autoria do senador Reguffe (DF), sem partido), para alterar a forma de acesso \u00e0s cadeiras dos tribunais superiores, incluindo o Tribunal de Contas da Uni\u00e3o e suas sucursais;<\/p>\n<p>O veterano senador Jos\u00e9 Ant\u00f4nio Reguffe, que j\u00e1 foi deputado distrital e federal, tido como um parlamentar exageradamente low profile, talvez tenha encontrado o ambiente adequado para iniciar a lideran\u00e7a de um processo de reconstru\u00e7\u00e3o da m\u00e1quina judici\u00e1ria. Se fizer apenas isso, j\u00e1 estar\u00e3o justificados todos os seus mandatos. No passado, contra nomes como Juc\u00e1, Collor, A\u00e9cio, Gleisi, Eun\u00edcio, Lindbergh e outros, passou os anos isolado em seu gabinete, s\u00f3 saindo de l\u00e1 para o papel de fonte de emissoras de TV, quando o assunto era verba de gabinete. Fortalecido pela renova\u00e7\u00e3o, Reguffe tomou a tribuna para um discurso que deixa clara a situa\u00e7\u00e3o atual e exp\u00f5e o cen\u00e1rio passado recente, as trocas de favores entre os poderes e outras excresc\u00eancias, como as indica\u00e7\u00f5es para as cadeiras dos tribunais superiores.<\/p>\n<p>A PEC 52\/2015 repara a pior das formas de escolha de ministros para o judici\u00e1rio, que \u00e9 a indica\u00e7\u00e3o pelo presidente da Rep\u00fablica \u2013 STF e TCU \u2013 e pelos governadores para os tribunais de contas estaduais. Ou seja, o \u00f3rg\u00e3o fiscalizador \u00e9 controlado pelos fiscalizados. \u00c9 claro que os contemplados vital\u00edcios dizem que n\u00e3o. Esse m\u00e9todo \u00e9 o respons\u00e1vel pelas decis\u00f5es esdr\u00faxulas que presenciamos a todo o momento, segundo o pr\u00f3prio Reguffe, e de acordo com a intelig\u00eancia b\u00e1sica da maioria dos eleitores, exclu\u00edda do processo.<\/p>\n<p>Dias Toffoli \u00e9 um exemplo cl\u00e1ssico e original. Segundo os internautas, o presidente do STF n\u00e3o foi capaz de passar em dois concursos para juiz, n\u00e3o exibe p\u00f3s-gradua\u00e7\u00e3o, mestrado ou doutorado nem obras publicadas, tradicionais requisitos para ocupar a cadeira m\u00e1xima do Judici\u00e1rio. Ainda assim, desprovido de conte\u00fado profundo, foi conduzido ao trono de rei do Judici\u00e1rio por ser amigo \u00edntimo de outro rei, o apenado Lula da Sila, que hoje ocupa um trono menos confort\u00e1vel onde deixa suas mem\u00f3rias. Toffoli deu provas de que, pelo menos, tem a qualidade da gratid\u00e3o ao exercer o voto de Minerva que destruiu a Lava Jato, o sonho do torneiro mec\u00e2nico.<\/p>\n<p>Est\u00e1 claro que o STF n\u00e3o cumpre o restrito papel de tribunal constitucional, mas est\u00e1 travestido de corte penal. Um absurdo. \u00c9 necess\u00e1rio concurso p\u00fablico \u2013 com salvaguardas \u2013 e an\u00e1lise meritocr\u00e1tica para esses cargos, imprescind\u00edveis \u00e0 democracia. E per\u00edodo determinado de 5 anos no cargo. A met\u00e1fora indica que agora os tr\u00eas irm\u00e3os, Athos, Porthos e Aramis, devem com urg\u00eancia sacar suas afiadas espadas \u2013 as redes sociais &#8211; para defender o trono leg\u00edtimo de D\u2019Artagnam, assim que ele retorne dos EUA, e seus s\u00faditos brasileiros pac\u00edficos e incautos.<\/p>\n<p>\u00c9 hora de mudar o foco, cercar o Senado Federal, onde a solu\u00e7\u00e3o legal aguarda o duelo leg\u00edtimo e letal, capaz de exterminar a sujeira que reina na Pra\u00e7a dos Tr\u00eas Poderes. \u00c9 no Senado que est\u00e3o o problema e a solu\u00e7\u00e3o. S\u00f3 assim, depois de enterrar os insumos da podrid\u00e3o, a massa que deseja Justi\u00e7a poder\u00e1 correr feliz e saltitante, para as redes sociais e distribuir as hashtags que mais desejam: #ToffoliPresente, #GilmarPresente, #MoraesPresente, #MarcoAur\u00e9lioPresente, #CelsoPresente, #LewandowskiPresente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 pronto o cerco ao Senado que escondeu investiga\u00e7\u00e3o de poss\u00edvel corrup\u00e7\u00e3o no Supremo Tribunal Federal. Quem acha que j\u00e1 viu ou soube de tudo, que durma com mais essa. Depois da afronta \u00e0 maioria dos brasileiros, ao transferir para o TSE os crimes investigados pela Lava Jato, o STF abriu as portas para a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-205090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205090"}],"version-history":[{"count":16,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205090\/revisions"}],"predecessor-version":[{"id":205113,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205090\/revisions\/205113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205092"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}