{"id":205120,"date":"2019-03-20T07:49:07","date_gmt":"2019-03-20T10:49:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205120"},"modified":"2019-03-20T07:49:58","modified_gmt":"2019-03-20T10:49:58","slug":"ficha-limpa-apoia-moro-e-declara-guerra-aos-ficha-suja","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ficha-limpa-apoia-moro-e-declara-guerra-aos-ficha-suja\/","title":{"rendered":"Ficha-limpa apoia Moro e declara guerra a ficha-suja"},"content":{"rendered":"<p>Deputados e senadores lan\u00e7aram nesta ter\u00e7a-feira (19) a Frente Parlamentar Mista \u00c9tica contra a Corrup\u00e7\u00e3o. O pacote anticrime e anticorrup\u00e7\u00e3o, apresentado ao Congresso pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro, ser\u00e1 uma das prioridades de atua\u00e7\u00e3o grupo. A frente ser\u00e1 presidida pela deputada Adriana Ventura (Novo-SP) e re\u00fane 215 deputados e seis senadores, de 24 partidos.<\/p>\n<p>De acordo o deputado Prof. Luiz Fl\u00e1vio Gomes (PSB-SP), o grupo tamb\u00e9m atuar\u00e1 na defesa do projeto de lei que restringe o foro privilegiado e a execu\u00e7\u00e3o da pena ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia. O parlamentar disse ainda que estar\u00e1 na pauta da frente a proposta que estabelece a compet\u00eancia da Justi\u00e7a Federal ou estadual em casos que envolvam crimes de caixa 2.<\/p>\n<p>Na semana passada, o Supremo Tribunal Federal (STF) se posicionou a favor da compet\u00eancia da Justi\u00e7a Eleitoral para investigar casos de corrup\u00e7\u00e3o quando envolverem simultaneamente caixa 2 de campanha e outros crimes comuns, como lavagem de dinheiro, que s\u00e3o investigados na Opera\u00e7\u00e3o Lava Jato.<\/p>\n<p>Para o senador Alessandro Vieira (PPS\/RS), autor de pedido para instala\u00e7\u00e3o da Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) no Senado para analisar as cortes superiores, o Judici\u00e1rio \u00e9 o \u00fanico ponto intocado no Brasil. \u201cTemos que mostrar que somos todos iguais. N\u00e3o estamos s\u00f3s. \u00c9 muito claro o desejo da sociedade. A luta pelo combate \u00e0 corrup\u00e7\u00e3o \u00e9 de todos n\u00f3s\u201d, disse.<\/p>\n<p>Para o fundador da Associa\u00e7\u00e3o Contas Abertas, economista Gil Castelo Branco, o grupo parlamentar representa a oportunidade de ter uma frente parlamentar avan\u00e7ada atuando no combate \u00e0 corrup\u00e7\u00e3o por meio de atualiza\u00e7\u00e3o nas leis brasileiras. O economista lembrou que tramita C\u00e2mara dos Deputados 344 propostas de combate \u00e0 corrup\u00e7\u00e3o e 98 no Senado, segundo levantamento da Funda\u00e7\u00e3o Getulio Vargas (FGV), divulgado em 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deputados e senadores lan\u00e7aram nesta ter\u00e7a-feira (19) a Frente Parlamentar Mista \u00c9tica contra a Corrup\u00e7\u00e3o. O pacote anticrime e anticorrup\u00e7\u00e3o, apresentado ao Congresso pelo ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro, ser\u00e1 uma das prioridades de atua\u00e7\u00e3o grupo. A frente ser\u00e1 presidida pela deputada Adriana Ventura (Novo-SP) e re\u00fane 215 deputados e seis senadores, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-205120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205120"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205120\/revisions"}],"predecessor-version":[{"id":205123,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205120\/revisions\/205123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205121"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}