{"id":205243,"date":"2019-03-21T09:47:20","date_gmt":"2019-03-21T12:47:20","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205243"},"modified":"2019-03-21T09:47:20","modified_gmt":"2019-03-21T12:47:20","slug":"cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/","title":{"rendered":"Cresce o abismo entre os alunos ricos e os pobres"},"content":{"rendered":"<p>No Brasil, enquanto 83% dos estudantes mais ricos saem da escola p\u00fablica tendo aprendido o adequado em l\u00edngua portuguesa ao final do ensino m\u00e9dio, entre os estudantes mais pobres, essa porcentagem \u00e9 17%. Em matem\u00e1tica, 63,6% dos alunos mais ricos aprenderam o adequado e apenas 3,1% dos mais pobres saem da escola sabendo o m\u00ednimo considerado suficiente na disciplina. Os dados s\u00e3o do Todos pela Educa\u00e7\u00e3o (TPE), organiza\u00e7\u00e3o social, sem fins lucrativos.<\/p>\n<p>A entidade analisou os microdados do Sistema de Avalia\u00e7\u00e3o da Educa\u00e7\u00e3o B\u00e1sica (Saeb) 2017 e mostrou que h\u00e1 diferen\u00e7a grande e constante, desde 2011, entre o desempenho dos mais ricos e dos mais pobres em todos os n\u00edveis analisados, no 5\u00ba e no 9\u00ba ano do ensino fundamental e no 3\u00ba ano do ensino m\u00e9dio. A disparidade entre as porcentagens de estudantes que aprendem o adequado chega a ser quase cinco vezes maior entre aqueles com maior n\u00edvel socioecon\u00f4mico e os com menor n\u00edvel.<\/p>\n<p>&#8220;A educa\u00e7\u00e3o, que poderia ser uma das principais ferramentas para diminuir a desigualdade de aprendizagem n\u00e3o tem conseguido fazer isso de maneira consistente no Brasil&#8221;, diz o diretor de Pol\u00edticas Educacionais do TPE, Olavo Nogueira Filho. &#8220;A gente est\u00e1 avan\u00e7ando na m\u00e9dia brasileira, mas est\u00e1 mantendo um alto grau de desigualdade entre alunos de n\u00edvel socioecon\u00f4mico mais alto e mais baixo. Estamos melhorando sem conseguir diminuir esse resultado entre mais ricos e mais pobres&#8221;, avalia.<\/p>\n<p>O Saeb avalia estudantes quanto aos conhecimentos de l\u00edngua portuguesa e matem\u00e1tica e \u00e9 aplicado de dois em dois anos. A avalia\u00e7\u00e3o \u00e9 de responsabilidade do Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep), que classifica os estudantes em seis grupos, considerando o n\u00edvel socioecon\u00f4mico.<\/p>\n<p>O grupo 1 re\u00fane os estudantes com o menor poder aquisitivo. S\u00e3o, em maior parte, estudantes com renda familiar mensal de at\u00e9 um sal\u00e1rio m\u00ednimo e que t\u00eam, em casa, bens elementares, como uma geladeira e uma televis\u00e3o, sem m\u00e1quina de lavar roupa ou computador. Os pais ou respons\u00e1veis t\u00eam forma\u00e7\u00e3o at\u00e9 o 5\u00ba ano do ensino fundamental ou inferior.<\/p>\n<p>Na outra ponta, est\u00e1 o grupo 6, com estudantes com renda familiar mensal de sete sal\u00e1rios m\u00ednimos ou mais, cujos pais ou respons\u00e1veis completaram a faculdade e que tem em casa tr\u00eas ou mais televisores, dois ou mais computadores, entre outros bens.<\/p>\n<p>A diferen\u00e7a \u00e9 constatada desde o 5\u00ba ano do ensino fundamental, quando 90,4% dos mais ricos aprendem o adequado em l\u00edngua portuguesa e 83,9%, em matem\u00e1tica e apenas 26,3% dos mais pobres aprendem o adequado em portugu\u00eas e 18,1%, em matem\u00e1tica.<\/p>\n<p>De acordo com Nogueira Filho, a escola p\u00fablica n\u00e3o est\u00e1 cumprindo um de seus principais potenciais: reduzir desigualdades. &#8220;Para fazer isso, \u00e9 preciso ter uma pol\u00edtica educacional que se preocupe com essa quest\u00e3o. Uma pol\u00edtica educacional que se traduza em mais recursos para quem tem maior desafio&#8221;, defende.<\/p>\n<p>De acordo com o diretor, ocorre o contr\u00e1rio no pa\u00eds. \u201cOs munic\u00edpios mais vulner\u00e1veis, em geral, s\u00e3o os que t\u00eam menor investimento por aluno quando comparados com regi\u00f5es de n\u00edvel socioecon\u00f4mico mais elevado&#8221;.<\/p>\n<p>De acordo com o levantamento do TPE, em m\u00e9dia, considerando juntos todos os n\u00edveis socioecon\u00f4micos, houve melhora na aprendizagem no pa\u00eds, no ensino fundamental. No ensino m\u00e9dio, h\u00e1 praticamente estagna\u00e7\u00e3o desde 2001.<\/p>\n<p>O maior salto foi no 5\u00ba ano do ensino fundamental. Em 2001, 23,7% dos estudantes aprendiam o adequado em l\u00edngua portuguesa e 14,9%, em matem\u00e1tica. Essas porcentagens chegaram a 60,7% e a 48,9%, respectivamente, em 2017.<\/p>\n<p>No final do ensino m\u00e9dio, em 2001, 25,8% dos jovens deixavam a escola sabendo o m\u00ednimo adequado em portugu\u00eas e 11,6%, em matem\u00e1tica. Em 2017, essas porcentagens passaram para 29,1% em l\u00edngua portuguesa e reduziram para 9,1% em matem\u00e1tica.<\/p>\n<p>O TPE considera como aprendizagem adequada estudantes que obtiveram pelo menos, em l\u00edngua portuguesa, 200 pontos no 5\u00ba ano do ensino fundamental, 275 no 9\u00ba ano e 300 no final do ensino m\u00e9dio. Em matem\u00e1tica, \u00e9 necess\u00e1rio tirar pelo menos 225 pontos no 5\u00ba ano, 300 pontos no 9\u00ba ano e 350 pontos no 3\u00ba ano do ensino m\u00e9dio.<\/p>\n<p>As pontua\u00e7\u00f5es foram definidas por um conjunto de especialistas que buscou como refer\u00eancia, inclusive, o desempenho de estudantes de n\u00edvel semelhante em outros pa\u00edses.<\/p>\n<p>Seguindo os n\u00edveis propostos pelo Inep, essas pontua\u00e7\u00f5es significam que os estudantes devem estar pelo menos no n\u00edvel 5 de 10 n\u00edveis em matem\u00e1tica e no n\u00edvel 4 de 9 n\u00edveis em l\u00edngua portuguesa, no 5\u00ba ano; no n\u00edvel 4 de 8 n\u00edveis em portugu\u00eas e 5 de 9 n\u00edveis em matem\u00e1tica, no 9\u00ba ano; e no 6 de 10 em matem\u00e1tica e n\u00edvel 4 de 8 n\u00edveis em l\u00edngua portuguesa, no 3\u00ba ano do ensino m\u00e9dio.<\/p>\n<p>No ano passado, o Minist\u00e9rio da Educa\u00e7\u00e3o divulgou, pela primeira vez, o n\u00edvel que considera adequado para cada etapa. Os n\u00edveis considerados s\u00e3o mais r\u00edgidos do que os definidos pelo Todos pela Educa\u00e7\u00e3o, considerando adequado apenas o n\u00edvel 7 em ambas disciplinas. A m\u00e9trica foi questionada por especialistas.<\/p>\n<p>Pelo crit\u00e9rio do MEC, apenas 1,62% dos estudantes obtiveram o m\u00ednimo adequado em l\u00edngua portuguesa ao final do ensino m\u00e9dio e 4,52%, o m\u00ednimo em matem\u00e1tica, em 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No Brasil, enquanto 83% dos estudantes mais ricos saem da escola p\u00fablica tendo aprendido o adequado em l\u00edngua portuguesa ao final do ensino m\u00e9dio, entre os estudantes mais pobres, essa porcentagem \u00e9 17%. Em matem\u00e1tica, 63,6% dos alunos mais ricos aprenderam o adequado e apenas 3,1% dos mais pobres saem da escola sabendo o m\u00ednimo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"tmauthors":[],"class_list":["post-205243","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","tag-capa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cresce o abismo entre os alunos ricos e os pobres - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cresce o abismo entre os alunos ricos e os pobres - Notibras\" \/>\n<meta property=\"og:description\" content=\"No Brasil, enquanto 83% dos estudantes mais ricos saem da escola p\u00fablica tendo aprendido o adequado em l\u00edngua portuguesa ao final do ensino m\u00e9dio, entre os estudantes mais pobres, essa porcentagem \u00e9 17%. Em matem\u00e1tica, 63,6% dos alunos mais ricos aprenderam o adequado e apenas 3,1% dos mais pobres saem da escola sabendo o m\u00ednimo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-21T12:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Cresce o abismo entre os alunos ricos e os pobres\",\"datePublished\":\"2019-03-21T12:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/\"},\"wordCount\":907,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/ensino_medio.jpg\",\"keywords\":[\"capa\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/\",\"name\":\"Cresce o abismo entre os alunos ricos e os pobres - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/ensino_medio.jpg\",\"datePublished\":\"2019-03-21T12:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/ensino_medio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/ensino_medio.jpg\",\"width\":1140,\"height\":760,\"caption\":\"Foto\\\/Arquivo Notibras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cresce o abismo entre os alunos ricos e os pobres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cresce o abismo entre os alunos ricos e os pobres - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/","og_locale":"pt_BR","og_type":"article","og_title":"Cresce o abismo entre os alunos ricos e os pobres - Notibras","og_description":"No Brasil, enquanto 83% dos estudantes mais ricos saem da escola p\u00fablica tendo aprendido o adequado em l\u00edngua portuguesa ao final do ensino m\u00e9dio, entre os estudantes mais pobres, essa porcentagem \u00e9 17%. Em matem\u00e1tica, 63,6% dos alunos mais ricos aprenderam o adequado e apenas 3,1% dos mais pobres saem da escola sabendo o m\u00ednimo [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-03-21T12:47:20+00:00","og_image":[{"width":1140,"height":760,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Cresce o abismo entre os alunos ricos e os pobres","datePublished":"2019-03-21T12:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/"},"wordCount":907,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg","keywords":["capa"],"articleSection":["Brasil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/","url":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/","name":"Cresce o abismo entre os alunos ricos e os pobres - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg","datePublished":"2019-03-21T12:47:20+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/ensino_medio.jpg","width":1140,"height":760,"caption":"Foto\/Arquivo Notibras"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/cresce-o-abismo-entre-os-alunos-ricos-e-os-pobres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Cresce o abismo entre os alunos ricos e os pobres"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205243"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205243\/revisions"}],"predecessor-version":[{"id":205245,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205243\/revisions\/205245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205244"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205243"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=205243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}