{"id":205281,"date":"2019-03-22T00:05:11","date_gmt":"2019-03-22T03:05:11","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205281"},"modified":"2019-03-22T07:07:45","modified_gmt":"2019-03-22T10:07:45","slug":"joao-de-deus-troca-cadeia-por-clinica-de-repouso","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/joao-de-deus-troca-cadeia-por-clinica-de-repouso\/","title":{"rendered":"Jo\u00e3o de Deus troca cadeia por cl\u00ednica de repouso"},"content":{"rendered":"<p>O ministro do Superior Tribunal de Justi\u00e7a (STJ) Nefi Cordeiro autorizou nesta quinta, 21, que o m\u00e9dium Jo\u00e3o de Deus deixe a pris\u00e3o e seja encaminhado para interna\u00e7\u00e3o no Instituto de Neurologia de Goi\u00e2nia. De acordo com a decis\u00e3o, o m\u00e9dium dever\u00e1 ficar internado durante o per\u00edodo de quatro semanas, sob escolta policial, ou monitoramento por tornozeleira eletr\u00f4nica.<\/p>\n<p>Jo\u00e3o de Deus foi preso no 16 de dezembro do ano passado sob a acusa\u00e7\u00e3o de viola\u00e7\u00e3o sexual mediante fraude e de estupro de vulner\u00e1vel, crimes que teriam sido praticados contra centenas de mulheres na institui\u00e7\u00e3o em que atendia pessoas em busca de tratamento espiritual, em Abadi\u00e2nia, Goi\u00e1s.<\/p>\n<p>O ministro atendeu a um pedido da defesa de Jo\u00e3o de Deus, que tem problemas de press\u00e3o arterial e um &#8220;aneurisma da aorta abdominal com dissec\u00e7\u00e3o e alto risco de ruptura&#8221;, segundo os advogados.<\/p>\n<p>Na decis\u00e3o, Nefi Cordeiro entendeu que todo preso tem direito \u00e0 dignidade e \u00e0 sa\u00fade. &#8220;Dever\u00e1 o paciente, como decorr\u00eancia, ser tratado pelo tempo m\u00ednimo indicado como necess\u00e1rio, em princ\u00edpio de quatro semanas, salvo adiantada melhoria em seu estado de sa\u00fade que lhe permita o retorno ao normal tratamento na unidade prisional.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Superior Tribunal de Justi\u00e7a (STJ) Nefi Cordeiro autorizou nesta quinta, 21, que o m\u00e9dium Jo\u00e3o de Deus deixe a pris\u00e3o e seja encaminhado para interna\u00e7\u00e3o no Instituto de Neurologia de Goi\u00e2nia. De acordo com a decis\u00e3o, o m\u00e9dium dever\u00e1 ficar internado durante o per\u00edodo de quatro semanas, sob escolta policial, ou monitoramento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":197007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-205281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205281"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205281\/revisions"}],"predecessor-version":[{"id":205282,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205281\/revisions\/205282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/197007"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}