{"id":205396,"date":"2019-03-24T08:44:37","date_gmt":"2019-03-24T11:44:37","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205396"},"modified":"2019-03-24T09:51:50","modified_gmt":"2019-03-24T12:51:50","slug":"maduro-acusa-trump-de-pagar-mercenarios-para-mata-lo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/maduro-acusa-trump-de-pagar-mercenarios-para-mata-lo\/","title":{"rendered":"Maduro acusa Trump de pagar mercen\u00e1rios para mat\u00e1-lo"},"content":{"rendered":"<p>O presidente venezuelano, Nicolas Maduro, acusou os Estados Unidos e o l\u00edder da oposi\u00e7\u00e3o Juan Guaido de estarem diretamente envolvidos em um plano para mat\u00e1-lo. &#8220;O imperialismo norte-americano quer me matar. Acabamos de expor o plano que o fantoche do diabo [Guaid\u00f3] dirigiu pessoalmente para me matar&#8221; , disse Maduro , falando aos partid\u00e1rios em uma manifesta\u00e7\u00e3o neste domingo, 24.<\/p>\n<p>&#8220;Temos provas; eles n\u00e3o poderiam e n\u00e3o podem [ter sucesso] porque somos protegidos por Deus&#8221;, acrescentou Maduro. O l\u00edder da Venezuela\u00a0ressaltou que o Minist\u00e9rio P\u00fablico fez s\u00e9rios progressos no caso, com &#8220;novos terroristas&#8221; previstos para serem presos &#8220;nos pr\u00f3ximos dias&#8221;.<\/p>\n<p>Na semana passada, a seguran\u00e7a venezuelana prendeu o chefe de gabinete de Guaid\u00f3, Robert Marrero, acusando-o de organizar uma c\u00e9lula terrorista e conspirar para assassinar altos funcion\u00e1rios venezuelanos e realizar atos de terrorismo e sabotagem usando dinheiro de contas banc\u00e1rias venezuelanas congeladas no exterior.<\/p>\n<p>Falando na televis\u00e3o venezuelana no s\u00e1bado, o ministro da Comunica\u00e7\u00e3o Jorge Rodriguez alegou que a oposi\u00e7\u00e3o havia recrutado os assassinos e paramilitares para envi\u00e1-los \u00e0 Col\u00f4mbia para treinamento. &#8220;Marrero estava envolvido na contrata\u00e7\u00e3o de pessoas da Guatemala e da Col\u00f4mbia para cumprir o plano de recrutamento e treinamento para assassinos&#8221;, disse ele.<\/p>\n<p>Rodriguez forneceu informa\u00e7\u00f5es detalhadas sobre a trama, que, segundo ele, incluiu a cria\u00e7\u00e3o de mais de meia d\u00fazia de equipes de oito mercen\u00e1rios para perseguir os l\u00edderes pol\u00edticos e militares da Venezuela, al\u00e9m de realizar conspira\u00e7\u00f5es terroristas contra o Estado. As evid\u00eancias inclu\u00edam grava\u00e7\u00f5es do que se dizia serem conversas do WhatsApp entre Marrero e Guaido sobre o uso de fundos venezuelanos congelados por san\u00e7\u00f5es dos EUA para financiar grupos armados com o apoio da Col\u00f4mbia.<\/p>\n<p>As autoridades venezuelanas j\u00e1 identificaram alguns dos mais de 30 paramilitares que se infiltraram na Venezuela a partir de El Salvador, Honduras e Guatemala depois de serem treinados na Col\u00f4mbia, segundo Rodriguez.<\/p>\n<p>J\u00e1 Maduro, em seu discurso, tamb\u00e9m indicou que um chefe paramilitar colombiano n\u00e3o identificado tamb\u00e9m havia sido capturado e agora estava &#8220;dando testemunho&#8221;.<\/p>\n<p>A longa crise pol\u00edtica da Venezuela se intensificou no final de janeiro, quando Juan Guaid\u00f3, chefe da semi-extinta Assembl\u00e9ia Nacional, declarou-se presidente interino na pend\u00eancia de novas elei\u00e7\u00f5es, poucos dias depois da posse de Maduro para um segundo mandato.<\/p>\n<p>A trama recebeu apoio imediato dos EUA e de seus aliados latino-americanos, al\u00e9m da Europa. R\u00fassia, China, Cuba, Bol\u00edvia, Turquia, S\u00edria, Cor\u00e9ia do Norte e v\u00e1rios outros pa\u00edses condenaram a tentativa de golpe e conclamaram os poderes externos a n\u00e3o interferirem nos assuntos internos da Venezuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente venezuelano, Nicolas Maduro, acusou os Estados Unidos e o l\u00edder da oposi\u00e7\u00e3o Juan Guaido de estarem diretamente envolvidos em um plano para mat\u00e1-lo. &#8220;O imperialismo norte-americano quer me matar. Acabamos de expor o plano que o fantoche do diabo [Guaid\u00f3] dirigiu pessoalmente para me matar&#8221; , disse Maduro , falando aos partid\u00e1rios em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-205396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205396"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205396\/revisions"}],"predecessor-version":[{"id":205398,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205396\/revisions\/205398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205399"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}