{"id":205472,"date":"2019-03-25T07:13:41","date_gmt":"2019-03-25T10:13:41","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205472"},"modified":"2019-03-25T07:13:41","modified_gmt":"2019-03-25T10:13:41","slug":"motos-ganham-mais-tecnologia-e-conectividade","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/","title":{"rendered":"Motos ganham mais tecnologia e conectividade"},"content":{"rendered":"<p>As motos ganharam nos \u00faltimos anos tecnologias antes presentes s\u00f3 em carros, como assistente de partida em rampa. Agora, chegou a hora de os modelos de duas rodas come\u00e7arem a trazer a enxurrada de itens de conectividade que t\u00eam sido incorporados aos autom\u00f3veis.<\/p>\n<p>A integra\u00e7\u00e3o de motos aos smartphones, por exemplo, permite ao motociclista atender chamadas ou mudar m\u00fasicas. H\u00e1 ainda uso de c\u00e2meras, acesso a dados de consumo e at\u00e9 altera\u00e7\u00e3o de mapas de pot\u00eancia via Bluetooth. Essas fun\u00e7\u00f5es interativas j\u00e1 est\u00e3o presentes em alguns modelos de duas rodas vendidos no Brasil. Em outros, chegam em breve.<\/p>\n<p>Uma das maiores inova\u00e7\u00f5es de conectividade foi apresentada pela Triumph. A fabricante inglesa, em parceria com as empresas GoPro e Google, conseguiu implementar um sistema de integra\u00e7\u00e3o das c\u00e2meras da primeira e do sistema de mapas da segunda aos pain\u00e9is virtuais de suas motos.<\/p>\n<p>Com isso, ser\u00e1 poss\u00edvel comandar as c\u00e2meras GoPro (a partir da vers\u00e3o 5) pelos punhos de comando e pelo painel de motos com a Scrambler 1200, que chega no segundo semestre ao Pa\u00eds. O sistema tamb\u00e9m estar\u00e1 dispon\u00edvel nas Tiger 800 e 1200, na Speed Triple e na Street Triple.<\/p>\n<p>Pelo aplicativo MyTriumph, ser\u00e1 poss\u00edvel definir uma rota, que ser\u00e1 mostrada no painel da moto com indica\u00e7\u00f5es por meio de setas. A parceria com a Google vai facilitar o acesso do sistema aos pontos de interesse (restaurantes, lojas, postos de combust\u00edvel).<\/p>\n<p>As Yamaha 250F, 450F e 450FX oferecem um aplicativo que permite mudar, al\u00e9m dos modos de condu\u00e7\u00e3o, par\u00e2metros que s\u00f3 poderiam ser alterados por meio de um controle da central eletr\u00f4nica. Entre eles est\u00e3o mapa de igni\u00e7\u00e3o e abertura do acelerador. Batizado de Power Tuner, ele exige conex\u00e3o do smartphone com a motocicleta via Wi-Fi.<\/p>\n<p>Na KTM, o aplicativo MyRide, dispon\u00edvel para a 390 Duke no Brasil, permite atender a chamadas e controlar sistema de m\u00fasica caso o capacete esteja equipado com um intercomunicador. Bem semelhante \u00e9 o ConnectedApp, da BMW, para as GS 850 e 1200.<\/p>\n<p>As duas motos t\u00eam painel de TFT. A mais que o da KTM, o sistema tem a op\u00e7\u00e3o de indicar a dire\u00e7\u00e3o, por meio de GPS.<\/p>\n<p>Para a linha Multistrada, a Ducati tem o LinkApp. Al\u00e9m das fun\u00e7\u00f5es que KTM e BMW oferecem, grava \u00e2ngulos de inclina\u00e7\u00e3o, velocidade e as \u00faltimas rotas. Tamb\u00e9m permite compartilhar esses dados com a adi\u00e7\u00e3o de fotos dos locais.<\/p>\n<p>O aplicativo permite ainda alterar ajustes dos modos de condu\u00e7\u00e3o (ABS, controle de tra\u00e7\u00e3o e suspens\u00e3o) pelo smartphone, mais f\u00e1cil de usar que o sistema nativo da motocicleta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As motos ganharam nos \u00faltimos anos tecnologias antes presentes s\u00f3 em carros, como assistente de partida em rampa. Agora, chegou a hora de os modelos de duas rodas come\u00e7arem a trazer a enxurrada de itens de conectividade que t\u00eam sido incorporados aos autom\u00f3veis. A integra\u00e7\u00e3o de motos aos smartphones, por exemplo, permite ao motociclista atender [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[72],"tags":[],"tmauthors":[],"class_list":["post-205472","post","type-post","status-publish","format-standard","has-post-thumbnail","category-veiculos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motos ganham mais tecnologia e conectividade - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motos ganham mais tecnologia e conectividade - Notibras\" \/>\n<meta property=\"og:description\" content=\"As motos ganharam nos \u00faltimos anos tecnologias antes presentes s\u00f3 em carros, como assistente de partida em rampa. Agora, chegou a hora de os modelos de duas rodas come\u00e7arem a trazer a enxurrada de itens de conectividade que t\u00eam sido incorporados aos autom\u00f3veis. A integra\u00e7\u00e3o de motos aos smartphones, por exemplo, permite ao motociclista atender [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-25T10:13:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Motos ganham mais tecnologia e conectividade\",\"datePublished\":\"2019-03-25T10:13:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/moto25.jpg\",\"articleSection\":[\"Ve\u00edculos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/\",\"name\":\"Motos ganham mais tecnologia e conectividade - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/moto25.jpg\",\"datePublished\":\"2019-03-25T10:13:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/moto25.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/moto25.jpg\",\"width\":1160,\"height\":773,\"caption\":\"Foto\\\/Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/motos-ganham-mais-tecnologia-e-conectividade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motos ganham mais tecnologia e conectividade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motos ganham mais tecnologia e conectividade - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/","og_locale":"pt_BR","og_type":"article","og_title":"Motos ganham mais tecnologia e conectividade - Notibras","og_description":"As motos ganharam nos \u00faltimos anos tecnologias antes presentes s\u00f3 em carros, como assistente de partida em rampa. Agora, chegou a hora de os modelos de duas rodas come\u00e7arem a trazer a enxurrada de itens de conectividade que t\u00eam sido incorporados aos autom\u00f3veis. A integra\u00e7\u00e3o de motos aos smartphones, por exemplo, permite ao motociclista atender [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-03-25T10:13:41+00:00","og_image":[{"width":1160,"height":773,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Motos ganham mais tecnologia e conectividade","datePublished":"2019-03-25T10:13:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/"},"wordCount":464,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg","articleSection":["Ve\u00edculos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/","url":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/","name":"Motos ganham mais tecnologia e conectividade - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg","datePublished":"2019-03-25T10:13:41+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/moto25.jpg","width":1160,"height":773,"caption":"Foto\/Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/motos-ganham-mais-tecnologia-e-conectividade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Motos ganham mais tecnologia e conectividade"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205472"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205472\/revisions"}],"predecessor-version":[{"id":205474,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205472\/revisions\/205474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205473"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205472"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=205472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}