{"id":205538,"date":"2019-03-26T07:01:59","date_gmt":"2019-03-26T10:01:59","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205538"},"modified":"2019-03-26T07:01:59","modified_gmt":"2019-03-26T10:01:59","slug":"sapos-venenosos-invadem-ruas-da-florida","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/","title":{"rendered":"Sapos venenosos invadem ruas da Fl\u00f3rida"},"content":{"rendered":"<p>Os sapos de cor marrom-avermelhada, que variam de seis a nove polegadas de comprimento e s\u00e3o nativos das Am\u00e9ricas Central e do Sul, podem ser altamente venenosos. Eles foram introduzidos pela primeira vez na Fl\u00f3rida em 1955 para serem usados \u200b\u200bno controle de pragas em planta\u00e7\u00f5es de cana-de-a\u00e7\u00facar.<\/p>\n<p>De acordo com o site da Universidade da Fl\u00f3rida , quando a &#8220;esp\u00e9cie \u00e9 amea\u00e7ada ou manipulada, ela secreta uma subst\u00e2ncia leitosa altamente t\u00f3xica de suas grandes gl\u00e2ndulas parat\u00f3ides localizadas na parte de tr\u00e1s de sua cabe\u00e7a. Essa secre\u00e7\u00e3o pode queimar olhos, pode irritar a pele e pode matar gatos e c\u00e3es&#8221;.<\/p>\n<p>&#8220;Se voc\u00ea suspeitar de envenenamento por sapo, pegue uma mangueira e coloque \u00e1gua na lateral da boca do gato ou c\u00e3o, apontando a cabe\u00e7a do animal para baixo para que a \u00e1gua n\u00e3o seja engolida. Esfregue as gengivas e boca para remover a toxina. Este tratamento \u00e9 geralmente bem sucedido , mas chame seu veterin\u00e1rio imediatamente&#8221;, adverte a University of Florida Wildlife Extension.<\/p>\n<p>Os sapos t\u00eam entupido os filtros da piscina e pululam cal\u00e7adas, cal\u00e7adas e gramados no sub\u00farbio da Fl\u00f3rida, segundo relatos da m\u00eddia local.<\/p>\n<p>&#8220;Eu s\u00f3 vejo uma enorme quantidade de sapos ou sapos em todos os lugares, cobrindo cada cent\u00edmetro quadrado&#8221;, disse Jennie Quasha, que mora no bairro de Mirabella, \u00e0 WPTV na semana passada. &#8220;Voc\u00ea n\u00e3o pode nem andar pela grama sem pisar em um.&#8221;<\/p>\n<p>&#8220;Eu estou preocupada com os animais das pessoas, ent\u00e3o definitivamente n\u00e3o h\u00e1 nata\u00e7\u00e3o na piscina ou brincar do lado de fora e aproveitar o ar livre&#8221;, acrescentou Quasha.<\/p>\n<p>De acordo com o Toad Busters, um servi\u00e7o de remo\u00e7\u00e3o de sapos no sul da Fl\u00f3rida, os sapos est\u00e3o em pleno ciclo de reprodu\u00e7\u00e3o gra\u00e7as a um inverno mais quente e chuvas torrenciais h\u00e1 algumas semanas.<\/p>\n<p>&#8220;Com o inverno mais quente e depois tivemos uma chuva de duas a tr\u00eas semanas atr\u00e1s, uma chuva torrencial &#8211; que fez com que eles entrassem em um ciclo de reprodu\u00e7\u00e3o&#8221;, disse Mark Holladay, t\u00e9cnico da Toad Buster, \u00e0 WPTV.<\/p>\n<p>&#8220;Eles n\u00e3o s\u00e3o seguros para animais de estima\u00e7\u00e3o ou crian\u00e7as. Se um animal de estima\u00e7\u00e3o fosse ingerir muitos deles, mesmo nesse tamanho pequeno, isso causaria um problema&#8221;.<\/p>\n<p>&#8220;Agora, \u00e9 a esta\u00e7\u00e3o para eles&#8221;, Amy Kight, diretora executiva do Busch Wildlife Sanctuary, em Jupiter, Fl\u00f3rida, acrescentou em uma entrevista ao The Palm Beach Post.<\/p>\n<p>&#8220;Na primavera e no ver\u00e3o, temos mais chuva, por isso \u00e9 mais prop\u00edcio para a cria\u00e7\u00e3o deles. Porque permanece mais leve, as pessoas ficam do lado de fora. Quando o crep\u00fasculo est\u00e1 chegando, os sapos come\u00e7am a emergir \u00e0 noite. As pessoas ainda est\u00e3o fora e fazendo coisas com seus animais de estima\u00e7\u00e3o, ent\u00e3o h\u00e1 mais encontros com elas&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os sapos de cor marrom-avermelhada, que variam de seis a nove polegadas de comprimento e s\u00e3o nativos das Am\u00e9ricas Central e do Sul, podem ser altamente venenosos. Eles foram introduzidos pela primeira vez na Fl\u00f3rida em 1955 para serem usados \u200b\u200bno controle de pragas em planta\u00e7\u00f5es de cana-de-a\u00e7\u00facar. De acordo com o site da Universidade [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"tmauthors":[],"class_list":["post-205538","post","type-post","status-publish","format-standard","has-post-thumbnail","category-curiosidades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras\" \/>\n<meta property=\"og:description\" content=\"Os sapos de cor marrom-avermelhada, que variam de seis a nove polegadas de comprimento e s\u00e3o nativos das Am\u00e9ricas Central e do Sul, podem ser altamente venenosos. Eles foram introduzidos pela primeira vez na Fl\u00f3rida em 1955 para serem usados \u200b\u200bno controle de pragas em planta\u00e7\u00f5es de cana-de-a\u00e7\u00facar. De acordo com o site da Universidade [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-26T10:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Sapos venenosos invadem ruas da Fl\u00f3rida\",\"datePublished\":\"2019-03-26T10:01:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sapo.jpg\",\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/\",\"name\":\"Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sapo.jpg\",\"datePublished\":\"2019-03-26T10:01:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sapo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sapo.jpg\",\"width\":1000,\"height\":541,\"caption\":\"Foto\\\/Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/sapos-venenosos-invadem-ruas-da-florida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sapos venenosos invadem ruas da Fl\u00f3rida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/","og_locale":"pt_BR","og_type":"article","og_title":"Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras","og_description":"Os sapos de cor marrom-avermelhada, que variam de seis a nove polegadas de comprimento e s\u00e3o nativos das Am\u00e9ricas Central e do Sul, podem ser altamente venenosos. Eles foram introduzidos pela primeira vez na Fl\u00f3rida em 1955 para serem usados \u200b\u200bno controle de pragas em planta\u00e7\u00f5es de cana-de-a\u00e7\u00facar. De acordo com o site da Universidade [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-03-26T10:01:59+00:00","og_image":[{"width":1000,"height":541,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Sapos venenosos invadem ruas da Fl\u00f3rida","datePublished":"2019-03-26T10:01:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/"},"wordCount":498,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg","articleSection":["Curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/","url":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/","name":"Sapos venenosos invadem ruas da Fl\u00f3rida - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg","datePublished":"2019-03-26T10:01:59+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/03\/sapo.jpg","width":1000,"height":541,"caption":"Foto\/Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/sapos-venenosos-invadem-ruas-da-florida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Sapos venenosos invadem ruas da Fl\u00f3rida"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205538"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205538\/revisions"}],"predecessor-version":[{"id":205540,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205538\/revisions\/205540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205539"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205538"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=205538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}