{"id":205648,"date":"2019-03-27T06:00:55","date_gmt":"2019-03-27T09:00:55","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205648"},"modified":"2019-03-27T08:48:04","modified_gmt":"2019-03-27T11:48:04","slug":"senado-arquiva-novo-pedido-para-cpi-da-lava-toga","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/senado-arquiva-novo-pedido-para-cpi-da-lava-toga\/","title":{"rendered":"Senado arquiva novo pedido para CPI da Lava Toga"},"content":{"rendered":"<p>O presidente do Senado, Davi Alcolumbre (DEM-AP), mandou arquivar o pedido de CPI da Lava Toga. A decis\u00e3o foi anunciada na noite desta ter\u00e7a-feira, 16, ao fim da sess\u00e3o plen\u00e1ria.<\/p>\n<p>Ao tomar a decis\u00e3o, Alcolumbre disse ter consultado a advocacia do Senado para avaliar uma nota t\u00e9cnica da consultoria legislativa que rejeitou os 13 pontos do pedido.<\/p>\n<p>A medida, por\u00e9m, n\u00e3o significa que a comiss\u00e3o, que investigaria supostas vantagens il\u00edcitas no Poder Judici\u00e1rio, esteja morta de vez.<\/p>\n<p>O assunto agora vai seguir para a CCJ do Senado, que far\u00e1 um parecer sobre o arquivamento. Mesmo que a decis\u00e3o seja pelo arquivamento, haver\u00e1 um novo sopro para ressuscitar a CPI.<\/p>\n<p>\u00c9 que a decis\u00e3o final caber\u00e1 ao plen\u00e1rio, que poder\u00e1 derrubar ou n\u00e3o a determina\u00e7\u00e3o de Alcolumbre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Senado, Davi Alcolumbre (DEM-AP), mandou arquivar o pedido de CPI da Lava Toga. A decis\u00e3o foi anunciada na noite desta ter\u00e7a-feira, 16, ao fim da sess\u00e3o plen\u00e1ria. Ao tomar a decis\u00e3o, Alcolumbre disse ter consultado a advocacia do Senado para avaliar uma nota t\u00e9cnica da consultoria legislativa que rejeitou os 13 pontos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-205648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205648"}],"version-history":[{"count":7,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205648\/revisions"}],"predecessor-version":[{"id":205655,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205648\/revisions\/205655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/126402"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}