{"id":205860,"date":"2019-03-29T13:52:20","date_gmt":"2019-03-29T16:52:20","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205860"},"modified":"2019-03-29T13:52:20","modified_gmt":"2019-03-29T16:52:20","slug":"mala-e-pouco-e-lava-jato-pega-temer-de-novo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/mala-e-pouco-e-lava-jato-pega-temer-de-novo\/","title":{"rendered":"Mala \u00e9 pouco. E Lava Jato pega Temer de novo"},"content":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal, no Rio, denunciou criminalmente o ex-presidente Michel Temer e o ex-ministro Moreira Franco, de Minas e Energia, por supostos desvios nas obras da usina nuclear de Angra 3.<\/p>\n<p>Os dois s\u00e3o alvo da Opera\u00e7\u00e3o Descontamina\u00e7\u00e3o \u2013 desdobramento, no Rio de Janeiro, da Lava Jato. Contra Temer, especificamente, foram apresentadas acusa\u00e7\u00f5es de corrup\u00e7\u00e3o, lavagem de dinheiro e peculato.<\/p>\n<p>As den\u00fancias ser\u00e3o analisadas pelo juiz Marcelo Bretas, da 7\u00aa Vara Federal do Rio. \u00c9 o mesmo magistrado que mandou prender Michel Temer, Moreira Franco e outros oito alvos da Descontamina\u00e7\u00e3o na semana passada. Se Bretas aceitar as acusa\u00e7\u00f5es, o ex-presidente responder\u00e1 a a\u00e7\u00f5es perante a Justi\u00e7a Federal.<\/p>\n<p>Nesta quinta, 28, Temer tornou-se r\u00e9u em a\u00e7\u00e3o criminal pela primeira vez por decis\u00e3o do juiz Rodrigo Parente Paiva, da 15\u00aa Vara Federal de Bras\u00edlia. Neste caso, o ex-presidente \u00e9 acusado por corrup\u00e7\u00e3o por causa da mala de R$ 500 mil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal, no Rio, denunciou criminalmente o ex-presidente Michel Temer e o ex-ministro Moreira Franco, de Minas e Energia, por supostos desvios nas obras da usina nuclear de Angra 3. Os dois s\u00e3o alvo da Opera\u00e7\u00e3o Descontamina\u00e7\u00e3o \u2013 desdobramento, no Rio de Janeiro, da Lava Jato. Contra Temer, especificamente, foram apresentadas acusa\u00e7\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":171652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-205860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205860"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205860\/revisions"}],"predecessor-version":[{"id":205861,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205860\/revisions\/205861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/171652"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}