{"id":205864,"date":"2019-03-29T15:01:57","date_gmt":"2019-03-29T18:01:57","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205864"},"modified":"2019-03-29T15:01:57","modified_gmt":"2019-03-29T18:01:57","slug":"inadimplencia-de-empresas-cresce-5-em-fevereiro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/inadimplencia-de-empresas-cresce-5-em-fevereiro\/","title":{"rendered":"Inadimpl\u00eancia de empresas cresce 5% em fevereiro"},"content":{"rendered":"<p>O n\u00famero de empresas com contas em atraso e registradas no cadastro de inadimplentes cresceu 5,02% em fevereiro na compara\u00e7\u00e3o com o mesmo m\u00eas de 2018. No entanto, o ritmo de alta perdeu for\u00e7a em todas as regi\u00f5es do pa\u00eds. O n\u00famero de d\u00edvidas contra\u00eddas em nome de pessoas jur\u00eddicas avan\u00e7ou 1,84% na compara\u00e7\u00e3o anual.<\/p>\n<p>Al\u00e9m disso, cada empresa devedora continua acumulando, em m\u00e9dia, duas pend\u00eancias financeiras. Os dados, divulgados nesta sexta-feira (29), s\u00e3o da Confedera\u00e7\u00e3o Nacional de Dirigentes Lojistas (CNDL) e do Servi\u00e7o de Prote\u00e7\u00e3o ao Cr\u00e9dito (SPC Brasil).<\/p>\n<p>De acordo com o indicador de inadimpl\u00eancia das empresas, o maior crescimento quanto ao n\u00famero de empresas negativadas foi observado no Sudeste, com alta de 8,65%. No Sul chegou a 2,99%, no Centro-Oeste a 1,54% e no Nordeste a 1,31%. O Norte apresentou a menor varia\u00e7\u00e3o entre as cinco regi\u00f5es, com -0,03%.<\/p>\n<p>Para o presidente do SPC Brasil, Roque Pellizzaro Junior, a queda da inadimpl\u00eancia deve-se a um cen\u00e1rio mais positivo em que j\u00e1 se observa uma melhora gradativa do faturamento de alguns setores da economia e taxas de juros mais baixas. \u201cApesar de as empresas ainda n\u00e3o terem recuperado a sa\u00fade financeira nos mesmos n\u00edveis que antecederam a crise, as vendas come\u00e7am a reagir dando f\u00f4lego maior para que elas cumpram seus compromissos\u201d, analisa.<\/p>\n<p>Dados abertos por setor da economia revelam que o aumento da inadimpl\u00eancia foi maior entre as empresas que atuam no ramo de servi\u00e7os, cujo avan\u00e7o foi 8,16% em fevereiro de 2019 na compara\u00e7\u00e3o com o mesmo per\u00edodo do ano anterior. Os atrasos entre empresas do com\u00e9rcio cresceram 2,87%, ao passo que a ind\u00fastria registrou varia\u00e7\u00e3o de 1,91%.<\/p>\n<p>Entre os segmentos credores, ou seja, empresas que deixaram de receber de outras empresas, o destaque tamb\u00e9m ficou por conta do ramo de servi\u00e7os, que engloba bancos e financeiras. Em termos de participa\u00e7\u00e3o, o setor det\u00e9m a maior fatia do total de d\u00edvidas, com 69,6%. O com\u00e9rcio manteve 17,2% das d\u00edvidas de empresas e a ind\u00fastria ficou com 12,4%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00famero de empresas com contas em atraso e registradas no cadastro de inadimplentes cresceu 5,02% em fevereiro na compara\u00e7\u00e3o com o mesmo m\u00eas de 2018. No entanto, o ritmo de alta perdeu for\u00e7a em todas as regi\u00f5es do pa\u00eds. O n\u00famero de d\u00edvidas contra\u00eddas em nome de pessoas jur\u00eddicas avan\u00e7ou 1,84% na compara\u00e7\u00e3o anual. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-205864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205864"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205864\/revisions"}],"predecessor-version":[{"id":205866,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205864\/revisions\/205866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205865"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}