{"id":205872,"date":"2019-03-29T20:00:07","date_gmt":"2019-03-29T23:00:07","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205872"},"modified":"2019-03-29T23:58:36","modified_gmt":"2019-03-30T02:58:36","slug":"planalto-quer-povo-louvando-a-bandeira-nacional","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/planalto-quer-povo-louvando-a-bandeira-nacional\/","title":{"rendered":"Planalto quer povo louvando a Bandeira Nacional"},"content":{"rendered":"<p>Em meio a conflitos sobre se os quarteis devem ou n\u00e3o festejar os 55 anos do &#8216;movimento militar&#8217; de 1964, quando o ent\u00e3o presidente Jo\u00e3o Goulart foi deposto, o porta-voz da Presid\u00eancia da Rep\u00fablica, general R\u00eago Barros, fez um apelo nesta sexta, 29, ao patriotismo dos brasileiros para que prestem homenagens \u00e0 Bandeira Nacional.<\/p>\n<p>A declara\u00e7\u00e3o foi feita ap\u00f3s o presidente Jair Bolsonaro ter participado horas antes, no Pal\u00e1cio da Alvorada, da cerim\u00f4nia de hasteamento da bandeira. \u201cGostaria muito que toda a sociedade tivesse a disponibilidade e o patriotismo de prostrar-se diante da bandeira ao menos uma vez por semana\u201d, disse o porta-voz.<\/p>\n<p>Por meio desse gesto, frisou R\u00eago Barros, o brasileiro estar\u00e1 demonstrando &#8220;seu apre\u00e7o \u00e0 soberania que essa Bandeira representa e a import\u00e2ncia de n\u00f3s termos uma sociedade democr\u00e1tica e livre\u201d.<\/p>\n<p>No in\u00edcio da semana, Bolsonaro recomendou que as For\u00e7as Armadas &#8216;rememorassem&#8217; o 31 de mar\u00e7o de 64, que completar\u00e1 55 anos neste domingo. Na parte da manh\u00e3, no Quartel-General do Ex\u00e9rcito, no Setor Militar Urbano, o Comando Militar do Planalto realizou uma cerim\u00f4nia para relembrar a data. O comandante do Ex\u00e9rcito, general Edson Leal Pujol, participou do ato.<\/p>\n<p>Horas depois a ju\u00edza da 6\u00aa Vara Federal de Bras\u00edlia, Ivani Silva da Luz, determinou que os militares se abstenham de manifesta\u00e7\u00f5es sobre a data. A magistrada acolhe pedido de defensores p\u00fablicos Federais, em a\u00e7\u00e3o civil p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio a conflitos sobre se os quarteis devem ou n\u00e3o festejar os 55 anos do &#8216;movimento militar&#8217; de 1964, quando o ent\u00e3o presidente Jo\u00e3o Goulart foi deposto, o porta-voz da Presid\u00eancia da Rep\u00fablica, general R\u00eago Barros, fez um apelo nesta sexta, 29, ao patriotismo dos brasileiros para que prestem homenagens \u00e0 Bandeira Nacional. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-205872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205872"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205872\/revisions"}],"predecessor-version":[{"id":205876,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205872\/revisions\/205876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205873"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}