{"id":205923,"date":"2019-03-30T15:17:59","date_gmt":"2019-03-30T18:17:59","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=205923"},"modified":"2019-03-30T15:19:05","modified_gmt":"2019-03-30T18:19:05","slug":"putin-sugere-a-trump-parar-de-ameacar-maduro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/putin-sugere-a-trump-parar-de-ameacar-maduro\/","title":{"rendered":"Putin sugere a Trump parar de amea\u00e7ar Maduro"},"content":{"rendered":"<p>A R\u00fassia voltou a defender neste s\u00e1bado, 30, a presen\u00e7a de seus militares enviados nos \u00faltimos dias para a Venezuela e recomendou que o presidente Donald Trump, dos Estados Unidos, deixe de &#8220;amea\u00e7ar&#8221; o pa\u00eds caribenho, que passa por uma profunda crise pol\u00edtica e social.<\/p>\n<p>&#8220;N\u00f3s recomendamos aos Estados Unidos que deixem de amea\u00e7ar a Venezuela, de asfixiar sua economia e de empurrar o pa\u00eds para uma guerra civil ao violar abertamente o direito internacional&#8221;, disse a porta-voz da diplomacia russa, Maria Zakharova, em comunicado emitido por determina\u00e7\u00e3o do presidente Vladimir Putin.<\/p>\n<p>&#8220;Fazemos um chamado a todas as for\u00e7as pol\u00edticas venezuelanas que coloquem os interesses de sua p\u00e1tria acima de suas pr\u00f3prias ambi\u00e7\u00f5es para dialogar&#8221;, completou Maria.<\/p>\n<p>Os EUA advertiram a R\u00fassia na sexta-feira contra o envio de militares para a Venezuela em apoio ao presidente Nicol\u00e1s Maduro, considerando essas a\u00e7\u00f5es uma &#8220;provoca\u00e7\u00e3o&#8221; e reafirmando sua determina\u00e7\u00e3o de defender seus interesses e de seus parceiros na regi\u00e3o.<\/p>\n<p>&#8220;A R\u00fassia indicou claramente o objetivo da ida de especialistas para Caracas. Trata-se de um &#8216;contingente militar'&#8221;, respondeu, ainda na sexta, a porta-voz de Moscou.<\/p>\n<p>O Kremlin pediu nesta semana que Trump n\u00e3o interfira nos assuntos bilaterais entre Venezuela e R\u00fassia, afirmando que os russos atuam dentro do marco de acordos e contratos firmados por Moscou e Caracas.<\/p>\n<p>A R\u00fassia e a Venezuela assinaram em 2011 um acordo de coopera\u00e7\u00e3o militar que prev\u00ea a venda de armamento russo a Caracas financiados por uma linha de cr\u00e9dito aberta por Putin para o chavismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A R\u00fassia voltou a defender neste s\u00e1bado, 30, a presen\u00e7a de seus militares enviados nos \u00faltimos dias para a Venezuela e recomendou que o presidente Donald Trump, dos Estados Unidos, deixe de &#8220;amea\u00e7ar&#8221; o pa\u00eds caribenho, que passa por uma profunda crise pol\u00edtica e social. &#8220;N\u00f3s recomendamos aos Estados Unidos que deixem de amea\u00e7ar a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":205924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[95],"class_list":["post-205923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=205923"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205923\/revisions"}],"predecessor-version":[{"id":205926,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/205923\/revisions\/205926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/205924"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=205923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=205923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=205923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}