{"id":206149,"date":"2019-04-03T00:19:50","date_gmt":"2019-04-03T03:19:50","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206149"},"modified":"2019-04-03T03:05:13","modified_gmt":"2019-04-03T06:05:13","slug":"lava-jato-paulista-tambem-pede-prisao-de-temer","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/lava-jato-paulista-tambem-pede-prisao-de-temer\/","title":{"rendered":"Lava Jato paulista tamb\u00e9m quer Temer preso"},"content":{"rendered":"<p>A for\u00e7a tarefa da Opera\u00e7\u00e3o Lava Jato do Minist\u00e9rio P\u00fablico Federal (MPF) em S\u00e3o Paulo denunciou nesta ter\u00e7a (2) o ex-presidente da Rep\u00fablica Michel Temer pelo crime de lavagem de dinheiro. De acordo com a den\u00fancia, o ex-presidente utilizou dinheiro de corrup\u00e7\u00e3o e de desvios da obra da Usina de Angra 3, em Angra dos Reis (RJ), para pagar a reforma na resid\u00eancia de sua filha Maristela Temer, no valor de R$ 1,6 milh\u00e3o. A obra ocorreu de 2013 a 2015.<\/p>\n<p>Al\u00e9m de Temer e de sua filha, tamb\u00e9m foram denunciados Jo\u00e3o Batista Lima Filho, o coronel Lima, e Maria Rita Fratezi, esposa do coronel, ambos s\u00f3cios-propriet\u00e1rios da Argeplan, que fez a maioria dos pagamentos da obra. Todos foram denunciados por lavagem de dinheiro.<\/p>\n<p>\u201cH\u00e1 di\u00e1logos que foram obtidos por medidas de busca que indicam conversas da senhora Maria Rita [controladora da Argeplan] e a senhora Maristela [filha de Michel Temer] e que demonstram que a senhora Maria Rita reportava \u00e0 senhora Maristela dados relativos \u00e0 obra empreendida sob a coordena\u00e7\u00e3o da Argeplan e a senhora Maristela responde no sentido de levar a autoriza\u00e7\u00e3o de gastos ao pai dela\u201d, destacou o procurador da Rep\u00fablica L\u00facio Mauro Carloni.<\/p>\n<p>De acordo com o MPF, a rela\u00e7\u00e3o de Temer com a Argeplan tem mais de 30 anos. Segundo os procuradores, \u00e0 medida em que Temer cresceu politicamente, a empresa do coronel passou a usufruir de grandes contratos p\u00fablicos, em especial quando Temer assumiu a Secretaria de Seguran\u00e7a P\u00fablica de S\u00e3o Paulo, ap\u00f3s o massacre do Carandiru, em 1992.<\/p>\n<p>O MPF destaca que o escrit\u00f3rio da Argeplan na vila Madalena, zona oeste da capital, foi o local de entrega de duas remessas de propina pagas em 2014 pela JBS e pela empreiteira Odebrecht, no valor somado de R$ 2,4 milh\u00f5es.<\/p>\n<p>Nesta ter\u00e7a-feira, Temer, Coronel Lima e Moreira Franco se tornaram r\u00e9us por desvios em obras da Usina Angra 3 ap\u00f3s o juiz Marcelo Bretas, da 7\u00aa Vara Criminal, aceitar duas den\u00fancias contra os acusados feitas na semana passada pelo Minist\u00e9rio P\u00fablico Federal no Rio. Eles responder\u00e3o por corrup\u00e7\u00e3o passiva, peculato (quando funcion\u00e1rio p\u00fablico tira vantagem do cargo) e lavagem de dinheiro.<\/p>\n<p>Em nota, os advogados Cristiano Benzota e Maur\u00edcio Leite, que defendem o coronel Lima e Maria Rita Fratezi, disseram que as den\u00fancias do MPF foram precipitadas \u2013 seja no caso do Rio de Janeiro, seja no caso de S\u00e3o Paulo \u2013 tendo em vista que os autos da investiga\u00e7\u00e3o do inqu\u00e9rito dos portos e seus desdobramentos \u201cficaram por mais de quarenta dias com a Procuradoria Geral da Rep\u00fablica\u201d.<\/p>\n<p>\u201cMesmo ap\u00f3s extensa avalia\u00e7\u00e3o, os remeteu para a primeira inst\u00e2ncia para que fossem instaurados inqu\u00e9ritos policiais, o que demonstra a inexist\u00eancia de provas dos supostos crimes e, quando muito, apenas a necessidade de continuidade das investiga\u00e7\u00f5es, que sequer foram realizadas\u201d.<\/p>\n<p>J\u00e1 o advogado de Maristela Temer, Fernando Castelo Branco, disse que n\u00e3o houve, por parte do MPF, preocupa\u00e7\u00e3o em se verificar a veracidade dos fatos. Segundo o advogado, Maristela j\u00e1 esclareceu o caso quando foi ouvida pela pol\u00edcia. \u201cA origem dos valores utilizados para a reforma de sua resid\u00eancia \u00e9 l\u00edcita e Maristela Temer jamais participou de qualquer conduta voltada \u00e0 lavagem de dinheiro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A for\u00e7a tarefa da Opera\u00e7\u00e3o Lava Jato do Minist\u00e9rio P\u00fablico Federal (MPF) em S\u00e3o Paulo denunciou nesta ter\u00e7a (2) o ex-presidente da Rep\u00fablica Michel Temer pelo crime de lavagem de dinheiro. De acordo com a den\u00fancia, o ex-presidente utilizou dinheiro de corrup\u00e7\u00e3o e de desvios da obra da Usina de Angra 3, em Angra dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-206149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206149"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206149\/revisions"}],"predecessor-version":[{"id":206165,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206149\/revisions\/206165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206150"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}