{"id":206163,"date":"2019-04-03T03:04:00","date_gmt":"2019-04-03T06:04:00","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206163"},"modified":"2019-04-03T03:04:00","modified_gmt":"2019-04-03T06:04:00","slug":"mourao-nada-contra-a-mare-do-nazismo-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/mourao-nada-contra-a-mare-do-nazismo-de-bolsonaro\/","title":{"rendered":"Mour\u00e3o nada contra a mar\u00e9 do nazismo de Bolsonaro"},"content":{"rendered":"<p>Os nazistas nunca foram de esquerda. Esquerda \u00e9 coisa de comunista. Mas, no frigir dos ovos, s\u00e3o dois regimes totalit\u00e1rios. S\u00e3o as faces de uma mesma moeda. Essa \u00e9 a nova diverg\u00eancia que op\u00f5e os dois chefes do governo brasileiro. Um, titular, \u00e9 Jair Bolsonaro; outro, eventual mandat\u00e1rio, \u00e9 o vice Hamilton Mour\u00e3o, que faz as vezes do N\u00famero 1 quando o titular est\u00e1 ausente.<\/p>\n<p>Nesta ter\u00e7a, 2, no exerc\u00edcio da Presid\u00eancia, Mour\u00e3o, provocado por jornalistas, sinalizou diverg\u00eancia em rela\u00e7\u00e3o ao conceito que Bolsonaro tem dessas ideologias. &#8220;De esquerda \u00e9 o comunismo. N\u00e3o resta a menor d\u00favida&#8221;, disse o vice. Segundo ele, nazismo e comunismo est\u00e3o em lados opostos, embora sejam &#8220;faces de uma moeda s\u00f3, o totalitarismo&#8221;, frisou.<\/p>\n<p>Horas antes, em Israel &#8211; de onde regressa na quarta, 3 &#8211; Jair Bolsonaro afirmou concordar com o chanceler Ernesto Ara\u00fajo em rela\u00e7\u00e3o \u00e0 avalia\u00e7\u00e3o de que o nazismo foi um movimento de esquerda. &#8220;N\u00e3o h\u00e1 d\u00favida&#8221;, resumiu o presidente.<\/p>\n<p>O ponto de vista de Mour\u00e3o \u00e9 outro.\u00a0&#8220;De esquerda \u00e9 o comunismo, n\u00e9? N\u00e3o resta a m\u00ednima d\u00favida. Quer dizer, acho que se a gente for olhar&#8230; Sou cr\u00edtico contumaz dessa quest\u00e3o de direita e esquerda, acho que s\u00e3o ambas vis\u00f5es totalit\u00e1rias de controle total da popula\u00e7\u00e3o, de desrespeito aos direitos humanos, que n\u00e3o se coadunam com o esp\u00edrito que a gente busca para a humanidade&#8221;, declarou.<\/p>\n<p>Mour\u00e3o \u00e9 cr\u00edtico contumaz de extremos da direita e esquerda e insiste que nazismo e comunismo est\u00e3o em lados opostos de uma mesma moeda. &#8220;Eu critico esquerda e direita. Acho que esquerda \u00e9 quando tem vis\u00e3o onde o estado interv\u00e9m mais na vida das pessoas, diferente de ser autorit\u00e1rio, isso \u00e9 ser esquerda. E direita \u00e9 voc\u00ea dar mais liberdade aos empreendedores, ter mais liberdade para poder estabelecer seus neg\u00f3cios, propriedade privada. Isso \u00e9 o que eu acho de direita e esquerda. Nazismo e comunismo s\u00e3o duas faces de uma moeda s\u00f3, o totalitarismo.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os nazistas nunca foram de esquerda. Esquerda \u00e9 coisa de comunista. Mas, no frigir dos ovos, s\u00e3o dois regimes totalit\u00e1rios. S\u00e3o as faces de uma mesma moeda. Essa \u00e9 a nova diverg\u00eancia que op\u00f5e os dois chefes do governo brasileiro. Um, titular, \u00e9 Jair Bolsonaro; outro, eventual mandat\u00e1rio, \u00e9 o vice Hamilton Mour\u00e3o, que faz [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":202460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-206163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206163"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206163\/revisions"}],"predecessor-version":[{"id":206164,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206163\/revisions\/206164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/202460"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}