{"id":206177,"date":"2019-04-03T13:32:51","date_gmt":"2019-04-03T16:32:51","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206177"},"modified":"2019-04-03T13:32:51","modified_gmt":"2019-04-03T16:32:51","slug":"bolsonaro-fala-em-jogar-pesado-pela-previdencia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/","title":{"rendered":"Bolsonaro fala em &#8216;jogar pesado&#8217; pela Previd\u00eancia"},"content":{"rendered":"<p>O presidente Jair Bolsonaro est\u00e1 viajando de volta ao Brasil debru\u00e7ado sobre um calhama\u00e7o de pap\u00e9is. Vem a ser um &#8216;pacote&#8217; de medidas econ\u00f4micas capaz, segundo ele, de tirar o Brasil do &#8216;fundo do po\u00e7o&#8217;. Antes de embarcar ele n\u00e3o eu detalhes. &#8220;Vou observar at\u00e9 as v\u00edrgulas; quando chegar a Bras\u00edlia (ele deve desembarcar pouco depois das 20 horas) verei o que fazer&#8221;, declarou ainda em em Israel.<\/p>\n<p>Outro tema que vai merecer aten\u00e7\u00e3o especial ser\u00e1 a reforma da Previd\u00eancia Social. O presidente pretende ter uma ampla reuni\u00e3o com l\u00edderes partid\u00e1rios no decorrer desta quinta, 4, na tentativa de convencer o Congresso Nacional a aprovar as mudan\u00e7as. Bolsonaro avalia que se a Nova Previd\u00eancia der certo, o Brasil &#8216;ter\u00e1 tudo para decolar&#8217;.<\/p>\n<p>Ainda em Jerusal\u00e9m, Bolsonaro demonstrou disposi\u00e7\u00e3o em ceder em sua proposta de reforma, j\u00e1 que considera o Congresso &#8220;soberano para fazer polimentos&#8221; e tirar &#8220;alguma coisa&#8221; do texto. &#8220;Isso (conversas com parlamentares) eu tenho que enfrentar, mas conhe\u00e7o a maioria dos parlamentares. N\u00e3o tenho problemas em dialogar com eles, n\u00e3o&#8221;, comentou. Ele disse que n\u00e3o sabia ainda com quem seria a primeira audi\u00eancia no retorno ao Pa\u00eds.<\/p>\n<p>O certo, disse Bolsonaro, \u00e9 que ele &#8216;jogar\u00e1 pesado&#8217; na reforma da Previd\u00eancia. Nestes dias em Israel, ele mostrou preocupa\u00e7\u00e3o com a possibilidade de as altera\u00e7\u00f5es propostas pelos deputados acabarem &#8220;desidratando&#8221; o projeto original. O presidente da C\u00e2mara, Rodrigo Maia, j\u00e1 sinalizou que a capitaliza\u00e7\u00e3o do sistema previdenci\u00e1rio e mudan\u00e7as na aposentadoria rural e na assist\u00eancia a idosos de baixa renda (BPC) n\u00e3o devem passar no Congresso.<\/p>\n<p>&#8220;A gente gostaria que passasse como chegou, mas sabemos que vai ter mudan\u00e7as. N\u00e3o existe projeto que n\u00e3o tem mudan\u00e7a, \u00e9 coisa rara acontecer isso a\u00ed, ainda mais um projeto t\u00e3o amplo, como \u00e9 o da reforma da Previd\u00eancia&#8221;, observou. Segundo o presidente, n\u00e3o \u00e9 quest\u00e3o de abrir m\u00e3o da proposta enviada ao Legislativo. &#8220;O deputado que eu fui durante 28 anos, na ponta da linha, sabe onde o calo dele aperta e questiona seu l\u00edder, e chega no Rodrigo Maia: &#8216;Essa quest\u00e3o aqui, se n\u00e3o tirar, a gente vota contra o projeto como um todo'&#8221;, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro est\u00e1 viajando de volta ao Brasil debru\u00e7ado sobre um calhama\u00e7o de pap\u00e9is. Vem a ser um &#8216;pacote&#8217; de medidas econ\u00f4micas capaz, segundo ele, de tirar o Brasil do &#8216;fundo do po\u00e7o&#8217;. Antes de embarcar ele n\u00e3o eu detalhes. &#8220;Vou observar at\u00e9 as v\u00edrgulas; quando chegar a Bras\u00edlia (ele deve desembarcar pouco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"tmauthors":[],"class_list":["post-206177","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","tag-capa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsonaro fala em &#039;jogar pesado&#039; pela Previd\u00eancia - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsonaro fala em &#039;jogar pesado&#039; pela Previd\u00eancia - Notibras\" \/>\n<meta property=\"og:description\" content=\"O presidente Jair Bolsonaro est\u00e1 viajando de volta ao Brasil debru\u00e7ado sobre um calhama\u00e7o de pap\u00e9is. Vem a ser um &#8216;pacote&#8217; de medidas econ\u00f4micas capaz, segundo ele, de tirar o Brasil do &#8216;fundo do po\u00e7o&#8217;. Antes de embarcar ele n\u00e3o eu detalhes. &#8220;Vou observar at\u00e9 as v\u00edrgulas; quando chegar a Bras\u00edlia (ele deve desembarcar pouco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T16:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Bolsonaro fala em &#8216;jogar pesado&#8217; pela Previd\u00eancia\",\"datePublished\":\"2019-04-03T16:32:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/volta-de-bolsonaro.3.jpg\",\"keywords\":[\"capa\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/\",\"name\":\"Bolsonaro fala em 'jogar pesado' pela Previd\u00eancia - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/volta-de-bolsonaro.3.jpg\",\"datePublished\":\"2019-04-03T16:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/volta-de-bolsonaro.3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/volta-de-bolsonaro.3.jpg\",\"width\":1140,\"height\":760,\"caption\":\"Foto: Alan Santos\\\/PR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsonaro fala em &#8216;jogar pesado&#8217; pela Previd\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsonaro fala em 'jogar pesado' pela Previd\u00eancia - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Bolsonaro fala em 'jogar pesado' pela Previd\u00eancia - Notibras","og_description":"O presidente Jair Bolsonaro est\u00e1 viajando de volta ao Brasil debru\u00e7ado sobre um calhama\u00e7o de pap\u00e9is. Vem a ser um &#8216;pacote&#8217; de medidas econ\u00f4micas capaz, segundo ele, de tirar o Brasil do &#8216;fundo do po\u00e7o&#8217;. Antes de embarcar ele n\u00e3o eu detalhes. &#8220;Vou observar at\u00e9 as v\u00edrgulas; quando chegar a Bras\u00edlia (ele deve desembarcar pouco [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2019-04-03T16:32:51+00:00","og_image":[{"width":1140,"height":760,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Bolsonaro fala em &#8216;jogar pesado&#8217; pela Previd\u00eancia","datePublished":"2019-04-03T16:32:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg","keywords":["capa"],"articleSection":["Brasil"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/","url":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/","name":"Bolsonaro fala em 'jogar pesado' pela Previd\u00eancia - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg","datePublished":"2019-04-03T16:32:51+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2019\/04\/volta-de-bolsonaro.3.jpg","width":1140,"height":760,"caption":"Foto: Alan Santos\/PR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/bolsonaro-fala-em-jogar-pesado-pela-previdencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Bolsonaro fala em &#8216;jogar pesado&#8217; pela Previd\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206177"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206177\/revisions"}],"predecessor-version":[{"id":206179,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206177\/revisions\/206179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206178"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206177"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=206177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}