{"id":206242,"date":"2019-04-04T11:03:32","date_gmt":"2019-04-04T14:03:32","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206242"},"modified":"2019-04-04T11:03:32","modified_gmt":"2019-04-04T14:03:32","slug":"stf-tira-da-pauta-acao-que-pode-dar-liberdade-a-lula","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/stf-tira-da-pauta-acao-que-pode-dar-liberdade-a-lula\/","title":{"rendered":"STF tira da pauta a\u00e7\u00e3o que pode dar liberdade a Lula"},"content":{"rendered":"<p>O presidente do Supremo Tribunal Federal (STF), ministro Dias Toffoli, atendeu a um pedido da Ordem dos Advogados do Brasil (OAB) e suspendeu o julgamento das a\u00e7\u00f5es que tratam da pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia, que estava marcado para 10 de abril. N\u00e3o h\u00e1 data para que o tema volte \u00e0 pauta.<\/p>\n<p>A OAB \u00e9 autora de uma das tr\u00eas a\u00e7\u00f5es declarat\u00f3rias de constitucionalidade (ADC) que tratam do assunto, cujo relator \u00e9 o ministro Marco Aur\u00e9lio Mello. As outras duas foram abertas pelos partidos PEN, hoje Patriota, e PCdoB.<\/p>\n<p>Nesta semana, o rec\u00e9m-eleito presidente do Conselho Federal da OAB, Felipe Santa Cruz, enviou um of\u00edcio a Toffoli, fora dos autos da ADC, pedindo o adiamento do julgamento, cuja data havia sido marcada pelo presidente do STF em dezembro.<\/p>\n<p>\u201c\u00c9 que, a prop\u00f3sito, a nova Diretoria deste Conselho, rec\u00e9m empossada, ainda est\u00e1 se inteirando de todos os aspectos envolvidos no presente processo e outros temas correlatos, raz\u00e3o pela qual necessita de maior prazo para estudar a melhor solu\u00e7\u00e3o para o caso\u201d, diz o pedido encaminhado por Santa Cruz.<\/p>\n<p>A suspens\u00e3o do julgamento foi feita \u00e0 revelia do relator, Marco Aur\u00e9lio, que afirmou que se o pedido tivesse sido encaminhado a ele, \u201cfatalmente n\u00e3o adiaria\u201d. Desde ao menos o in\u00edcio do ano passado, o ministro cobra o julgamento das ADC\u00b4s, liberadas para an\u00e1lise do plen\u00e1rio desde dezembro de 2017.<\/p>\n<p>Internamente, ministros avaliam que o adiamento alivia a press\u00e3o da opini\u00e3o p\u00fablica sobre o Supremo, uma vez que uma decis\u00e3o contra a pris\u00e3o em segunda inst\u00e2ncia poderia beneficiar o ex-presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n<p>O ex-presidente est\u00e1 preso desde 7 de abril na Superintend\u00eancia da Pol\u00edcia Federal em Curitiba, ap\u00f3s ter tido sua condena\u00e7\u00e3o por corrup\u00e7\u00e3o e lavagem de dinheiro na Lava Jato confirmada pelo Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF4), segunda inst\u00e2ncia da Justi\u00e7a Federal, com sede em Porto Alegre.<\/p>\n<p>Um recurso de Lula contra a condena\u00e7\u00e3o est\u00e1 prestes a ser julgado no Superior Tribunal de Justi\u00e7a (STJ), em Bras\u00edlia. Ao adiar o julgamento das ADC\u00b4s sobre a segunda inst\u00e2ncia para uma data provavelmente posterior, o Supremo deve evitar que o debate seja fulanizado.<\/p>\n<p>No ano passado, a presidente anterior do STF, ministra C\u00e1rmen L\u00facia, n\u00e3o a pautou as a\u00e7\u00f5es. Na ocasi\u00e3o, havia uma press\u00e3o causada pela condena\u00e7\u00e3o de Lula no TRF4. A ministra resolveu, h\u00e1 um ano, pautar um habeas corpus do ex-presidente, que acabou rejeitado por 6 votos a 5.<\/p>\n<p>No voto decisivo, a ministra Rosa Weber disse que em princ\u00edpio \u00e9 contra a pris\u00e3o ap\u00f3s segunda inst\u00e2ncia, mas que votaria contra o pedido de liberdade do ex-presidente em respeito ao entendimento vigente do Supremo, que autoriza o cumprimento antecipado da pena.<\/p>\n<p>Na ocasi\u00e3o, Weber indicou que numa eventual an\u00e1lise de m\u00e9rito das ADC\u00b4s sobre o assunto, poderia votar contra a pris\u00e3o em segunda inst\u00e2ncia, o que mudaria o entendimento atual que autoriza a medida.<\/p>\n<p>O Supremo j\u00e1 alterou algumas vezes o entendimento sobre o assunto, e desde de 2016, na an\u00e1lise de uma liminar sobre o tema, por 6 votos a 5 foi autorizada o cumprimento de pena ap\u00f3s a condena\u00e7\u00e3o em segundo grau da Justi\u00e7a.<\/p>\n<p>Desde ent\u00e3o, alterou-se a composi\u00e7\u00e3o do plen\u00e1rio e ao menos um ministro, Gilmar Mendes, anunciou ter alterado seu entendimento, posicionando-se contra a pris\u00e3o em segunda inst\u00e2ncia. O tema diz respeito a centenas de milhares de presos provis\u00f3rios que aguardam o entendimento definitivo do Supremo em penitenci\u00e1rias superlotadas.<\/p>\n<p>Em dezembro, Marco Aur\u00e9lio chegou a conceder uma liminar libertando todos os presos que ainda tenham recursos pendentes de an\u00e1lise em inst\u00e2ncias superiores, mas a medida foi cassada por Toffoli pouco depois.<\/p>\n<p>Nas ADC\u00b4s, os autores sustentam que, de acordo com a Constitui\u00e7\u00e3o, um condenado s\u00f3 pode come\u00e7ar a cumprir pena e ter afastada sua presun\u00e7\u00e3o de inoc\u00eancia ap\u00f3s o tr\u00e2nsito em julgado do processo, isto \u00e9, quando n\u00e3o \u00e9 mais poss\u00edvel recorrer aos tribunais superiores em Bras\u00edlia, incluindo o pr\u00f3prio STF.<\/p>\n<p>A Procuradoria-Geral da Rep\u00fablica, que \u00e9 contra a medida, argumenta que a pris\u00e3o ap\u00f3s a segunda inst\u00e2ncia garante que a Justi\u00e7a seja feita, ante a demora no julgamento de volumosos recursos nos tribunais superiores.<\/p>\n<p>No m\u00eas passado, a Advocacia-Geral da Uni\u00e3o (AGU) apoiou o posicionamento da PGR, argumentando, em manifesta\u00e7\u00e3o enviada ao STF, que n\u00e3o h\u00e1 preju\u00edzo ao princ\u00edpio da presun\u00e7\u00e3o de inoc\u00eancia se condenados come\u00e7arem a cumprir pena antes de eventuais recursos a inst\u00e2ncias superiores, levando-se em considera\u00e7\u00e3o que em todas os graus de jurisdi\u00e7\u00e3o s\u00e3o garantidos diferentes recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Supremo Tribunal Federal (STF), ministro Dias Toffoli, atendeu a um pedido da Ordem dos Advogados do Brasil (OAB) e suspendeu o julgamento das a\u00e7\u00f5es que tratam da pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia, que estava marcado para 10 de abril. N\u00e3o h\u00e1 data para que o tema volte \u00e0 pauta. A OAB [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":201019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-206242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206242"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206242\/revisions"}],"predecessor-version":[{"id":206243,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206242\/revisions\/206243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/201019"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}