{"id":206574,"date":"2019-04-09T06:00:48","date_gmt":"2019-04-09T09:00:48","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206574"},"modified":"2019-04-09T07:06:34","modified_gmt":"2019-04-09T10:06:34","slug":"rio-amanhece-debaixo-dagua-chuva-mata-3","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/rio-amanhece-debaixo-dagua-chuva-mata-3\/","title":{"rendered":"Rio amanhece debaixo d&#8217;\u00e1gua; chuva mata 3"},"content":{"rendered":"<p>O Rio amanheceu debaixo d&#8217;\u00e1gua nesta ter\u00e7a-feira, 9, ap\u00f3s o temporal da v\u00e9spera que deixou tr\u00eas pessoas mortas e provocou estragos incalcul\u00e1veis em v\u00e1rias zonas da cidade. O prefeito Marcelo Crivella decretou estado de crise.<\/p>\n<p>O temporal alagou ruas, derrubou \u00e1rvores e destruiu carros em v\u00e1rios bairros. A Pol\u00edcia Militar confirmou que uma pessoa morreu na Rua Marqu\u00eas de S\u00e3o Vicente, na G\u00e1vea, zona sul da cidade.<\/p>\n<p>J\u00e1 no Morro da Babil\u00f4nia, o Corpo de Bombeiros foi acionado para prestar socorro em um soterramento e informou que duas mulheres adultas morreram.<\/p>\n<p>A for\u00e7a da \u00e1gua tamb\u00e9m causou o desabamento de mais um trecho da ciclovia Tim Maia, projetada para ligar o Leblon, na zona sul, \u00e0 Barra da Tijuca, na zona oeste.<\/p>\n<p>Desde que foi inaugurada, em 2016, a estrutura j\u00e1 sofreu quatro desabamentos. O mais grave deles ocorreu logo ap\u00f3s a inaugura\u00e7\u00e3o, quando uma ressaca no mar derrubou uma parte da pista, matando duas pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Rio amanheceu debaixo d&#8217;\u00e1gua nesta ter\u00e7a-feira, 9, ap\u00f3s o temporal da v\u00e9spera que deixou tr\u00eas pessoas mortas e provocou estragos incalcul\u00e1veis em v\u00e1rias zonas da cidade. O prefeito Marcelo Crivella decretou estado de crise. O temporal alagou ruas, derrubou \u00e1rvores e destruiu carros em v\u00e1rios bairros. A Pol\u00edcia Militar confirmou que uma pessoa morreu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-206574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206574"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206574\/revisions"}],"predecessor-version":[{"id":206577,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206574\/revisions\/206577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206575"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}