{"id":206737,"date":"2019-04-11T12:07:02","date_gmt":"2019-04-11T15:07:02","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206737"},"modified":"2019-04-11T12:09:07","modified_gmt":"2019-04-11T15:09:07","slug":"to-com-gentili-o-pt-so-goza-e-nao-quer-ser-ferrado-diz-bolsonaro","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/to-com-gentili-o-pt-so-goza-e-nao-quer-ser-ferrado-diz-bolsonaro\/","title":{"rendered":"&#8216;T\u00f4 com Gentili. O PT s\u00f3 goza e n\u00e3o quer ser ferrado&#8217;, diz Bolsonaro"},"content":{"rendered":"<p>O presidente Jair Bolsonaro usou o Twitter nesta quinta, 11, para manifestar solidariedade ao apresentador Danilo Gentili, que na quarta-feira, 10, foi condenado a seis meses e 28 dias de pris\u00e3o em regime semiaberto por suposta inj\u00faria \u00e0 deputada federal Maria do Ros\u00e1rio (PT-RS).<\/p>\n<p>\u201cMe solidarizo com o apresentador e comediante Danilo Gentili ao exercer seu direito de livre express\u00e3o e sua profiss\u00e3o, da qual, por vezes, eu mesmo sou alvo, mas compreendo que s\u00e3o piadas e faz parte do jogo, algo que infelizmente vale para uns e n\u00e3o para outros\u201d, escreveu Bolsonaro.<\/p>\n<p>O pr\u00f3prio presidente j\u00e1 foi condenado a pagar uma multa de R$ 10 mil por ofensas disparadas contra a deputada. Gentili foi condenado pela 5.\u00aa Vara Federal Criminal de S\u00e3o Paulo. Em 2016, o apresentador do SBT publicou uma s\u00e9rie de tu\u00edtes chamando a deputada de \u201cfalsa\u201d, \u201cc\u00ednica\u201d e \u201cnojenta\u201d. E em outra ocasi\u00e3o, escreveu &#8216;deputada&#8217;, encobrindo as primeira e \u00faltima s\u00edlabas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro usou o Twitter nesta quinta, 11, para manifestar solidariedade ao apresentador Danilo Gentili, que na quarta-feira, 10, foi condenado a seis meses e 28 dias de pris\u00e3o em regime semiaberto por suposta inj\u00faria \u00e0 deputada federal Maria do Ros\u00e1rio (PT-RS). \u201cMe solidarizo com o apresentador e comediante Danilo Gentili ao exercer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-206737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206737"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206737\/revisions"}],"predecessor-version":[{"id":206743,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206737\/revisions\/206743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206739"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}