{"id":206909,"date":"2019-04-15T04:00:51","date_gmt":"2019-04-15T07:00:51","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=206909"},"modified":"2019-04-15T06:58:31","modified_gmt":"2019-04-15T09:58:31","slug":"affair-brasilinha-coloca-ibaneis-contra-a-parede","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/affair-brasilinha-coloca-ibaneis-contra-a-parede\/","title":{"rendered":"Affair Brasilinha coloca Ibaneis contra a parede"},"content":{"rendered":"<p>Um dos mais conhecidos secret\u00e1rios de Ibaneis Rocha, com acesso direto a influentes jornalistas de Bras\u00edlia, est\u00e1 prestes a chutar o pau da barraca.<\/p>\n<p>Diz que n\u00e3o aguenta mais ser tratado como coc\u00f4 do cavalo do bandido por Paulo Henrique Rodrigues Costa, presidente do Banco de Bras\u00edlia.<\/p>\n<p>Se decidir realmente pedir as contas, o secret\u00e1rio promete abrir a gaveta e distribuir c\u00f3pias do &#8216;V\u00eddeo de Brasilinha&#8217;. Quem conhece o material classifica como nitroglicerina pura.<\/p>\n<p>A possibilidade de o v\u00eddeo ser divulgado \u00e9 real. E pode derrubar toda a estrutura do Pal\u00e1cio do Buriti. Mas se o secret\u00e1rio for convencido a ficar, \u00e9 certo que cai o homem forte do BRB. E a filmagem volta para a gaveta.<\/p>\n<p>Esse filmete, que envolve pai e m\u00e3e decentes e seu filho arrimo de fam\u00edlia, seria usado na campanha eleitoral pelos ent\u00e3o candidatos ao Pal\u00e1cio do Buriti Eliana Pedrosa e Alberto Fraga, principais advers\u00e1rios do eleito Ibaneis Rocha.<\/p>\n<p>Quando a disputa era mais acirrada, os comandos das campanhas mudaram. E tanto Fraga como Eliana foram desaconselhados a usar a &#8216;arma letal&#8217; no \u00faltimo debate do primeiro turno. Motivo: o jogo seria muito sujo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos mais conhecidos secret\u00e1rios de Ibaneis Rocha, com acesso direto a influentes jornalistas de Bras\u00edlia, est\u00e1 prestes a chutar o pau da barraca. Diz que n\u00e3o aguenta mais ser tratado como coc\u00f4 do cavalo do bandido por Paulo Henrique Rodrigues Costa, presidente do Banco de Bras\u00edlia. Se decidir realmente pedir as contas, o secret\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-206909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=206909"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206909\/revisions"}],"predecessor-version":[{"id":206914,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/206909\/revisions\/206914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206910"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=206909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=206909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=206909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}