{"id":207032,"date":"2019-04-17T04:00:50","date_gmt":"2019-04-17T07:00:50","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207032"},"modified":"2019-04-19T15:08:05","modified_gmt":"2019-04-19T18:08:05","slug":"deputado-general-risca-o-pavio-de-polvora-para-a-cpi-da-lava-toga","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/deputado-general-risca-o-pavio-de-polvora-para-a-cpi-da-lava-toga\/","title":{"rendered":"Deputado-general risca pavio de p\u00f3lvora da CPI da Lava Toga"},"content":{"rendered":"<p>A censura imposta pelo Supremo Tribunal Federal a ve\u00edculos que publicaram mat\u00e9rias sobre supostas liga\u00e7\u00f5es do presidente da Corte, Dias Toffoli, com a Odebrecht, continuam repercutindo em Bras\u00edlia. Na noite desta ter\u00e7a, 16, o general-deputado Gir\u00e3o, do PSL potiguar, acendeu o pavio do barril de p\u00f3lvora na guerra que se trava em v\u00e1rias frentes contra o STF. A <strong>Notibras<\/strong>, ele defendeu a imediata instala\u00e7\u00e3o da CPI da Lava Toga para \u2018purificar\u2019 o Supremo. Essa \u2018purifica\u00e7\u00e3o\u2019, no caso, seria necess\u00e1ria para limpar os pecados e as manchas morais da Corte.<\/p>\n<p>Mais cedo, ao ocupar a tribuna da C\u00e2mara dos Deputados, o general Gir\u00e3o alertou que a democracia e o pr\u00f3prio Poder Judici\u00e1rio enfrentam fragilidades que merecem aten\u00e7\u00e3o e vigil\u00e2ncia especiais. E advertiu que o Brasil \u2018vive dias dif\u00edceis\u2019. O general-deputado atacou com firmeza a censura imposta pelo Supremo a meios de comunica\u00e7\u00e3o. \u201cFoi um gesto agressivo para tentar barrar investiga\u00e7\u00f5es contra seus membros (do STF)\u201d, acusou.<\/p>\n<p>Segundo o general-deputado, num Estado Democr\u00e1tico, o acusador n\u00e3o deve ser julgador. \u201cN\u00e3o por outro motivo, a instaura\u00e7\u00e3o do inqu\u00e9rito, com a designa\u00e7\u00e3o direta de relator, sem sorteio e sem consulta ao Plen\u00e1rio da Corte, foi criticada por membros do pr\u00f3prio STF\u201d, disse, citando a decis\u00e3o do presidente Dias Toffoli de apurar respons\u00e1veis por supostas fake news. Ao rasgar a pr\u00f3pria Constitui\u00e7\u00e3o, afirmou Gir\u00e3o, o STF pode estar se aproximando da figura de um tribunal de exce\u00e7\u00e3o, inclusive porque n\u00e3o foram acionados os competentes \u00f3rg\u00e3os de investiga\u00e7\u00e3o e de acusa\u00e7\u00e3o.<\/p>\n<p>O general Gir\u00e3o lembrou o artigo 220 da Constitui\u00e7\u00e3o, que garante \u201ca manifesta\u00e7\u00e3o do pensamento, a cria\u00e7\u00e3o, a express\u00e3o e a informa\u00e7\u00e3o, sob qualquer forma; processo ou ve\u00edculo n\u00e3o sofrer\u00e3o qualquer restri\u00e7\u00e3o\u201d. N\u00e3o bastasse isso, acrescentou, o texto constitucional impede \u201ctoda e qualquer censura de natureza pol\u00edtica, ideol\u00f3gica e art\u00edstica\u201d.<\/p>\n<p><strong>General Paulo Chagas<\/strong> &#8211; Depois dos ataques virulentos \u00e0 censura do Supremo aos meios de comunica\u00e7\u00e3o, Gir\u00e3o saiu em defesa do seu colega general Paulo Chagas, alvo de um gesto insano do ministro Alexandre de Moraes. \u201cAlegando propaganda de processos violentos ou ilegais para a altera\u00e7\u00e3o da ordem pol\u00edtica e social\u201d, disse o deputado, foram determinadas \u00e0 Pol\u00edcia Federal buscas a apreens\u00f5es na resid\u00eancia de Paulo Chagas, em \u00c1guas Claras, bairro de Bras\u00edlia.<\/p>\n<p>Na opini\u00e3o do deputado-general Gir\u00e3o, o Supremo recorreu a um ato de for\u00e7a \u201ccontra cidad\u00e3os que est\u00e3o sendo constrangidos por professarem a livre manifesta\u00e7\u00e3o e express\u00e3o do pensamento\u201d. Depois, pontuou: \u201cN\u00e3o posso, na qualidade de homem p\u00fablico, de legislador, de conhecedor que sou do meu amigo Paulo Chagas, acreditar que ele tenha cometido algo que justifique uma agress\u00e3o (invas\u00e3o de sua resid\u00eancia) dessa natureza\u201d.<\/p>\n<p>Sem medir palavras, o deputado-general disse estar acompanhando com lupa as manifesta\u00e7\u00f5es populares pedindo que seja instaurada, no \u00e2mbito do Senado Federal, investiga\u00e7\u00e3o para apurar irregularidades e ilegalidades possivelmente cometidas por integrantes do Supremo Tribunal Federal. Segundo ele, a j\u00e1 apelidada \u201cCPI da Lava Toga\u201d tem o n\u00famero suficiente de assinaturas de senadores. Por essas e por outras, disse, enf\u00e1tico, essa investiga\u00e7\u00e3o deveria ser apoiada por todos os que nada temem, por nada terem feito de errado, a come\u00e7ar pelos pr\u00f3prios ministros do STF.<\/p>\n<p>&#8211; Pode anotar a\u00ed, advertiu Gir\u00e3o. Mais cedo ou mais tarde, o que se espera \u00e9 que as verdades venham \u00e0 tona, que o \u00f3rg\u00e3o m\u00e1ximo do judici\u00e1rio nacional seja purificado e que o Estado Democr\u00e1tico de Direito prevale\u00e7a sobre todas e quaisquer arbitrariedades\u201d. Depois, encerrando, citou Rui Barbosa: \u201cA pior ditadura \u00e9 a do Poder Judici\u00e1rio. Contra ela, n\u00e3o h\u00e1 a quem recorrer\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A censura imposta pelo Supremo Tribunal Federal a ve\u00edculos que publicaram mat\u00e9rias sobre supostas liga\u00e7\u00f5es do presidente da Corte, Dias Toffoli, com a Odebrecht, continuam repercutindo em Bras\u00edlia. Na noite desta ter\u00e7a, 16, o general-deputado Gir\u00e3o, do PSL potiguar, acendeu o pavio do barril de p\u00f3lvora na guerra que se trava em v\u00e1rias frentes contra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-207032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207032"}],"version-history":[{"count":7,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207032\/revisions"}],"predecessor-version":[{"id":207145,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207032\/revisions\/207145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207033"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}