{"id":207092,"date":"2019-04-18T00:19:59","date_gmt":"2019-04-18T03:19:59","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207092"},"modified":"2019-04-18T08:24:30","modified_gmt":"2019-04-18T11:24:30","slug":"perseguicao-de-ibaneis-deixa-sem-teto-irado","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/perseguicao-de-ibaneis-deixa-sem-teto-irado\/","title":{"rendered":"Persegui\u00e7\u00e3o de Ibaneis deixa sem-teto irado"},"content":{"rendered":"<p>O direito \u00e0 moradia digna e o combate \u00e0s remo\u00e7\u00f5es violentas em ocupa\u00e7\u00f5es foram temas em debate durante audi\u00eancia p\u00fablica da Comiss\u00e3o de Defesa dos Direitos Humanos, Cidadania, \u00c9tica e Decoro Parlamentar na manh\u00e3 desta quarta-feira (17). O presidente da comiss\u00e3o, deputado F\u00e1bio Felix (PSOL), mediou o encontro que reuniu ativistas, integrantes de movimentos sociais e representantes do Executivo no plen\u00e1rio.<\/p>\n<p>Pol\u00edticas p\u00fablicas habitacionais &#8220;voltadas \u00e0s pessoas e n\u00e3o ao lucro&#8221; foi a defesa de Felix, ao considerar que moradia digna envolve infraestrutura e concep\u00e7\u00e3o de cidade, com equipamentos p\u00fablicos, como escolas, postos de sa\u00fade, espa\u00e7os de lazer e conv\u00edvio, entre outros. Ainda de acordo com o parlamentar, o d\u00e9ficit habitacional hoje no DF gira em torno de 120 mil moradias. Essa situa\u00e7\u00e3o se resolve, segundo Felix, &#8220;com pol\u00edtica p\u00fablica e n\u00e3o com bala de borracha&#8221;.<\/p>\n<p>Outros parlamentares tamb\u00e9m destacaram a fun\u00e7\u00e3o social da cidade e se opuseram \u00e0 remo\u00e7\u00e3o for\u00e7ada, como os deputados Leandro Grass (Rede) e Arlete Sampaio (PT). &#8220;O crescimento da cidade de forma ordenada e planejada&#8221; \u00e9 o principal desafio atual, na opini\u00e3o de Grass, que elencou elementos desse processo, como a preserva\u00e7\u00e3o ambiental e a\u00e7\u00f5es para combater a grilagem e preservar a dignidade das pessoas.<\/p>\n<p>&#8220;N\u00e3o existe invas\u00e3o de terra, mas falta de moradia&#8221;, frisou Arlete Sampaio. A parlamentar lembrou que, neste ano, haver\u00e1 a revis\u00e3o do Plano Diretor de Ordenamento Territorial (PDOT), momento oportuno para trazer o direito \u00e0 moradia ao centro das discuss\u00f5es.<\/p>\n<p><strong>Remo\u00e7\u00f5es<\/strong> \u2013 Moradores de ocupa\u00e7\u00f5es protestaram contra as a\u00e7\u00f5es de remo\u00e7\u00e3o da Ag\u00eancia de Fiscaliza\u00e7\u00e3o do Distrito Federal (Agefis), como a representante de Santa Luzia, na Estrutural, Meire Paulina. Ela contou que no local houve &#8220;onze opera\u00e7\u00f5es, algumas bem truculentas&#8221; desde 2017, quando teve in\u00edcio o processo. &#8220;Se l\u00e1 n\u00e3o pode ficar, leva (sic) a gente para outro lugar, o que a gente quer \u00e9 moradia digna&#8221;, disse.<\/p>\n<p>&#8220;Direito n\u00e3o se mendiga, direito se exige&#8221;, manifestaram integrantes do Movimento dos Trabalhadores Sem Teto presentes no encontro. &#8220;N\u00e3o \u00e9 poss\u00edvel que Bras\u00edlia tenha a maior \u00e1rea p\u00fablica do Pa\u00eds e o maior d\u00e9ficit habitacional&#8221;, protestou a representante do MTST, Maria Jos\u00e9 Almeida. Aplaudida pelos participantes, ela acrescentou: &#8220;Queremos moradia concreta e papel n\u00e3o \u00e9 moradia&#8221;, em refer\u00eancia aos programas habitacionais prometidos pelo governo.<\/p>\n<p><strong>Participa\u00e7\u00e3o efetiva<\/strong> \u2013 A disposi\u00e7\u00e3o do atual governo \u00e9 regularizar ao inv\u00e9s de &#8220;passar o trator&#8221;, garantiu o secret\u00e1rio de Desenvolvimento Urbano e Habita\u00e7\u00e3o do DF, Mateus Leandro de Oliveira, que considera o direito \u00e0 moradia como um dos pilares do direito urban\u00edstico. &#8220;Vamos ouvir a popula\u00e7\u00e3o&#8221; para assegurar a &#8220;participa\u00e7\u00e3o efetiva&#8221;, prometeu o secret\u00e1rio.<\/p>\n<p>De acordo com Oliveira, aquela Secretaria, a Companhia Imobili\u00e1ria de Bras\u00edlia &#8211; Terracap e a Companhia de Desenvolvimento Habitacional do Distrito Federal (Codhab) precisam trabalhar juntos. Ele chamou a aten\u00e7\u00e3o para \u00e1reas n\u00e3o regulariz\u00e1veis por crit\u00e9rios ambientais, fruto de decis\u00f5es judiciais, a exemplo da ocupa\u00e7\u00e3o de Santa Luzia. Contudo, ele considerou que &#8220;nada justifica remo\u00e7\u00f5es com viola\u00e7\u00e3o de direitos humanos&#8221;.<\/p>\n<p>As quest\u00f5es ambiental e social devem estar atreladas nas pol\u00edticas habitacionais, avaliou a coordenadora do BR Cidades, Liza Andrade. Professora de Arquitetura da Universidade de Bras\u00edlia (UnB), ela citou que chegam a Bras\u00edlia cerca de 60 mil pessoas por ano. Como vamos resolver isso?, indagou, ao ponderar a quest\u00e3o diante de desafios como a escassez dos mananciais d&#8217;\u00e1gua. A professora alertou que \u00e9 preciso &#8220;incluir a popula\u00e7\u00e3o nos projetos da Terracap&#8221; e acredita ser vi\u00e1vel inserir &#8220;popula\u00e7\u00f5es pobres em \u00e1reas nobres&#8221; das cidades, como fez Barcelona (Espanha) por meio de a\u00e7\u00f5es de planejamento urban\u00edstico.<\/p>\n<p>A origem e o planejamento da cidade devem estar no epicentro do debate, segundo o presidente do Conselho de Arquitetura e Urbanismo do DF, Daniel Mangabeira. &#8221; Na semana passada participamos da entrega de trinta moradias no Sol Nascente; o trabalho \u00e9 bel\u00edssimo, mas \u00e9 uma gota no oceano&#8221;, assumiu. Ele defendeu a realiza\u00e7\u00e3o de concursos de arquitetura na \u00e1rea de habita\u00e7\u00e3o coletiva popular. &#8220;O concurso p\u00fablico \u00e9 garantia de qualidade de projeto&#8221;, considerou, ao acrescentar que &#8220;uma boa cidade come\u00e7a com um bom projeto&#8221;. Ainda durante a audi\u00eancia foram discutidas quest\u00f5es tangentes \u00e0 fun\u00e7\u00e3o social da cidade, como a mobilidade urbana e a acessibilidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O direito \u00e0 moradia digna e o combate \u00e0s remo\u00e7\u00f5es violentas em ocupa\u00e7\u00f5es foram temas em debate durante audi\u00eancia p\u00fablica da Comiss\u00e3o de Defesa dos Direitos Humanos, Cidadania, \u00c9tica e Decoro Parlamentar na manh\u00e3 desta quarta-feira (17). O presidente da comiss\u00e3o, deputado F\u00e1bio Felix (PSOL), mediou o encontro que reuniu ativistas, integrantes de movimentos sociais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-207092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207092"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207092\/revisions"}],"predecessor-version":[{"id":207095,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207092\/revisions\/207095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207094"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}