{"id":207148,"date":"2019-04-19T19:50:42","date_gmt":"2019-04-19T22:50:42","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207148"},"modified":"2019-04-19T19:56:01","modified_gmt":"2019-04-19T22:56:01","slug":"trump-quer-vetar-ajuda-dos-russos-para-a-venezuela","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/trump-quer-vetar-ajuda-dos-russos-para-a-venezuela\/","title":{"rendered":"Trump quer vetar ajuda dos russos para a Venezuela"},"content":{"rendered":"<p>Os EUA pediram \u00e0 comunidade internacional que negue aos avi\u00f5es russos que voam para a Venezuela o direito de passagem atrav\u00e9s de seu espa\u00e7o a\u00e9reo. O primeiro a acatar a orienta\u00e7\u00e3o foi Malta, que mandou dois avi\u00f5es de combate escoltarem um cargueiro russo, que se destinava a Caracas, para fora do seu espa\u00e7o a\u00e9reo.<\/p>\n<p>A porta-voz do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores da R\u00fassia, Maria Zakharova, denunciou o incidente nesta sexta, 19. Segundo ela, Malta n\u00e3o forneceu nenhum motivo para negar o sobrevoo de avi\u00f5es russos. Ela deixou claro que Moscou levar\u00e1 esse fato em considera\u00e7\u00e3o em suas rela\u00e7\u00f5es bilaterais com a na\u00e7\u00e3o insular.<\/p>\n<p>A Venezuela foi engolida por uma crise pol\u00edtica, que tomou outro rumo ap\u00f3s a figura da oposi\u00e7\u00e3o, Juan Guaid\u00f3 proclamou-se presidente interino do pa\u00eds. A medida foi imediatamente apoiada pelos Estados Unidos e pela maioria dos estados ocidentais, mas foi duramente criticada pela R\u00fassia, Turquia, China, Ir\u00e3 e muitos outros pa\u00edses. Eles expressaram seu apoio ao presidente constitucionalmente eleito Nicol\u00e1s Maduro.<\/p>\n<p>Washington criticou o apoio de Moscou ao presidente e especificamente a chegada de avi\u00f5es russos que transportavam militares no m\u00eas passado. Os EUA chamaram a presen\u00e7a desse grupo russo de &#8220;provoca\u00e7\u00e3o indesejada&#8221;. Ao mesmo tempo, Moscou disse que seu pessoal militar estava em Caracas para realizar a manuten\u00e7\u00e3o da tecnologia militar russa sob um acordo bilateral com Caracas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os EUA pediram \u00e0 comunidade internacional que negue aos avi\u00f5es russos que voam para a Venezuela o direito de passagem atrav\u00e9s de seu espa\u00e7o a\u00e9reo. O primeiro a acatar a orienta\u00e7\u00e3o foi Malta, que mandou dois avi\u00f5es de combate escoltarem um cargueiro russo, que se destinava a Caracas, para fora do seu espa\u00e7o a\u00e9reo. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[95],"class_list":["post-207148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207148"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207148\/revisions"}],"predecessor-version":[{"id":207153,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207148\/revisions\/207153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207149"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}