{"id":207283,"date":"2019-04-22T10:20:25","date_gmt":"2019-04-22T13:20:25","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207283"},"modified":"2019-04-22T10:23:30","modified_gmt":"2019-04-22T13:23:30","slug":"caminhoneiros-fazem-planalto-ligar-sinal-de-alerta-maximo","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/caminhoneiros-fazem-planalto-ligar-sinal-de-alerta-maximo\/","title":{"rendered":"Caminhoneiros fazem Planalto ligar sinal de alerta m\u00e1ximo"},"content":{"rendered":"<p>Relat\u00f3rios reservados est\u00e3o sendo despejados na Presid\u00eancia da Rep\u00fablica como \u00e1gua em cachoeira. Ganharam intensidade desde a semana passada, quando a Petrobras anunciou um novo reajuste no pre\u00e7o do \u00f3leo diesel.<\/p>\n<p>A causa de toda essa preocupa\u00e7\u00e3o s\u00e3o os caminhoneiros. Diferentes grupos de WhatsApp da categoria est\u00e3o sendo monitorados. O Pal\u00e1cio do Planalto ligou o sinal verde por temer uma greve na segunda, 29, antev\u00e9spera o feriado de 1\u00ba de Maio.<\/p>\n<p>Nas \u00e1reas de seguran\u00e7a, informa\u00e7\u00e3o e intelig\u00eancia o movimento \u00e9 grande. Os ministros S\u00e9rgio Moro (Justi\u00e7a), Augusto Heleno (Gabinete de Seguran\u00e7a Institucional) e Santos Cruz (Secretaria de Governo) est\u00e3o em contato permanente.<\/p>\n<p>Esses tr\u00eas ministros s\u00e3o respons\u00e1veis, respectivamente, pela Pol\u00edcia Federal, For\u00e7a Nacional e Pol\u00edcia Rodovi\u00e1ria Federal; estrat\u00e9gia de defesa e contrainforma\u00e7\u00e3o; e, rela\u00e7\u00e3o com as organiza\u00e7\u00f5es sociais.<\/p>\n<p>A orienta\u00e7\u00e3o do presidente Jair Bolsonaro \u00e9 evitar uma greve a qualquer custo. Teme-se no Pal\u00e1cio do Planalto que, se bem organizados, os caminhoneiros podem provocar preju\u00edzo igual ou superior ao registrado no movimento que colocou o Brasil de cabe\u00e7a para baixo no ano passado.<\/p>\n<p>Nesta segunda, 22, havia duas informa\u00e7\u00f5es pontuais circulando entre os poderes da Rep\u00fablica: 1) O general Santos Cruz avalia que o quadro \u00e9 delicado. Admite que os caminhoneiros est\u00e3o insatisfeitos e que o governo se v\u00ea entre a cruz e a espada; 2) Wanderlei Alvez, conhecido como Dedeco, estaria insuflando seus colegas a pararem por 24 horas, como forma de aviso ao governo. O argumento \u00e9 de que n\u00e3o s\u00e3o ouvidos pelas autoridades, que preferem tratar com grupos patronais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relat\u00f3rios reservados est\u00e3o sendo despejados na Presid\u00eancia da Rep\u00fablica como \u00e1gua em cachoeira. Ganharam intensidade desde a semana passada, quando a Petrobras anunciou um novo reajuste no pre\u00e7o do \u00f3leo diesel. A causa de toda essa preocupa\u00e7\u00e3o s\u00e3o os caminhoneiros. Diferentes grupos de WhatsApp da categoria est\u00e3o sendo monitorados. O Pal\u00e1cio do Planalto ligou o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":180489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-207283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207283"}],"version-history":[{"count":5,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207283\/revisions"}],"predecessor-version":[{"id":207288,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207283\/revisions\/207288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/180489"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}