{"id":207408,"date":"2019-04-25T00:19:01","date_gmt":"2019-04-25T03:19:01","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207408"},"modified":"2019-04-25T07:22:44","modified_gmt":"2019-04-25T10:22:44","slug":"china-adverte-franca-por-presenca-de-navios-de-guerra","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/china-adverte-franca-por-presenca-de-navios-de-guerra\/","title":{"rendered":"China adverte Fran\u00e7a por presen\u00e7a de navios de guerra"},"content":{"rendered":"<p>A Marinha chinesa alertou um navio de guerra franc\u00eas que entrou no estreito de Taiwan no in\u00edcio deste m\u00eas, disse Pequim na quinta-feira, acrescentando que apresentou um protesto oficial a Paris por causa da mudan\u00e7a.<\/p>\n<p>De acordo com o Minist\u00e9rio da Defesa chin\u00eas, o navio de guerra franc\u00eas \u201centrou ilegalmente nas \u00e1guas territoriais da China\u201d em 7 de abril.<\/p>\n<p>Isso ocorre depois que o Minist\u00e9rio de Defesa Nacional de Taiwan (MND) disse no come\u00e7o do m\u00eas que dois ca\u00e7as chineses J-11 cruzaram a &#8220;linha mediana&#8221; do Estreito de Taiwan em 31 de mar\u00e7o, levando Taipei a embaralhar v\u00e1rias aeronaves para interceptar os avi\u00f5es.<\/p>\n<p>Al\u00e9m disso, a passagem do navio de guerra franc\u00eas em 7 de abril acontece em meio a passagens regulares de navios da Marinha dos EUA atrav\u00e9s da hidrovia estrat\u00e9gica. No final de mar\u00e7o, a s\u00e9tima frota da Marinha dos EUA disse em comunicado que havia enviado o destr\u00f3ier naval USS Curtis Wilbur e Bertholf, da Guarda Costeira, atrav\u00e9s do Estreito de Taiwan.<\/p>\n<p>A declara\u00e7\u00e3o apontou que os navios \u201crealizaram um tr\u00e2nsito rotineiro do Estreito de Taiwan [em] de 24 a 25 de mar\u00e7o (hor\u00e1rio local) de acordo com o direito internacional\u201d.<\/p>\n<p>Pequim fez uma representa\u00e7\u00e3o para Washington sobre a passagem dos navios de guerra dos EUA, disse o porta-voz do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores da China, Geng Shuang.<\/p>\n<p>Ele acrescentou que Pequim insta os EUA a &#8220;honrarem a pol\u00edtica &#8216;One China&#8217; e tr\u00eas comunicados conjuntos entre chineses e americanos [sobre o assunto] e serem prudentes sobre a quest\u00e3o de Taiwan, a fim de evitar a deteriora\u00e7\u00e3o das rela\u00e7\u00f5es entre Pequim e Washington ea paz e estabilidade no Estreito de Taiwan \u201d.<\/p>\n<p>Os EUA intensificaram as miss\u00f5es de patrulha no Estreito de Taiwan desde o ver\u00e3o de 2018. No final de janeiro de 2019, Washington enviou o destr\u00f3ier de m\u00edsseis guiados USS McCampbell e o petroleiro de reabastecimento da frota USNS Walter S. Diehl para &#8220;demonstrar o compromisso dos EUA com um gratuito e aberto Indo-Pacifico&#8221;, como comentou o porta-voz Tim Gorman.<\/p>\n<p>A passagem de navios de guerra dos EUA ocorre em meio a tens\u00f5es entre Washington e Pequim, enquanto os dois permanecem engajados no processo de negocia\u00e7\u00e3o de um acordo comercial.<\/p>\n<p>O Estreito de Taiwan divide Taiwan da China continental. Pequim considera Taiwan como parte de uma China unida. As rela\u00e7\u00f5es entre os dois lados foram cortadas em 1949, depois que os remanescentes das for\u00e7as de Chiang Kai-shek fugiram para a ilha ap\u00f3s sua derrota no continente. Os la\u00e7os foram parcialmente restaurados nos anos 80.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Marinha chinesa alertou um navio de guerra franc\u00eas que entrou no estreito de Taiwan no in\u00edcio deste m\u00eas, disse Pequim na quinta-feira, acrescentando que apresentou um protesto oficial a Paris por causa da mudan\u00e7a. De acordo com o Minist\u00e9rio da Defesa chin\u00eas, o navio de guerra franc\u00eas \u201centrou ilegalmente nas \u00e1guas territoriais da China\u201d [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-207408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207408"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207408\/revisions"}],"predecessor-version":[{"id":207410,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207408\/revisions\/207410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207409"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}