{"id":207709,"date":"2019-05-04T00:40:36","date_gmt":"2019-05-04T03:40:36","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207709"},"modified":"2019-05-04T08:43:45","modified_gmt":"2019-05-04T11:43:45","slug":"agricultura-quer-incrementar-negocios-com-o-oriente","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/agricultura-quer-incrementar-negocios-com-o-oriente\/","title":{"rendered":"Agricultura quer incrementar neg\u00f3cios com o Oriente"},"content":{"rendered":"<p>A ministra Tereza Cristina (Agricultura, Pecu\u00e1ria e Abastecimento) vai liderar uma comitiva de 98 pessoas em viagem a quatro pa\u00edses do Oriente: Jap\u00e3o, China, Vietn\u00e3 e Indon\u00e9sia. A viagem, de 16 dias, come\u00e7a na segunda (6).<\/p>\n<p>Segundo dados do Minist\u00e9rio da Economia (Comex Vis), o Brasil mant\u00e9m com os quatro parceiros comerciais uma pauta de exporta\u00e7\u00e3o concentrada em produtos b\u00e1sicos como a soja triturada (China e Vietn\u00e3); trigo em gr\u00e3os (Indon\u00e9sia); carne de frango (Jap\u00e3o); algod\u00e3o (Indon\u00e9sia e Vietn\u00e3); caf\u00e9 (Jap\u00e3o); farelo e res\u00edduos de \u00f3leo de soja (Indon\u00e9sia).<\/p>\n<p>As visitas aos pa\u00edses asi\u00e1ticos ocorrem em momento de riscos e oportunidades comerciais, sobretudo com a China, nosso principal parceiro (35% das exporta\u00e7\u00f5es em 2018). O Brasil acompanha os desdobramentos de acordo comercial entre os Estados Unidos e a China, que pode aquecer a economia global e a demanda por alimentos.<\/p>\n<p>O eventual acordo suspenderia a guerra comercial iniciada no ano passado pelos dois pa\u00edses, por\u00e9m, pode reduzir a compra de soja brasileira pela China, porque o acerto dever\u00e1 derrubar a cobran\u00e7a de tarifas nas exporta\u00e7\u00f5es da soja norte-americana ao mercado chin\u00eas e, assim, afetar as exporta\u00e7\u00f5es brasileiras. \u201cAs coisas nesse mercado n\u00e3o s\u00e3o simplistas e nem para amadores\u201d, disse Tereza Cristina em entrevista coletiva nesta sexta-feira em Bras\u00edlia.<\/p>\n<p>No primeiro trimestre de 2019, as vendas de soja triturada do Brasil para China (US$ 4,75 bilh\u00f5es) corresponderam a 9% do valor arrecadado com o total de exporta\u00e7\u00f5es (US$ 52,6 bilh\u00f5es). No per\u00edodo, de cada US$ 100 que o pa\u00eds captou com a venda do produto em todo o mundo, US$ 77,48 vieram da China.<\/p>\n<p>Al\u00e9m do armist\u00edcio comercial entre americanos e chineses, o Brasil pode ser afetado com a chamada peste su\u00edna africana, um v\u00edrus que tem dizimado o rebanho de porcos da China, principal consumidora de carne su\u00edna do mundo. A morte dos porcos, alimentado com soja e milho, pode diminuir a procura pelos produtos brasileiros.<\/p>\n<p>A redu\u00e7\u00e3o do rebanho, por outro lado, tende a aumentar o pre\u00e7o da carne su\u00edna no mercado internacional e criar demanda para frigor\u00edficos e fabricantes brasileiros. \u201c\u00c9 um mercado que se abre\u201d, prev\u00ea a ministra.<\/p>\n<p>\u201cO Brasil todo pode se beneficiar. O que n\u00f3s temos que fazer \u00e9 ir l\u00e1 e garantir a qualidade de nossos produtos. Depois, tem toda rela\u00e7\u00e3o comercial que n\u00e3o \u00e9 o Minist\u00e9rio da Agricultura. Ai vai ser entre os privados, as empresas brasileiras e os exportadores chineses\u201d, disse.<\/p>\n<p>Tereza Cristina tem como expectativa de viagem conversar com autoridades sanit\u00e1rias da China sobre a habilita\u00e7\u00e3o de novos frigor\u00edficos e fabricantes para exporta\u00e7\u00e3o de carne su\u00edna, bovina, asinina (de burro) e de aves. Segundo o minist\u00e9rio, o Brasil tem 79 plantas de fornecedores com perspectiva de serem habilitadas para exportar para a China.<\/p>\n<p>Outra possibilidade da viagem \u00e9 estimular empres\u00e1rios da China e do Jap\u00e3o quanto \u00e0 possibilidade de investimento em obras de infraestrutura e log\u00edstica para escoamento da produ\u00e7\u00e3o agropecu\u00e1ria no Brasil. \u201cSomos competitivos da porteira para dentro\u201d, disse Tereza Cristina, que n\u00e3o vai levar nenhum projeto espec\u00edfico aos pa\u00edses orientais.<\/p>\n<p>Indagada por jornalistas sobre o direito de leg\u00edtima de defesa contra ocupa\u00e7\u00e3o de terras, proposta que tem o apoio do presidente Jair Bolsonaro, a ministra manifestou concord\u00e2ncia. \u201cEu concordo que devamos fazer a defesa leg\u00edtima da propriedade sim. Por que uns t\u00eam o direito de invadir e voc\u00ea que est\u00e1 l\u00e1 dentro n\u00e3o tem o direito de se defender?\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ministra Tereza Cristina (Agricultura, Pecu\u00e1ria e Abastecimento) vai liderar uma comitiva de 98 pessoas em viagem a quatro pa\u00edses do Oriente: Jap\u00e3o, China, Vietn\u00e3 e Indon\u00e9sia. A viagem, de 16 dias, come\u00e7a na segunda (6). Segundo dados do Minist\u00e9rio da Economia (Comex Vis), o Brasil mant\u00e9m com os quatro parceiros comerciais uma pauta de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-207709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207709"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207709\/revisions"}],"predecessor-version":[{"id":207711,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207709\/revisions\/207711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207710"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}