{"id":207863,"date":"2019-05-07T23:13:58","date_gmt":"2019-05-08T02:13:58","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207863"},"modified":"2019-05-07T23:56:26","modified_gmt":"2019-05-08T02:56:26","slug":"terreiro-reune-politicos-com-cachaca-do-piaui","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/terreiro-reune-politicos-com-cachaca-do-piaui\/","title":{"rendered":"Terreiro re\u00fane pol\u00edticos com cacha\u00e7a do Piau\u00ed"},"content":{"rendered":"<p>Pol\u00edticos de Bras\u00edlia est\u00e3o se reunindo a cada 15 dias em um terreiro de macumba na regi\u00e3o rural do Parano\u00e1. Quem garante s\u00e3o testemunhas oculares, entre as quais influentes advogados.<\/p>\n<p>Em noites de Lua crescente, bebem cacha\u00e7a despachada do Vale de S\u00e3o Vicente, em Inhuma, no saudoso Piau\u00ed; fumam um Bom Baiano e se lambuzam com galinha preta.<\/p>\n<p>Quando \u00e9 Lua cheia, o quadro muda. O charuto tem o selo Cohiba, um fais\u00e3o dourado \u00e9 posto na mesa e as ta\u00e7as s\u00e3o enchidas com Ch\u00e2teau Margaux.<\/p>\n<p>Em comum, nessas ocasi\u00f5es &#8211; ainda segundo pessoas que presenciaram as reuni\u00f5es -, \u00e9 que a baiana roda literalmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edticos de Bras\u00edlia est\u00e3o se reunindo a cada 15 dias em um terreiro de macumba na regi\u00e3o rural do Parano\u00e1. Quem garante s\u00e3o testemunhas oculares, entre as quais influentes advogados. Em noites de Lua crescente, bebem cacha\u00e7a despachada do Vale de S\u00e3o Vicente, em Inhuma, no saudoso Piau\u00ed; fumam um Bom Baiano e se lambuzam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-207863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207863"}],"version-history":[{"count":5,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207863\/revisions"}],"predecessor-version":[{"id":207870,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207863\/revisions\/207870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207864"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}