{"id":207882,"date":"2019-05-08T10:40:48","date_gmt":"2019-05-08T13:40:48","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207882"},"modified":"2019-05-08T12:54:15","modified_gmt":"2019-05-08T15:54:15","slug":"porte-de-arma-fica-mais-facil-para-politicos-jornalistas-etc","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/porte-de-arma-fica-mais-facil-para-politicos-jornalistas-etc\/","title":{"rendered":"Porte de arma fica mais f\u00e1cil para pol\u00edticos, jornalistas etc"},"content":{"rendered":"<p>Jornalistas, pol\u00edticos, fazendeiros, algumas categorias de profissionais liberais e caminhoneiros est\u00e3o no grupo de pessoas que ter\u00e3o facilitada o porte de armas. O decreto 9.785 do presidente Jair Bolsonaro, anunciado na ter\u00e7a-feira, 7, foi publicado nesta quarta-feira, 8, no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p>O item do decreto que disciplina o porte de armas de fogo diz que a libera\u00e7\u00e3o ser\u00e1 expedida pela Pol\u00edcia Federal, \u00e9 pessoal, intransfer\u00edvel, ter\u00e1 validade no territ\u00f3rio nacional e garantir\u00e1 o direito de portar consigo qualquer arma de fogo, acess\u00f3rio ou muni\u00e7\u00e3o do acervo do interessado com registro v\u00e1lido nos sistemas do governo por meio da apresenta\u00e7\u00e3o do documento de identifica\u00e7\u00e3o do portador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornalistas, pol\u00edticos, fazendeiros, algumas categorias de profissionais liberais e caminhoneiros est\u00e3o no grupo de pessoas que ter\u00e3o facilitada o porte de armas. O decreto 9.785 do presidente Jair Bolsonaro, anunciado na ter\u00e7a-feira, 7, foi publicado nesta quarta-feira, 8, no Di\u00e1rio Oficial da Uni\u00e3o. O item do decreto que disciplina o porte de armas de fogo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-207882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207882"}],"version-history":[{"count":6,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207882\/revisions"}],"predecessor-version":[{"id":207889,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207882\/revisions\/207889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207883"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}