{"id":207917,"date":"2019-05-09T07:02:39","date_gmt":"2019-05-09T10:02:39","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207917"},"modified":"2019-05-09T07:04:09","modified_gmt":"2019-05-09T10:04:09","slug":"povo-quer-mudar-previdencia-mas-com-ressalvas","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/povo-quer-mudar-previdencia-mas-com-ressalvas\/","title":{"rendered":"Nova Previd\u00eancia \u00e9 boa, mas com ressalvas"},"content":{"rendered":"<p>Pesquisa divulgada pela Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) aponta que 59% dos entrevistados reconhecem que \u00e9 preciso reformar a Previd\u00eancia, e que 72% concordam que deve ser estabelecida uma idade m\u00ednima para a aposentadoria.<\/p>\n<p>Embora a maioria dos entrevistados concorde com a ado\u00e7\u00e3o de uma idade m\u00ednima, \u00e9 grande a parcela dos que defendem aposentadoria em idades muito baixas. Para 80% das pessoas ouvidas, a aposentadoria deveria ocorrer com 60 anos ou menos. Os que acreditam que a aposentadoria deveria ocorrer a partir dos 61 anos s\u00e3o 19%.<\/p>\n<p>A pesquisa Retratos da Sociedade Brasileira \u2013 Reforma da Previd\u00eancia mostra que apesar de mais da metade dos entrevistados reconhecer que \u00e9 preciso mudar as regras da Previd\u00eancia, os brasileiros n\u00e3o est\u00e3o bem-informados sobre a atual proposta de reforma.<\/p>\n<p>De acordo com a pesquisa, apenas 36% responderam ter conhecimento amplo ou conhecer os principais pontos do texto, que est\u00e1 em discuss\u00e3o no Congresso Nacional. Entre os que dizem conhecer a atual proposta, 51% s\u00e3o contra e 39% s\u00e3o a favor a proposta.<\/p>\n<p>O levantamento mostra ainda que 63% dos homens s\u00e3o mais favor\u00e1veis a reformar a Previd\u00eancia, enquanto o percentual entre as mulheres \u00e9 de 54%. Entre os que t\u00eam renda familiar acima dos cinco sal\u00e1rios m\u00ednimos, 73% avaliam que \u00e9 necess\u00e1rio fazer mudan\u00e7as nas regras da previd\u00eancia. Entre aqueles que recebem at\u00e9 um sal\u00e1rio m\u00ednimo, 51% acreditam que o sistema precisa mudar.<\/p>\n<p>Para 33% dos entrevistados, as regras da Previd\u00eancia deveriam mudar apenas para quem ainda n\u00e3o contribui para o sistema, e 26% concordam que o sistema deve mudar para quem j\u00e1 contribui, mas ainda n\u00e3o se aposentou.<\/p>\n<p>Os dados mostram que 77% acreditam que \u00e9 dever da sociedade garantir um sal\u00e1rio m\u00ednimo a todos os idosos de baixa renda, inclusive \u00e0queles que nunca contribu\u00edram para a Previd\u00eancia.<\/p>\n<p>Perguntados se estariam dispostos a pagar mais impostos para manter as atuais regras da previd\u00eancia, 83% responderam que n\u00e3o.<\/p>\n<p>A pesquisa foi feita em parceria com o Ibope Intelig\u00eancia. Foram ouvidas 2 mil pessoas em 126 munic\u00edpios entre os dias 12 e 15 de abril. A margem de erro \u00e9 de 2 pontos percentuais e o grau de confian\u00e7a \u00e9 de 95%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa divulgada pela Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) aponta que 59% dos entrevistados reconhecem que \u00e9 preciso reformar a Previd\u00eancia, e que 72% concordam que deve ser estabelecida uma idade m\u00ednima para a aposentadoria. Embora a maioria dos entrevistados concorde com a ado\u00e7\u00e3o de uma idade m\u00ednima, \u00e9 grande a parcela dos que defendem aposentadoria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":207918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-207917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207917"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207917\/revisions"}],"predecessor-version":[{"id":207921,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207917\/revisions\/207921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/207918"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}