{"id":207972,"date":"2019-05-10T07:52:38","date_gmt":"2019-05-10T10:52:38","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=207972"},"modified":"2019-05-10T07:52:38","modified_gmt":"2019-05-10T10:52:38","slug":"toma-la-da-ca-entra-no-jogo-da-nova-previdencia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/toma-la-da-ca-entra-no-jogo-da-nova-previdencia\/","title":{"rendered":"Toma l\u00e1-d\u00e1-c\u00e1 entra no jogo da Nova Previd\u00eancia"},"content":{"rendered":"<p>A t\u00e3o condenada pol\u00edtica do \u201ctoma l\u00e1-d\u00e1-c\u00e1\u201d, que Jair Bolsonaro, na campanha eleitoral, prometeu varrer do cen\u00e1rio nacional, caminha para ser usada pelo pr\u00f3prio presidente da Rep\u00fablica como arma para salvar a reforma da Previd\u00eancia.<\/p>\n<p>Com s\u00e9rias dificuldades para aprova\u00e7\u00e3o da Nova Previd\u00eancia sem sofrer uma ampla desidrata\u00e7\u00e3o, o Pal\u00e1cio do Planalto aceita a recria\u00e7\u00e3o dos minist\u00e9rios da Integra\u00e7\u00e3o Nacional e Cidades. Eles ser\u00e3o ocupados por pol\u00edticos indicados pelo Centr\u00e3o.<\/p>\n<p>As legendas do Centr\u00e3o (MDB, PSDB, DEM, PSD, PR, PP, PPS, Solidariedade e PTB) foram as que mais sofreram derrotas nas elei\u00e7\u00f5es de outubro. Elas se agruparam e passaram a ser a maior for\u00e7a politica tanto na C\u00e2mara como no Senado.<\/p>\n<p>Sem o apoio delas, o governo n\u00e3o conseguir\u00e1 fazer avan\u00e7ar suas propostas de reforma da Previd\u00eancia, mudan\u00e7as nas leis tributarias e legisla\u00e7\u00e3o anticrime.<\/p>\n<p>Ante essa realidade n\u00e3o restou ao presidente Jair Bolsonaro se curvar ao poderio dos pol\u00edticos profissionais do Centr\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A t\u00e3o condenada pol\u00edtica do \u201ctoma l\u00e1-d\u00e1-c\u00e1\u201d, que Jair Bolsonaro, na campanha eleitoral, prometeu varrer do cen\u00e1rio nacional, caminha para ser usada pelo pr\u00f3prio presidente da Rep\u00fablica como arma para salvar a reforma da Previd\u00eancia. Com s\u00e9rias dificuldades para aprova\u00e7\u00e3o da Nova Previd\u00eancia sem sofrer uma ampla desidrata\u00e7\u00e3o, o Pal\u00e1cio do Planalto aceita a recria\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-207972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=207972"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207972\/revisions"}],"predecessor-version":[{"id":207973,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/207972\/revisions\/207973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206133"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=207972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=207972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=207972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}