{"id":208204,"date":"2019-05-14T20:17:45","date_gmt":"2019-05-14T23:17:45","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208204"},"modified":"2019-05-14T20:17:45","modified_gmt":"2019-05-14T23:17:45","slug":"weintraub-tera-que-explicar-cortes-nas-universidades","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/weintraub-tera-que-explicar-cortes-nas-universidades\/","title":{"rendered":"Weintraub ter\u00e1 que explicar cortes nas universidades"},"content":{"rendered":"<p>O plen\u00e1rio da C\u00e2mara aprovou nesta ter\u00e7a-feira (14), por 307 votos a 82, a convoca\u00e7\u00e3o do ministro da Educa\u00e7\u00e3o, Abraham Weintraub, para explicar aos parlamentares os cortes no or\u00e7amento das universidades p\u00fablicas e de institutos federais.<\/p>\n<p>Por se tratar de convoca\u00e7\u00e3o, o ministro \u00e9 obrigado a comparecer \u00e0 comiss\u00e3o geral que o ouvir\u00e1 no plen\u00e1rio da C\u00e2mara nesta quarta-feira (15), \u00e0s 15h. Segundo o autor do pedido, deputado Orlando Silva (PCdoB-SP), o ministro precisa explicar como ser\u00e1 feito o bloqueio dos recursos.<\/p>\n<p>\u201c\u00c9 uma oportunidade para que o povo brasileiro perceba que a C\u00e2mara dos Deputados est\u00e1 sens\u00edvel ao clamor da sociedade, j\u00e1 que amanh\u00e3 as ruas ser\u00e3o ocupadas por gente preocupada com a cultura e a educa\u00e7\u00e3o. O ministro vai explicar o corte de 30% das universidades e institutos federais\u201d, comentou.<\/p>\n<p>Antes da vota\u00e7\u00e3o, a l\u00edder do governo no Congresso, deputada Joice Hasselmann (PSL-SP) havia declarado que o ministro da Educa\u00e7\u00e3o est\u00e1 preparado para debater e esclarecer a situa\u00e7\u00e3o da pasta. \u201cO ministro [da Educa\u00e7\u00e3o] \u00e9 preparado para falar sobre o assunto. A convoca\u00e7\u00e3o n\u00e3o \u00e9 agrad\u00e1vel, mas \u00e9 do jogo democr\u00e1tico e, se a maioria quiser convoc\u00e1-lo, ele vir\u00e1\u201d, afirmou.<\/p>\n<p>Apenas PSL e Novo orientaram seus parlamentares a votar contra a convoca\u00e7\u00e3o. Para a deputada Carla Zambelli (PSL-SP), a convoca\u00e7\u00e3o \u00e9 um instrumento para adiar a vota\u00e7\u00e3o de medidas provis\u00f3rias importantes para o governo federal, como a MP 870, da reforma administrativa, que definiu a estrutura de governo na gest\u00e3o Bolsonaro e foi modificada por parlamentares, em comiss\u00e3o mista, na semana passada. A medida que altera a estrutura ministerial perde validade no dia 3 de junho e precisa ser votada por deputados e posteriormente por senadores para que n\u00e3o deixe de vigorar.<\/p>\n<p>\u201cQual \u00e9 a inten\u00e7\u00e3o real de se convocar ministro para ir ao Plen\u00e1rio? Por que est\u00e3o com medo de discutir as medidas provis\u00f3rias? Por que insistem em tirar o Coaf do Moro? Para proibir a Receita Federal de representar? \u201d, argumentou.<\/p>\n<p>Apesar de ter sido convocado para participar de comiss\u00e3o geral, a presen\u00e7a de Abraham Weintraub j\u00e1 era prevista na C\u00e2mara dos Deputados \u00e0s 10h desta quarta-feira. O ministro havia sido convidado para dar explica\u00e7\u00f5es sobre os cortes no Or\u00e7amento da Educa\u00e7\u00e3o na Comiss\u00e3o de Trabalho, de Administra\u00e7\u00e3o e Servi\u00e7o P\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O plen\u00e1rio da C\u00e2mara aprovou nesta ter\u00e7a-feira (14), por 307 votos a 82, a convoca\u00e7\u00e3o do ministro da Educa\u00e7\u00e3o, Abraham Weintraub, para explicar aos parlamentares os cortes no or\u00e7amento das universidades p\u00fablicas e de institutos federais. Por se tratar de convoca\u00e7\u00e3o, o ministro \u00e9 obrigado a comparecer \u00e0 comiss\u00e3o geral que o ouvir\u00e1 no plen\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-208204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208204"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208204\/revisions"}],"predecessor-version":[{"id":208206,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208204\/revisions\/208206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208205"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}