{"id":208341,"date":"2019-05-17T09:37:55","date_gmt":"2019-05-17T12:37:55","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208341"},"modified":"2019-05-17T09:59:24","modified_gmt":"2019-05-17T12:59:24","slug":"coreia-aprimora-base-para-lancamento-de-misseis","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/coreia-aprimora-base-para-lancamento-de-misseis\/","title":{"rendered":"Coreia aprimora base para lan\u00e7amento de m\u00edsseis"},"content":{"rendered":"<p>Um grupo de pesquisadores dos Estados Unidos (EUA) informou que uma an\u00e1lise feita por seus integrantes indica que uma base de lan\u00e7amento de m\u00edsseis na Coreia do Norte foi aprimorada.<\/p>\n<p>Nessa quinta-feira (16), o grupo, denominado 38 North, divulgou os resultados da an\u00e1lise de imagens de sat\u00e9lite, que mostram a Esta\u00e7\u00e3o de Lan\u00e7amento de Sat\u00e9lite Sohae, em Tongchang-ri, localizada na parte noroeste da Coreia do Norte.<\/p>\n<p>Segundo a equipe, uma foto tirada em 18 de abril parece mostrar que a constru\u00e7\u00e3o de um pr\u00e9dio em L foi conclu\u00edda em uma \u00e1rea onde s\u00e3o montados os componentes relacionados a lan\u00e7amentos.<\/p>\n<p>O grupo afirma que um ve\u00edculo continua estacionado na instala\u00e7\u00e3o de observa\u00e7\u00e3o, que registra dados.<\/p>\n<p>Acredita-se que a esta\u00e7\u00e3o de lan\u00e7amento esteja pronta para entrar em opera\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grupo de pesquisadores dos Estados Unidos (EUA) informou que uma an\u00e1lise feita por seus integrantes indica que uma base de lan\u00e7amento de m\u00edsseis na Coreia do Norte foi aprimorada. Nessa quinta-feira (16), o grupo, denominado 38 North, divulgou os resultados da an\u00e1lise de imagens de sat\u00e9lite, que mostram a Esta\u00e7\u00e3o de Lan\u00e7amento de Sat\u00e9lite [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-208341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208341"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208341\/revisions"}],"predecessor-version":[{"id":208343,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208341\/revisions\/208343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208342"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}