{"id":208344,"date":"2019-05-17T12:15:35","date_gmt":"2019-05-17T15:15:35","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208344"},"modified":"2019-05-17T12:16:40","modified_gmt":"2019-05-17T15:16:40","slug":"grupos-especiais-do-governo-vao-cacar-corruptos","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/grupos-especiais-do-governo-vao-cacar-corruptos\/","title":{"rendered":"Grupos especiais do governo v\u00e3o ca\u00e7ar corruptos"},"content":{"rendered":"<p>A Advocacia-Geral da Uni\u00e3o (AGU) publicou nesta sexta (17) no Di\u00e1rio Oficial da Uni\u00e3o portaria em que cria escrit\u00f3rios regionais de dedica\u00e7\u00e3o exclusiva ao combate \u00e0 corrup\u00e7\u00e3o, cada um composto por 100 advogados p\u00fablicos.<\/p>\n<p>Com isso, advogados p\u00fablicos que atuavam em casos de corrup\u00e7\u00e3o espalhados pelas diversas varas do pa\u00eds ficar\u00e3o agora concentrados nos chamados Grupos Regionais de Atua\u00e7\u00e3o Proativa (Graps), atuantes em cada uma das cinco procuradorias regionais da Uni\u00e3o e com 100 integrantes dedicados exclusivamente ao tema.<\/p>\n<p>Os Graps ter\u00e3o duas frentes principais de atua\u00e7\u00e3o, segundo a AGU: o combate \u00e0 improbidade administrativa e a recupera\u00e7\u00e3o de ativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Advocacia-Geral da Uni\u00e3o (AGU) publicou nesta sexta (17) no Di\u00e1rio Oficial da Uni\u00e3o portaria em que cria escrit\u00f3rios regionais de dedica\u00e7\u00e3o exclusiva ao combate \u00e0 corrup\u00e7\u00e3o, cada um composto por 100 advogados p\u00fablicos. Com isso, advogados p\u00fablicos que atuavam em casos de corrup\u00e7\u00e3o espalhados pelas diversas varas do pa\u00eds ficar\u00e3o agora concentrados nos chamados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":132303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-208344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208344"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208344\/revisions"}],"predecessor-version":[{"id":208346,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208344\/revisions\/208346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/132303"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}