{"id":208382,"date":"2019-05-18T00:01:06","date_gmt":"2019-05-18T03:01:06","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208382"},"modified":"2019-05-18T03:17:04","modified_gmt":"2019-05-18T06:17:04","slug":"gays-atacam-preconceito-e-pedem-mais-respeito","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/gays-atacam-preconceito-e-pedem-mais-respeito\/","title":{"rendered":"Gays atacam preconceito e pedem mais respeito"},"content":{"rendered":"<p>Criado para conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da luta contra a discrimina\u00e7\u00e3o dos homossexuais, transexuais e transg\u00eaneros, o Dia Internacional de Luta Contra a Homofobia, Bifobia e Transfobia foi celebrado na sexta (17) em todo o mundo.<\/p>\n<p>A data busca estimular a toler\u00e2ncia e o respeito ao pr\u00f3ximo, independentemente de sua orienta\u00e7\u00e3o sexual. Em boa parte do mundo, \u00e9 comemorada desde 1990, quando a Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) retirou a homossexualidade do rol das doen\u00e7as listadas na Classifica\u00e7\u00e3o Estat\u00edstica Internacional de Doen\u00e7as e Problemas Relacionados com a Sa\u00fade (CID) e aboliu o uso do termo &#8220;homossexualismo\u201d. No Brasil, no entanto, a data s\u00f3 foi inclu\u00edda no calend\u00e1rio oficial quase 20 anos depois, em 2010.<\/p>\n<p>Apesar dos avan\u00e7os, dados de organiza\u00e7\u00f5es que atuam neste campo no pa\u00eds, como o Grupo Gay da Bahia, apontam recorde de mortes por homofobia no Brasil em 2017. Segundo levantamento da organiza\u00e7\u00e3o, uma pessoa \u00e9 assassinada a cada 19 horas em fun\u00e7\u00e3o da sua orienta\u00e7\u00e3o sexual ou identidade de g\u00eanero. Os dados mostram ainda que ao menos 8.027 pessoas foram mortas entre 1963 e 2018 por esta raz\u00e3o.<\/p>\n<p>\u201cEstamos lutando pela nossa exist\u00eancia e por nosso amor\u201d, declarou a presidente do Conselho Nacional de Combate \u00e0 Discrimina\u00e7\u00e3o e Promo\u00e7\u00e3o dos Direitos de L\u00e9sbicas, Gays, Bissexuais, Travestis e Transexuais (CNCD\/LGBT), Marina Reidel, durante audi\u00eancia p\u00fablica realizada pela Comiss\u00e3o de Direitos Humanos e Minorias da C\u00e2mara dos Deputados, nesta quarta-feira (15).<\/p>\n<p>Segundo Marina, a comunidade LGBTI+ vem, pouco a pouco, conquistando respeito e representatividade, mas ainda h\u00e1 muito o que fazer. \u201cPrecisamos continuar nesta luta, que n\u00e3o \u00e9 s\u00f3 de hoje\u201d, disse ao defender o Conselho. Criado em 2001, o \u00f3rg\u00e3o colegiado composto por representantes da sociedade civil e do governo federal \u00e9 respons\u00e1vel por, entre outras coisas, formular e propor diretrizes de a\u00e7\u00e3o governamental voltadas ao combate \u00e0 discrimina\u00e7\u00e3o e promo\u00e7\u00e3o e defesa dos direitos de l\u00e9sbicas, gays, bissexuais, travestis, transexuais e intersexuais.<\/p>\n<p>No entanto, o decreto presidencial 9.759, de 11 de abril, pretende diminuir de 700 para menos de 50 o n\u00famero de conselhos como o CNCD\/LGBT. Para desburocratizar e economizar, o decreto deu prazo de 60 dias aos conselhos, comit\u00eas, comiss\u00f5es, grupos e qualquer outro colegiado da administra\u00e7\u00e3o p\u00fablica federal para justificarem sua exist\u00eancia. A medida ainda estabelece novas regras para o funcionamento dos \u00f3rg\u00e3os de participa\u00e7\u00e3o social parit\u00e1ria que sobrarem \u2013 havendo a possibilidade de recria\u00e7\u00e3o do CNCD\/LGBT com outra configura\u00e7\u00e3o.<\/p>\n<p>Para o conselheiro Emerson Santos, coordenador-nacional da Articula\u00e7\u00e3o Brasileira de Jovens L\u00e9sbicas, Gays, Bissexuais, Travestis e Transexuais, caso ocorra, a extin\u00e7\u00e3o do conselho nacional ser\u00e1 um retrocesso. \u201cTemos resistido bravamente neste conselho. Estamos passando por um momento de desmonte da pol\u00edtica nacional LGBTI+. A extin\u00e7\u00e3o do conselho no dia 28 de junho j\u00e1 foi anunciada, mesmo o mandato dos conselheiros tendo validade at\u00e9 dezembro deste ano. N\u00e3o aceitamos a recria\u00e7\u00e3o do conselho com menos de 15 representantes da sociedade civil\u201d, declarou Santos.<\/p>\n<p><strong>Preconceito<\/strong><br \/>\nPara ilustrar o que considera mudan\u00e7as culturais positivas, o diretor-presidente da Alian\u00e7a Nacional LGBTI+, Toni Reis lembrou que, quando crian\u00e7a, sua orienta\u00e7\u00e3o sexual era tratada como uma doen\u00e7a. &#8220;Quando eu tinha 14 anos, o padre falava que ou eu era pecador, ou doente, ou sem-vergonha. Que eu tinha que escolher uma das tr\u00eas coisas, porque as tr\u00eas, juntas, n\u00e3o era poss\u00edvel\u201d, lembrou Reis. \u201cJ\u00e1 recentemente, eu e meu marido recebemos uma carta muito bacana do Papa [Francisco], na qual ele desejava felicidades \u00e0 nossa fam\u00edlia\u201d, contou Reis, que \u00e9 casado com um ingl\u00eas e se classifica como cat\u00f3lico-apost\u00f3lico-romano praticante. \u201cO que tamb\u00e9m queremos ser \u00e9 cidad\u00e3os. Queremos simplesmente ser respeitados\u201d, disse o presidente da Alian\u00e7a Nacional na audi\u00eancia p\u00fablica no Congresso. Segundo afirmou aos parlamentares, 73% dos jovens homossexuais, transexuais e transg\u00eaneros sofrem bullying e\/ou preconceito nas escolas em que estudam; 36% deles s\u00e3o v\u00edtimas de agress\u00f5es violentas e 60% se sentem inseguros no ambiente escolar.<\/p>\n<p>\u201c\u00c9 por isso que pedimos uma educa\u00e7\u00e3o que respeite a diversidade. N\u00e3o queremos transformar ningu\u00e9m em gay, l\u00e9sbica ou trans. O que queremos \u00e9 que as pessoas sejam respeitadas\u201d, refor\u00e7ou, lembrando que, em m\u00e9dia, uma pessoa \u00e9 agredida a cada duas horas por motivos homof\u00f3bicos. \u201cTemos que propor solu\u00e7\u00f5es para este problema\u201d, ponderou Reis, chamando todos os segmentos da sociedade a discutir o tema.<\/p>\n<p><strong>Inclus\u00e3o<\/strong><br \/>\nA presidenta da Rede Nacional de Pessoas Trans do Brasil, Tathiane Aquino de Ara\u00fajo, tamb\u00e9m defendeu uma educa\u00e7\u00e3o inclusiva e mais oportunidades de emprego especialmente a jovens transexuais. Segundo Tathiane, a falta de oportunidades muitas vezes leva transg\u00eaneros \u00e0 prostitui\u00e7\u00e3o. \u201cPrincipalmente quando falamos de pessoas trans, estamos falando de homens e mulheres travestis e transsexuais a quem a sociedade n\u00e3o d\u00e1 alternativa de sobreviv\u00eancia que n\u00e3o as esquinas do pa\u00eds\u201d, lamentou Tathiane.<\/p>\n<p>Segundo ela, antes mesmo da viol\u00eancia f\u00edsica que faz com que a expectativa de vida de uma pessoa trans esteja em 35 anos de \u201csobreviv\u00eancia\u201d, o grupo \u00e9 vitimado pelo preconceito e pelo descaso social: \u201c\u00c9 uma morte social que, quando n\u00e3o mata fisicamente, leva nossa popula\u00e7\u00e3o a desfalecer [aos poucos]. As portas v\u00e3o todas se fechando\u201d, disse Tathiane, ao destacar a import\u00e2ncia da escola e da compreens\u00e3o familiar, principalmente durante a juventude.<\/p>\n<p>\u201cNosso problema n\u00e3o \u00e9 &#8216;sair do arm\u00e1rio&#8217;. \u00c9 algo muito mais forte. Quando meu pai, na minha inf\u00e2ncia, me obrigava a usar camisa de time de futebol e cal\u00e7\u00e3o para ir ao est\u00e1dio, eu o seguia for\u00e7ada, para n\u00e3o apanhar. Quando atingimos a adolesc\u00eancia, que \u00e9 uma fase crucial, isto costuma se manifestar de uma forma explosiva. A\u00ed vem a incompreens\u00e3o da sociedade, pois a escola n\u00e3o est\u00e1 preparada para nos receber e a fam\u00edlia, muitas vezes, expulsa o jovem de casa\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criado para conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da luta contra a discrimina\u00e7\u00e3o dos homossexuais, transexuais e transg\u00eaneros, o Dia Internacional de Luta Contra a Homofobia, Bifobia e Transfobia foi celebrado na sexta (17) em todo o mundo. A data busca estimular a toler\u00e2ncia e o respeito ao pr\u00f3ximo, independentemente de sua orienta\u00e7\u00e3o sexual. Em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":206910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-208382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208382"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208382\/revisions"}],"predecessor-version":[{"id":208383,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208382\/revisions\/208383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/206910"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}