{"id":208450,"date":"2019-05-19T13:54:35","date_gmt":"2019-05-19T16:54:35","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208450"},"modified":"2019-05-19T13:54:35","modified_gmt":"2019-05-19T16:54:35","slug":"agua-tem-muita-se-tiver-racionamento-e-praga","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/agua-tem-muita-se-tiver-racionamento-e-praga\/","title":{"rendered":"\u00c1gua tem muita; se tiver racionamento, \u00e9 praga"},"content":{"rendered":"<p>O reservat\u00f3rio de Santa Maria, no Distrito Federal, chegou a 100% de sua capacidade neste domingo (19). A informa\u00e7\u00e3o foi dada pela Ag\u00eancia Reguladora das \u00c1guas, Energia e Saneamento B\u00e1sico (Adasa).<\/p>\n<p>O reservat\u00f3rio de Santa Maria \u00e9 respons\u00e1vel pelo abastecimento da maior parte da \u00e1rea central da capital, chamada de Plano Piloto. Em 2017, no que a Adasa chama de \u201cper\u00edodo de escassez\u201d, ele chegou a ter apenas 21,8% da capacidade.<\/p>\n<p>Esse per\u00edodo levou a uma crise h\u00eddrica que atingiu Bras\u00edlia fortemente. Per\u00edodos sem \u00e1gua em algumas regi\u00f5es geraram transtorno aos moradores. O governo do Distrito Federal promoveu campanhas de redu\u00e7\u00e3o do consumo para lidar com o abastecimento deficiente pelo baixo volume dos reservat\u00f3rios.<\/p>\n<p>Desde 2017, os reservat\u00f3rios passaram a se recuperar. Segundo a Adasa, o de Santa Maria retomou \u00edndices mais elevados da capacidade de forma mais lenta. &#8211; o que ocorreu por caracter\u00edsticas pr\u00f3prias do reservat\u00f3rio, como o fato de ser abastecido por pequenos riachos. Em 2018, ele atingiu 50% do volume em abril.<\/p>\n<p>Apesar da recupera\u00e7\u00e3o, a Adasa segue orientando os moradores a manter pr\u00e1ticas de redu\u00e7\u00e3o de consumo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O reservat\u00f3rio de Santa Maria, no Distrito Federal, chegou a 100% de sua capacidade neste domingo (19). A informa\u00e7\u00e3o foi dada pela Ag\u00eancia Reguladora das \u00c1guas, Energia e Saneamento B\u00e1sico (Adasa). O reservat\u00f3rio de Santa Maria \u00e9 respons\u00e1vel pelo abastecimento da maior parte da \u00e1rea central da capital, chamada de Plano Piloto. Em 2017, no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-208450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208450"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208450\/revisions"}],"predecessor-version":[{"id":208452,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208450\/revisions\/208452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208451"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}