{"id":208544,"date":"2019-05-22T08:00:57","date_gmt":"2019-05-22T11:00:57","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208544"},"modified":"2019-05-22T08:28:46","modified_gmt":"2019-05-22T11:28:46","slug":"samba-cachaca-e-lagrimas-nos-60-anos-de-brasilia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/samba-cachaca-e-lagrimas-nos-60-anos-de-brasilia\/","title":{"rendered":"Samba, cacha\u00e7a e l\u00e1grimas nos 60 anos de Bras\u00edlia"},"content":{"rendered":"<p>Novamente o Governo do Distrito Federal, agora comandado por Ibaneis Rocha (MDB) atravessa o samba, no descompasso recorrente e desarm\u00f4nico entre a Secretaria de Cultura e as entidades culturais da capital da Rep\u00fablica.<\/p>\n<p>O an\u00fancio \u2013 para perplexidade dos carnavalescos da cidade &#8211; da Vila Isabel, escola de samba do Rio de Janeiro para apresentar enredo alusivo aos 60 anos de Bras\u00edlia, no pr\u00f3ximo Carnaval, teve o efeito de uma bomba. E o patroc\u00ednio, em tempos de vacas magras, ser\u00e1 de 4 milh\u00f5es de reais.<\/p>\n<p>A Associa\u00e7\u00e3o Recreativa e Cultural Unidos do Cruzeiro \u2013 ARUC, maior campe\u00e3 do Carnaval de Bras\u00edlia, por meio de nota emitida por sua diretoria, manifestou a sua indigna\u00e7\u00e3o com o desprezo \u00e0 pr\u00f3pria escola, \u00e0s coirm\u00e3s e \u00e0 Liga das Escola de Samba do Distrito Fefderal, que sequer foram consultadas. ( Leia abaixo \u00edntegra da nota).<\/p>\n<p>Em evento realizado no dia 10 de abril \u00faltimo na Comiss\u00e3o de Cultura da C\u00e2mara do Deputados, quando foi aprovado o PL 256\/19, que reconhece as escolas de samba como manifesta\u00e7\u00e3o da cultura brasileira \u2013 sem a presen\u00e7a de nenhum representante da Secult-DF-, o presidente da Liga das Escolas de Samba de Bras\u00edlia, Geomar Leite, antecipou a exist\u00eancia de um zum-zum sobre a possibilidade de a Vila Isabel homenagear Bras\u00edlia nos 60 anos da cidade, mas que nada lhe foi passado.<\/p>\n<p>Carnavalesco e jornalistas especializados no tema, residentes em Bras\u00edlia, manifestaram ao pr\u00f3prio secret\u00e1rio Ad\u00e3o C\u00e2ndido, a intens\u00e3o de colaborar tanto no projeto de revitaliza\u00e7\u00e3o do Carnaval de Bras\u00edlia, como nos eventos relacionados \u00e0s culturas populares. Mas, pelo que se sabe, n\u00e3o h\u00e1 muita transpar\u00eancia na escolha de profissionais para compor uma poss\u00edvel comiss\u00e3o coordenadora desses projetos.<\/p>\n<p><strong>Tempos de Arruda<\/strong><br \/>\nCoincidentemente ou n\u00e3o, o epis\u00f3dio parece ir tomando o mesmo rumo do ocorrido em 2010, no governo de Jos\u00e9 Roberto Arruda.<\/p>\n<p>Em meados de 2007, o Instituto Jo\u00e3osinho Trinta (com a participa\u00e7\u00e3o do pr\u00f3prio Jo\u00e3osinho, que \u00e0 \u00e9poca residia na capital) elaborou uma sinopse com a ideia de um enredo alusivo aos 50 anos de Bras\u00edlia. Uma apresenta\u00e7\u00e3o inicial foi feita \u00e0 Beija- Flor, dada a proximidade do carnavalesco com a escola de Nil\u00f3polis.<\/p>\n<p>A seguir, foi levada a inten\u00e7\u00e3o e o pr\u00e9-projeto ao Governo do Distrito Federal. A proposta era desencadear um certame licitat\u00f3rio, algo do tipo Chamamento P\u00fablico, entre as principais escolas de samba do Rio de Janeiro e, posteriormente, o envolvimento das escolas de samba do DF e de sua Liga.<\/p>\n<p>O conjunto de documentos inclu\u00eda ainda a implementa\u00e7\u00e3o do projeto pedag\u00f3gico <em>Carnaval: Ind\u00fastria Social,<\/em>\u00a0que chegou a ser licitado, mas interrompido pelos problemas do governo Arruda.<\/p>\n<p>A partir da\u00ed, a Nota da Diretoria da ARUC, descreve com precis\u00e3o e maestria os demais acontecimentos lament\u00e1veis, que continuam a marcar a rela\u00e7\u00e3o da Secretaria de Cultura com as entidades culturais do Distrito Federal.<\/p>\n<p>A t\u00edtulo de recorda\u00e7\u00e3o, vale lembrar que em 2010, Jo\u00e3osinho Trinta e o Instituto IJT, autores da ideia, foram alijados do processo. Assumiram a condu\u00e7\u00e3o do assunto o famigerado trio de deputados distritais, que se tornaram nacionalmente conhecidos pelo epis\u00f3dio da &#8220;Ora\u00e7\u00e3o da Propina&#8221;. E o dinheiro do carnaval mudou de bolso.<\/p>\n<p><strong>Beija-Flor 2010<\/strong><br \/>\nA Comiss\u00e3o de Carnaval da Beija-Flor teve muitas dificuldades \u00e0 \u00e9poca, para finalizar o projeto que homenageou \u00e0 capital da Rep\u00fablica, pelos seus primeiros 50 anos. O acordo inicial entre a escola e o GDF, que seria de patroc\u00ednio de 5 milh\u00f5es de reais, acabou ficando em torno de 3,5 milh\u00f5es, com muitas dificuldades para o recebimento, conforme relato de Jo\u00e3o Ant\u00f4nio, ent\u00e3o respons\u00e1vel pelo Barrac\u00e3o da escola de Nil\u00f3polis.<\/p>\n<p>Por diversas raz\u00f5es a Comiss\u00e3o de Carnaval optou por se afastar da linha de enredo proposta por Jo\u00e3osinho Trinta. Somando-se a isso a dificuldade de recursos, fez com que a \u201cMajestosa e Soberana\u201d \u2013 como \u00e9 conhecida no meio carnavalesco &#8211; realizasse um dos piores desfiles de sua hist\u00f3ria. E, na opini\u00e3o de diversos especialistas, \u201cficou pra l\u00e1 de bom\u201d, aquele insosso 3\u00ba lugar. Na pr\u00e1tica, os jurados resolveram dar uma m\u00e3ozinha, diante de tantas trapalhadas.<\/p>\n<p><strong>Nota da ARUC<\/strong> &#8211; A Diretoria da ARUC estranha a aus\u00eancia das escolas de samba de Bras\u00edlia na solenidade de assinatura do conv\u00eanio do GDF com a Unidos de Vila Isabel, com vistas ao Carnaval de 2020, para a qual n\u00e3o foram convidadas.<\/p>\n<p>Mais do que isso, a ARUC estranha o fato das escolas de samba de Bras\u00edlia e a pr\u00f3pria Uniesbe terem sido totalmente marginalizadas desse processo, n\u00e3o tendo sido consultadas ou sequer informadas do projeto, ao contr\u00e1rio do que aconteceu em 2010, nos 50 anos de Bras\u00edlia, quando a cidade foi enredo da Beija-Flor de Nil\u00f3polis e as escolas de samba de Bras\u00edlia participaram de uma Comiss\u00e3o, com outros segmentos do governo e da \u00e1rea cultural de Bras\u00edlia, que acompanhou todo o processo, inclusive com visitas peri\u00f3dicas \u00e0 Beija-Flor e com a realiza\u00e7\u00e3o de uma eliminat\u00f3ria de samba-enredo em Bras\u00edlia, na ARUC, da qual participaram compositores da cidade, classificando 3 sambas para participar da disputa na quadra da Beija-Flor.<\/p>\n<p>A marginaliza\u00e7\u00e3o das escolas de samba de Bras\u00edlia desse processo agora com a Unidos de Vila Isabel \u00e9 um desprest\u00edgio para as entidades carnavalescas da cidade.<\/p>\n<p>A ARUC, na condi\u00e7\u00e3o de mais antiga escola de samba de Bras\u00edlia, de maior campe\u00e3 do Carnaval da cidade e de Patrim\u00f4nio Cultural Imaterial do DF estranha, tamb\u00e9m, a declara\u00e7\u00e3o do Secret\u00e1rio de Cultura, Ad\u00e3o C\u00e2ndido, de que a reestrutura\u00e7\u00e3o das escolas de samba em Bras\u00edlia \u00e9 incipiente, e reafirma que, mesmo sem a realiza\u00e7\u00e3o do desfile das escolas de samba nos \u00faltimos 5 anos, t\u00eam feito sua parte para manter viva a bandeira do samba e do Carnaval, mesmo sem apoio do GDF e da Secretaria de Cultura, com atividades esportivas, culturais, carnavalescas e comunit\u00e1rias, de janeiro a janeiro, e espera ser consultada previamente sobre a participa\u00e7\u00e3o da Vila Isabel na organiza\u00e7\u00e3o do Carnaval de Bras\u00edlia.<\/p>\n<p>N\u00f3s, mais do que ningu\u00e9m, conhecemos os problemas, as dificuldades e as necessidades das escolas de samba de Bras\u00edlia, achamos importante o interc\u00e2mbio com as escolas de samba do Rio de Janeiro, mas n\u00e3o abrimos m\u00e3o de participar ativa e diretamente desse processo de reconstru\u00e7\u00e3o do Carnaval de Bras\u00edlia.<\/p>\n<p>Queremos ser parceiros nesse processo porque temos certeza de que temos contribui\u00e7\u00f5es importantes a dar, com base na nossa experi\u00eancia e nos nossos 58 anos de hist\u00f3ria, onde sempre fizemos parcerias e interc\u00e2mbios com nossas coirm\u00e3s cariocas.<\/p>\n<p>N\u00e3o podemos e n\u00e3o aceitamos ser colocados \u00e0 margem desse processo em respeito \u00e0 nossa hist\u00f3ria.<\/p>\n<p>Bras\u00edlia, 21 de maio de 2019<\/p>\n<p>Moacyr Oliveira Filho<br \/>\nPresidente da ARUC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novamente o Governo do Distrito Federal, agora comandado por Ibaneis Rocha (MDB) atravessa o samba, no descompasso recorrente e desarm\u00f4nico entre a Secretaria de Cultura e as entidades culturais da capital da Rep\u00fablica. O an\u00fancio \u2013 para perplexidade dos carnavalescos da cidade &#8211; da Vila Isabel, escola de samba do Rio de Janeiro para apresentar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-208544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208544"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208544\/revisions"}],"predecessor-version":[{"id":208548,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208544\/revisions\/208548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208545"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}