{"id":208613,"date":"2019-05-23T08:47:17","date_gmt":"2019-05-23T11:47:17","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208613"},"modified":"2019-05-23T09:21:02","modified_gmt":"2019-05-23T12:21:02","slug":"se-nao-der-verde-e-amarelo-quadro-vai-ficar-preto","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/se-nao-der-verde-e-amarelo-quadro-vai-ficar-preto\/","title":{"rendered":"Se n\u00e3o der verde e amarelo, quadro vai ficar preto&#8230;"},"content":{"rendered":"<p>O ministro Marco Aur\u00e9lio Mello, do Supremo Tribunal Federal, classificou de \u201cinusitada\u201d, com o tom de uma analogia prof\u00e9tica, a manifesta\u00e7\u00e3o convocada por grupos aliados ao presidente Jair Bolsonaro para o domingo, 26, com lemas contra o Congresso e o STF.<\/p>\n<p>\u201cO governo precisa de defesa? Eu acho que n\u00e3o. Eu conhe\u00e7o protesto para se reivindicar alguma coisa, para se reclamar. Mas para dar apoio ao governo, n\u00e3o vejo em um Estado democr\u00e1tico essa necessidade\u201d, disse Marco Aur\u00e9lio, ao chegar para a sess\u00e3o plen\u00e1ria na quarta, 22.<\/p>\n<p>\u201c\u00c9 inusitado. Lembra que o ex-presidente Fernando Collor conclamou a se sair de verde e amarelo e as pessoas sa\u00edram de preto\u2026\u201d. O que aconteceu, recordou, \u00e9 que todo mundo foi \u00e0s ruas de preto. Logo depois Collor caiu, alvo de um impeachment.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Marco Aur\u00e9lio Mello, do Supremo Tribunal Federal, classificou de \u201cinusitada\u201d, com o tom de uma analogia prof\u00e9tica, a manifesta\u00e7\u00e3o convocada por grupos aliados ao presidente Jair Bolsonaro para o domingo, 26, com lemas contra o Congresso e o STF. \u201cO governo precisa de defesa? Eu acho que n\u00e3o. Eu conhe\u00e7o protesto para se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-208613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208613"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208613\/revisions"}],"predecessor-version":[{"id":208618,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208613\/revisions\/208618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208617"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}