{"id":208699,"date":"2019-05-25T09:00:55","date_gmt":"2019-05-25T12:00:55","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208699"},"modified":"2019-05-25T09:20:09","modified_gmt":"2019-05-25T12:20:09","slug":"generais-dao-a-bolsonaro-opcao-de-ser-presidente","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/generais-dao-a-bolsonaro-opcao-de-ser-presidente\/","title":{"rendered":"Generais d\u00e3o a Bolsonaro op\u00e7\u00e3o de ser presidente"},"content":{"rendered":"<p>O sansei Kim Kataguiri, deputado federal pelo DEM\/SP, acha que o presidente Bolsonaro n\u00e3o \u00e9 sensei. Para poupar pesquisas e n\u00e3o interromper a leitura, aos desatentos, sansei nas Am\u00e9ricas significa neto de imigrantes japoneses; e sensei \u00e9 aquele que ensina, lidera, orienta. \u00c9 o mestre.<\/p>\n<p>Menin\u00e3o, o japinha \u00e9 bom de fala. Tem perfil controverso, mas costuma acertar, motivo que o levou a liderar um movimento nacional em apoio ao impedimento da \u201cpresidenta\u201d Dilma e \u00e0 elei\u00e7\u00e3o de Bolsonaro. Conveniente situa\u00e7\u00e3o, n\u00e3o h\u00e1 d\u00favida, para quem \u00e9 l\u00edder do MBL \u2013 Movimento Brasil Livre, respons\u00e1vel pelo oportuno sucesso dele nas redes sociais e nas urnas.<\/p>\n<p>Pela idade do sansei eleito para a C\u00e2mara dos Deputados e de seu pr\u00f3ximo temporal coleguinha de gera\u00e7\u00e3o, filho do presidente Bolsonaro, Carlos, eleito mero vereador para tratar de assuntos da cidade do Rio de Janeiro, n\u00e3o h\u00e1 como n\u00e3o estabelecer equival\u00eancias. Ou a falta delas.<\/p>\n<p>O japa Kataguiri \u00e9 valente, devemos reconhecer, ainda que n\u00e3o sejam aprovados, por muitos, seus m\u00e9todos e filia\u00e7\u00e3o partid\u00e1ria. Enfrenta seus opositores na arena para a qual foi eleito, fala ao vivo, no p\u00falpito do Congresso Nacional, antes de repercutir suas falas nas redes sociais.<\/p>\n<p>Carlos Bolsonaro, que \u00e9 cobrado pelo desempenho em a\u00e7\u00f5es em prol dos habitantes da cidade carioca para a qual foi eleito e \u00e9 pago \u2013 n\u00e3o h\u00e1 nas suas redes sociais nenhuma satisfa\u00e7\u00e3o sobre isso \u2013 preferiu a inser\u00e7\u00e3o longe da cidade que o elegeu, orientado pela astrologia desacreditada de seu pai adotivo, para dar palpites no Pal\u00e1cio do Planalto e prejudicar o Brasil.<\/p>\n<p>Em resumo \u00e9 isso. E o resultado \u00e9 o que a\u00ed est\u00e1. Kataguiri, o infante federal, afirma que melhor seria Bolsonaro ser a rainha da Inglaterra, deixar que profissionais assumam a governan\u00e7a. Dois filhos de Bolsonaro, que s\u00e3o identificados maldosamente como parlamentares \u00fateis (e at\u00e9 agora n\u00e3o foram, antes fossem), Fl\u00e1vio e Eduardo, que teriam legitimidade para tocar fogo no circo, s\u00e3o t\u00edmidos e preteridos na guerra atual travada entre o Executivo, o Legislativo e o Judici\u00e1rio.<\/p>\n<p>Onde est\u00e3o? Entregaram a fam\u00edlia ao irm\u00e3o porra-louca vereador que n\u00e3o tem nenhuma rela\u00e7\u00e3o institucional com o Pal\u00e1cio do Planalto. E a\u00ed?, perguntam os \u00f3rg\u00e3os de imprensa isentos. O menin\u00e3o Carlos Bolsonaro, hipnotizado pelos astros, mimado para escapar dos consult\u00f3rios de an\u00e1lise ap\u00f3s a separa\u00e7\u00e3o de seus pais, nomeia assessores no Pal\u00e1cio do Planalto, por recomenda\u00e7\u00e3o de um sniper metaf\u00edsico que n\u00e3o acerta um \u00fanico tiro a dist\u00e2ncia. Mora nos EUA.<\/p>\n<p>Fabio Wajngarten, que n\u00e3o tem forma\u00e7\u00e3o nem hist\u00f3rico profissional reconhecido internacionalmente no meio da propaganda, muito menos pelos expoentes t\u00e9cnicos em redes sociais, pode ter sido indicado por sua origem judaica e por ter colaborado um pouquinho \u2013 entretanto, a grande massa atuante nas redes sociais foi org\u00e2nica e ele nenhuma participa\u00e7\u00e3o teve no caso &#8211; na campanha eleitoral de Bolsonaro. Suas credenciais n\u00e3o existem tecnicamente. Mas ele foi plantado l\u00e1, ao lado de um her\u00f3i de guerra.<\/p>\n<p>O ministro que n\u00e3o costuma achar gra\u00e7a de nada, ainda que Kataguiri reconhe\u00e7a Bolsonaro como rainha da Inglaterra, \u00e9 soldado e n\u00e3o pensa de maneira n\u00e3o cartesiana. Tomara que seja a interpreta\u00e7\u00e3o (nesse caso) sensata nos bastidores do poder Executivo. Melhor para Bolsonaro.<\/p>\n<p>A orienta\u00e7\u00e3o para o presidente recusar a manifesta\u00e7\u00e3o pr\u00f3-interven\u00e7\u00e3o no Legislativo e Judici\u00e1rio anunciada para este domingo 26 foi orientada pelo mesmo general que n\u00e3o ri. Comunistas colegas do guru astr\u00f3logo de Carlos Bolsonaro, tamb\u00e9m t\u00eam c\u00e9rebro, assim como os generais, e sabem que n\u00e3o h\u00e1 possibilidade de interven\u00e7\u00e3o militar. Usando a nomenclatura empregada por esse idiota que influenciou e ofendeu autoridades, que defeca asneiras, cujo nome deve ser evitado para n\u00e3o propagar ainda mais a sua vaidade de personagem adivinhador do futuro, que gostaria de estar no programa Fant\u00e1stico do dia 31 de dezembro fazendo previs\u00f5es, s\u00f3 existe uma recomenda\u00e7\u00e3o: vai cagar, astr\u00f3logo!<\/p>\n<p>A sorte da sociedade brasileira \u00e9 que existe uma decis\u00e3o de miss\u00e3o que os generais v\u00e3o cumprir: o restabelecimento da democracia. Est\u00e1 dif\u00edcil porque perderam a oportunidade hist\u00f3rica de enquadrar o Judici\u00e1rio e o Legislativo. A chama foi parcialmente apagada pela imaturidade de Bolsonaro, pelo seu compromisso com um filho pr\u00f3digo, pela inexperi\u00eancia prov\u00e1vel de nunca ter liderado coisa nenhuma em 30 anos de parlamento, que n\u00e3o entendeu quem s\u00e3o os chamados cag\u00f5es pelo seu filho tchuthuca.<\/p>\n<p>Agora os comandantes n\u00e3o deixar\u00e3o o governo de jeito nenhum, com ou sem Bolsonaro, s\u00f3 quando a dec\u00eancia for uma esperan\u00e7a. O Brasil pode ficar tranquilo. Carlos Bolsonaro far\u00e1 do Rio de Janeiro uma cidade maravilhosa, ele \u00e9 um g\u00eanio. O Rio \u00e9 um reduto onde metade dos eleitores \u00e9 produto da mil\u00edcia. Metade da outra metade \u00e9 produto de eleitores submissos \u00e0 mil\u00edcia.<\/p>\n<p>Certamente Carlos Bolsonaro n\u00e3o faz parte desse eleitorado. Ele est\u00e1 muito preocupado com isso e pretende honrar o sal\u00e1rio e os votos que recebeu. Vai parar de fazer asneiras no plano nacional. Kim Kataguiri e Guedes encheram o saco de amadorismos. Generais tamb\u00e9m. J\u00e1 pediram os passaportes, embora prefiram ficar e colocar too mundo na linha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O sansei Kim Kataguiri, deputado federal pelo DEM\/SP, acha que o presidente Bolsonaro n\u00e3o \u00e9 sensei. Para poupar pesquisas e n\u00e3o interromper a leitura, aos desatentos, sansei nas Am\u00e9ricas significa neto de imigrantes japoneses; e sensei \u00e9 aquele que ensina, lidera, orienta. \u00c9 o mestre. Menin\u00e3o, o japinha \u00e9 bom de fala. Tem perfil controverso, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-208699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208699"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208699\/revisions"}],"predecessor-version":[{"id":208701,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208699\/revisions\/208701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/198693"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}