{"id":208861,"date":"2019-05-28T09:21:22","date_gmt":"2019-05-28T12:21:22","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208861"},"modified":"2019-05-28T10:23:55","modified_gmt":"2019-05-28T13:23:55","slug":"com-o-povo-nas-ruas-ha-algo-de-novo-no-ar","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/com-o-povo-nas-ruas-ha-algo-de-novo-no-ar\/","title":{"rendered":"Com o povo nas ruas h\u00e1 algo de novo no ar"},"content":{"rendered":"<p>Recentemente manifestei minha posi\u00e7\u00e3o nas redes sociais sobre o momento atual e o que existe de oculto no cotidiano pol\u00edtico. Amigos, seguidores, corajosos \u2013 ou expiadores da timeline alheia \u2013 opinaram.<\/p>\n<p>Uma minoria; dessas que comandam o mundo ou acham que comandam, mas possuem um racionalismo ing\u00eanuo sobre o mecanismo que faz a pol\u00edtica no dia a dia deste pa\u00eds. Ing\u00eanuo do lado do povo, por\u00e9m, altamente malicioso do ponto de vista dos protagonistas astutos da pol\u00edtica nacional e internacional.<\/p>\n<p>Muitos acreditam que t\u00eam acesso ao que faz o mundo funcionar e de que aquilo que n\u00e3o entendem n\u00e3o existe. Desafio \u00e0queles que lideram interven\u00e7\u00f5es pol\u00edticas, propagam f\u00e9 religiosa para que sejam mais cautelosos, pois, um simples haltere pode desenvolver mais m\u00fasculos do que m\u00e1quinas modernas e caras.<\/p>\n<p>Discursos homog\u00eaneos e ilus\u00f5es coletivas, especialmente sob a globaliza\u00e7\u00e3o, buscam monocultura intelectual e, por vezes, transformam uma pessoa em intelectual, por\u00e9m idiota.<\/p>\n<p>Na pol\u00edtica brasileira, a desigualdade din\u00e2mica leva em conta todo o futuro e todo o passado.<\/p>\n<p>O her\u00f3i (brasileiro) de hoje, pode ter sido o dinamizador do passado, mesmo que recente, na busca hegem\u00f4nica de uma ilus\u00e3o que permeia o coletivo de uma \u00e9poca n\u00e3o t\u00e3o distante da atual, mas que o futuro j\u00e1 est\u00e1 escrito e o mecanismo, que p\u00f5e a roda para funcionar, futuramente.<\/p>\n<p>Mas, nada nos impede de fazermos isso, j\u00e1!<\/p>\n<p>Na pol\u00edtica, o vencedor n\u00e3o \u00e9 aquele que termina por \u00faltimo. E se voc\u00ea gastar seu tempo tentando pressionar os outros, talvez haja algo de errado com voc\u00ea. Por\u00e9m, sempre \u00e9 mais f\u00e1cil manipular a macrobaboseira do que a microbaboseira pol\u00edtica.<\/p>\n<p>E eu com isso?!<\/p>\n<p>No domingo (26), manifestantes foram \u00e0s ruas para declarar apoio ao presidente Jair Bolsonaro, e levantar outras bandeiras, como o apoio \u00e0 Reforma da Previd\u00eancia, \u00e0 Opera\u00e7\u00e3o Lava Jato, o rep\u00fadio ao Centr\u00e3o, ao Congresso e ao STF.<\/p>\n<p>Foram registrados atos em todo o Pa\u00eds. As manifesta\u00e7\u00f5es serviram para demonstrar o respaldo popular do governo. A defesa das reformas (inclusive a da Previd\u00eancia, considerada impopular).<\/p>\n<p>Em um passado recente, seria imposs\u00edvel imaginar uma passeata em apoio \u00e0 reforma da Previd\u00eancia. J\u00e1 aos demais temas&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente manifestei minha posi\u00e7\u00e3o nas redes sociais sobre o momento atual e o que existe de oculto no cotidiano pol\u00edtico. Amigos, seguidores, corajosos \u2013 ou expiadores da timeline alheia \u2013 opinaram. Uma minoria; dessas que comandam o mundo ou acham que comandam, mas possuem um racionalismo ing\u00eanuo sobre o mecanismo que faz a pol\u00edtica no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-208861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208861"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208861\/revisions"}],"predecessor-version":[{"id":208863,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208861\/revisions\/208863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208862"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}