{"id":208934,"date":"2019-05-29T19:37:42","date_gmt":"2019-05-29T22:37:42","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208934"},"modified":"2019-05-29T20:57:15","modified_gmt":"2019-05-29T23:57:15","slug":"ibaneis-volta-de-lisboa-quem-paga-a-conta-da-festa","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/ibaneis-volta-de-lisboa-quem-paga-a-conta-da-festa\/","title":{"rendered":"Ibaneis volta de Lisboa. Quem paga a conta da festa?"},"content":{"rendered":"<p>O governador Ibaneis Rocha (MDB) est\u00e1 desembarcando em Bras\u00edlia ap\u00f3s uma viagem a Lisboa, onde passou o fim de semana descansando e estendeu dois dias \u00fateis para supostamente tratar de interesses do Distrito Federal. A pauta desses contatos, por\u00e9m, n\u00e3o foi divulgada.<\/p>\n<p>Ibaneis chega justamente na hora em que dos cofres p\u00fablicos est\u00e1 saindo dinheiro para pagar a conta de consultores do Projeto Bras\u00edlia 60 Anos na Sapuca\u00ed, sob a batuta da Vila Isabel. Sup\u00f5e-se que o governador, que anunciou a presen\u00e7a da cidade no samb\u00f3dromo do Rio em 2020 sem um centavo do governo, vai explicar quem pagar\u00e1 o pato.<\/p>\n<p>A conta a parcial, s\u00f3 de passagens a\u00e9reas e di\u00e1rias, bateu em 35 mil reais. Essa \u00e9 a mixaria que o contribuinte do Distrito Federal est\u00e1 pagando, at\u00e9 agora, pelo vai e vem na Ponte A\u00e9rea Rio-Bras\u00edlia. A &#8216;merrequinha&#8217; diz respeito apenas ao vai e vem de integrantes da Vila Isabel e de servidores da Secretaria de Cultura, para tentarem formular um encantado termo de coopera\u00e7\u00e3o t\u00e9cnica, que at\u00e9 agora n\u00e3o ficou pronto.<\/p>\n<p>E n\u00e3o foi por falta de empenho, pois teve gente que embarcou em Bras\u00edlia na sexta-feira e s\u00f3 voltou na segunda. Um fim de semana inteiro labutando no Rio!<\/p>\n<p>Notem que n\u00e3o est\u00e3o inclusos a\u00ed os gastos com bebidas, comida e outras despesas eventuais. E teve cach\u00ea para artistas e m\u00fasicos, no famoso churrasco do domingo, dia 26? A p\u00e2ndega n\u00e3o deve ter sa\u00eddo barata. Mas com certeza deixou muitas d\u00favidas. O anfitri\u00e3o seria o verdadeiro mecenas, ou teria algum outro mentor? Teve dinheiro p\u00fablico ou n\u00e3o? Se o evento era privado, por que no convite tinha a logomarca do governo? Agora, se era p\u00fablico, olha que tem coisa mal cheirosa.<\/p>\n<p>O prest\u00edgio do projeto Bras\u00edlia 60 anos na Sapuca\u00ed est\u00e1 baixo. Al\u00e9m da aus\u00eancia de todos os representantes de escolas de samba, tinha pouca gente para uma boca livre. O fato \u00e9 que esse enredo promete. A maneira misteriosa como a escola de samba chegou, sem a participa\u00e7\u00e3o de concorrentes no processo; o an\u00fancio do secret\u00e1rio de Cultura de que \u201ca parceria n\u00e3o seria apenas para o Carnaval 2020, mas para todo o mandato de Ibaneis&#8221;, s\u00e3o apenas alguns dos muitos mist\u00e9rios que os carnavalescos de gabinete prometem para del\u00edrio da popula\u00e7\u00e3o.<\/p>\n<p>Se o tal do termo de coopera\u00e7\u00e3o, apesar de todo o empenho aqui demonstrado, ainda n\u00e3o ficou pronto, o governador deve estar se perguntando l\u00e1 de tr\u00e1s dos montes: Que papel foi aquele que eu assinei no dia 21? E, se n\u00e3o h\u00e1 documento de compromisso entre as partes, como \u00e9 que est\u00e3o pagando di\u00e1rias para sambistas prestarem servi\u00e7os como colaboradores oficiais?<\/p>\n<p>Ih, governador. Ao que parece, o Di\u00e1rio Oficial do Distrito Federal andou publicando portaria que deveria ser mantida em sigilo. Mas, c\u00e1 pra n\u00f3s. Como existe um neg\u00f3cio chamado Lei de Acesso \u00e0 Informa\u00e7\u00e3o, mais dia, menos dia, o assunto viria \u00e0 tona. A prop\u00f3sito, ainda h\u00e1 muitas perguntas a serem feitas. E como o jornalismo virtual \u00e9 r\u00e1pido, \u00e9 bom a equipe do governo come\u00e7ar a pensar em resposta plaus\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Ibaneis Rocha (MDB) est\u00e1 desembarcando em Bras\u00edlia ap\u00f3s uma viagem a Lisboa, onde passou o fim de semana descansando e estendeu dois dias \u00fateis para supostamente tratar de interesses do Distrito Federal. A pauta desses contatos, por\u00e9m, n\u00e3o foi divulgada. Ibaneis chega justamente na hora em que dos cofres p\u00fablicos est\u00e1 saindo dinheiro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-208934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208934"}],"version-history":[{"count":12,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208934\/revisions"}],"predecessor-version":[{"id":208947,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208934\/revisions\/208947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208935"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}